{"id":557,"date":"2013-04-01T11:57:10","date_gmt":"2013-04-01T09:57:10","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/cuervoalfageme\/?p=557"},"modified":"2013-04-01T11:57:10","modified_gmt":"2013-04-01T09:57:10","slug":"mas-sobre-hipotecas-la-clausula-suelo","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/2013\/04\/01\/mas-sobre-hipotecas-la-clausula-suelo\/","title":{"rendered":"M\u00e1s sobre hipotecas: La cl\u00e1usula suelo."},"content":{"rendered":"<p align=\"JUSTIFY\"><img loading=\"lazy\" decoding=\"async\" style=\"float: left; margin: 5px;\" src=\"\/\/www.sxc.hu\/pic\/m\/h\/hi\/hisks\/1172982_vintage_keys.jpg\" alt=\"\" width=\"200\" height=\"300\" \/>Los contratos de pr\u00e9stamo hipotecario, sus condiciones, sus cl\u00e1usulas y las ejecuciones que conlleva con el resultado final de un posible desahucio son, sin duda, uno de los principales problemas que han cobrado protagonismo con la crisis. Si la semana pasada coment\u00e1bamos la sentencia del Tribunal de Justicia de la Uni\u00f3n Europa sobre las deficiencias de nuestro proceso de ejecuci\u00f3n hipotecaria e indicaba las pautas para considerar cu\u00e1ndo una cl\u00e1usula incluida en uno de estos contratos podr\u00eda ser abusiva, esta vez ha sido nuestro Tribunal Supremo quien ha analizado espec\u00edficamente la denominada \u201ccl\u00e1usula suelo\u201d, muy habitual en los contratos de pr\u00e9stamo hipotecario.<\/p>\n<p align=\"JUSTIFY\">En la mayor parte de las hipotecas se fija como tipo de inter\u00e9s el Euribor al que se a\u00f1ade un diferencial. De esta manera si el Euribor baja, el inter\u00e9s final baja. La cl\u00e1usula suelo establece que el tipo de inter\u00e9s aplicable no descienda por debajo de un m\u00ednimo aunque aplicando el Euribor pudiera bajar m\u00e1s.<\/p>\n<p align=\"JUSTIFY\">Pues bien, este tipo de cl\u00e1usulas podr\u00edan ser anuladas en determinadas circunstancias. \u00bfCu\u00e1ndo podr\u00edan serlo? Cuando no se facilite al cliente informaci\u00f3n suficiente y espec\u00edfica sobre su funcionamiento de tal manera que pueda conocer la transcendencia de su aplicaci\u00f3n. Es decir, el Tribunal Supremo aboga por entender que cabe la anulaci\u00f3n de dicha cl\u00e1usula por falta de transparencia informativa. Hasta ahora hab\u00eda sentencias de jueces y tribunales menores indicando que era abusiva en alguno casos por falta de reciprocidad entre los derechos y obligaciones de banco y cliente. Ahora el criterio cambia, la cl\u00e1usula es v\u00e1lida pero solo con informaci\u00f3n suficiente al consumidor.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los contratos de pr\u00e9stamo hipotecario, sus condiciones, sus cl\u00e1usulas y las ejecuciones que conlleva con el resultado final de un posible desahucio son, sin duda, uno de los principales problemas que han cobrado protagonismo con la crisis. Si la semana pasada coment\u00e1bamos la sentencia del Tribunal de Justicia de la Uni\u00f3n Europa sobre las deficiencias [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[],"class_list":["post-557","post","type-post","status-publish","format-standard","hentry","category-cuestion-de-opiniones","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/posts\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/cuervoalfageme\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}