{"id":1046,"date":"2018-02-28T12:13:45","date_gmt":"2018-02-28T11:13:45","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/fonendoscopio\/?p=1046"},"modified":"2018-02-28T12:13:45","modified_gmt":"2018-02-28T11:13:45","slug":"los-implantes-cocleares-actuales-con-mas-pequenos-y-cuentan-con-estrategias-de-codificacion-mas-eficaces","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/2018\/02\/28\/los-implantes-cocleares-actuales-con-mas-pequenos-y-cuentan-con-estrategias-de-codificacion-mas-eficaces\/","title":{"rendered":"Los implantes cocleares actuales con m\u00e1s peque\u00f1os y cuentan con estrategias de codificaci\u00f3n m\u00e1s eficaces"},"content":{"rendered":"<div class=\"new-article__content-cms\">\n<div class=\"content first-click-free__article-content--target\">\n<div class=\"wysiwyg\">\n<p>Los implantes cocleares son hoy en d\u00eda m\u00e1s peque\u00f1os, con una tecnolog\u00eda m\u00e1s moderna y con unas estrategias de codificaci\u00f3n m\u00e1s eficaces, ha se\u00f1alado Luis Lassaletta, presidente de la Comisi\u00f3n de Otoneurolog\u00eda de la Sociedad Espa\u00f1ola de Otorrinolaringolog\u00eda y Cirug\u00eda de Cabeza y Cuello (SEORL-CCC), con motivo del D\u00eda Internacional del Implante Coclear, celebrado el pasado 25 de febrero.<a href=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/22\/2018\/02\/implantes-cocleares.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-1047 alignleft\" src=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/22\/2018\/02\/implantes-cocleares-300x200.jpg\" alt=\"implantes-cocleares\" width=\"300\" height=\"200\" srcset=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/22\/2018\/02\/implantes-cocleares-300x200.jpg 300w, https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/22\/2018\/02\/implantes-cocleares.jpg 579w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los \u00faltimos avances en implantes cocleares han mejorado la calidad de vida de las personas con d\u00e9ficit auditivo severo o profundo gracias a su miniaturizaci\u00f3n y al aumento de sus indicaciones, seg\u00fan concluye un an\u00e1lisis llevado a cabo por la SEORL-CCC. Adem\u00e1s, la comisi\u00f3n ha elaborado un \u2018Dec\u00e1logo de consejos para pacientes\u2019 con implante coclear para favorecer la adaptaci\u00f3n de estas personas.<\/p>\n<div class=\"gcols block_ads top adgear_col-middle adgear_16-9\">\u00a0La cirug\u00eda para colocar este implante consiste en la colocaci\u00f3n de un dispositivo quir\u00fargico debajo de la piel con un receptor interno y una gu\u00eda de electrodos que se introduce dentro de la c\u00f3clea, que estimula las terminaciones nerviosas del nervio auditivo mediante est\u00edmulos el\u00e9ctricos.<\/div>\n<p>&#8220;Se intenta as\u00ed simular el funcionamiento normal de la c\u00f3clea. El otorrinolaring\u00f3logo juega un papel clave es este proceso, pues coordinar\u00e1 al equipo implantador para obtener el mejor resultado posible, que estar\u00e1 formado por audi\u00f3logos, logopedas, programadores o psic\u00f3logos&#8221;, ha comentado Lassaletta.<\/p>\n<p>Las principales novedades en implantes tienen que ver con la est\u00e9tica, por un lado, y con las indicaciones, por otro. Seg\u00fan ha explicado el especialista, hace a\u00f1os los \u00fanicos candidatos a implante coclear eran los ni\u00f1os o adultos con sordera profunda bilateral, pero en la actualidad estos implantes son \u00fatiles en muchas otras afectaciones&#8221;.<\/p>\n<p>Un estudio publicado en <em>Audiology &amp; Neuro-otology<\/em> ha concluido que estos implantes pueden ofrecer mejoras significativas en la calidad de vida, al comprobar como permiten una reducci\u00f3n en la severidad percibida del tinnitus y mejoras subjetivas en la percepci\u00f3n del habla. En la misma l\u00ednea, otra investigaci\u00f3n publicada en <em>Otology &amp; Neurotology<\/em> ha estimado en 324.000 las personas en todo el mundo han recibido un implante coclear desde 2012.<\/p>\n<p>Un total de 40 centros m\u00e9dicos espa\u00f1oles realizan ya este tipo de intervenciones. &#8220;Esta avance ha permitido que en Espa\u00f1a cada vez existan menos personas sordomudas, puesto que implantamos el dispositivo antes de que los ni\u00f1os desarrollen el lenguaje&#8221;, ha indicado Lassaletta.<\/p>\n<p>En el citado \u2018Dec\u00e1logo de consejos para pacientes&#8217;\u00a0 se incluyen recomendaciones como someterse a un programa de seguimiento, plantearse peque\u00f1as metas para orientar mejor su aprendizaje y crecimiento, alejarse de las fuentes de ruido, pedir ayuda al interlocutor o simular conversaciones por tel\u00e9fono para favorecer la adaptaci\u00f3n.<\/p>\n<p>Tambi\u00e9n destacan consejos como concentrarse al ver la televisi\u00f3n u o\u00edr m\u00fasica; pedir un micr\u00f3fono o, en reuniones grupales buscar una posici\u00f3n cercana a un altavoz, revisar la reprogramaci\u00f3n del sistema, favorecer el descanso, ya que es recomendable dejar a la mente descansar para no agotarse durante el aprendizaje, y plantear una rehabilitaci\u00f3n auditiva con un logopeda especializado.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<footer class=\"new-article__footer sticky-tools-share-stopper\">\n<section class=\"new-article-footer__disclaimer\">\n<div class=\"gcol\">\n<div class=\"references_disclaimer ui-tabs ui-corner-all ui-widget ui-widget-content\">\n<div id=\"tab_reference\"><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/footer>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Los implantes cocleares son hoy en d\u00eda m\u00e1s peque\u00f1os, con una tecnolog\u00eda m\u00e1s moderna y con unas estrategias de codificaci\u00f3n m\u00e1s eficaces, ha se\u00f1alado Luis Lassaletta, presidente de la Comisi\u00f3n de Otoneurolog\u00eda de la Sociedad Espa\u00f1ola de Otorrinolaringolog\u00eda y Cirug\u00eda de Cabeza y Cuello (SEORL-CCC), con motivo del D\u00eda Internacional del Implante Coclear, celebrado el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,3],"tags":[794,795],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1046"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"predecessor-version":[{"id":1048,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1046\/revisions\/1048"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}