{"id":1655,"date":"2020-11-28T21:09:05","date_gmt":"2020-11-28T20:09:05","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/?p=1655"},"modified":"2020-11-30T10:37:05","modified_gmt":"2020-11-30T09:37:05","slug":"mortalidad-en-profesionales-de-salud-por-covid-19-una-crisis-a-escala-asombrosa","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/2020\/11\/28\/mortalidad-en-profesionales-de-salud-por-covid-19-una-crisis-a-escala-asombrosa\/","title":{"rendered":"Mortalidad en profesionales de salud por COVID-19: una &#8220;crisis a escala asombrosa&#8221;"},"content":{"rendered":"<p>&#8220;El hecho de que m\u00e1s de 7.000 personas mueran en su intento por salvar vidas constituye una crisis a escala asombrosa&#8221;, as\u00ed lo destaca un nuevo an\u00e1lisis de Amnist\u00eda Internacional, que revela que al menos 7.000 trabajadores de la salud han muerto en todo el mundo tras enfermar por COVID-19. M\u00e9xico es el pa\u00eds con la cifra m\u00e1s alta, con 1.320 v\u00edctimas fatales, seguido por Estados Unidos (1.077 fallecimientos)\u00a0y Brasil (634), otros pa\u00edses del continente refieren menos decesos.<sup>[1]<\/sup><\/p>\n<p>Seg\u00fan datos<a href=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2020\/09\/gripe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1624 alignleft\" src=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2020\/09\/gripe-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2020\/09\/gripe-300x150.jpg 300w, https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2020\/09\/gripe.jpg 318w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> difundidos\u00a0por la Organizaci\u00f3n Panamericana de la Salud (OPS), M\u00e9xico y Estados Unidos representan casi 85% de los fallecimientos en la regi\u00f3n.<sup>[2]<\/sup> La directora de la organizaci\u00f3n, Dra. Carissa Etienne, alert\u00f3 que casi tres cuartas partes de los trabajadores de la salud diagnosticados con COVID-19 son mujeres\u00a0y que el continente americano es el que tiene el mayor n\u00famero de trabajadores de la salud infectados en el mundo.<\/p>\n<h4><b>Datos incompletos<\/b><\/h4>\n<p>&#8220;Las comparaciones entre pa\u00edses en t\u00e9rminos absolutos distan de la realidad&#8221;, coment\u00f3 a <em>Medscape en espa\u00f1ol<\/em> el especialista en medicina interna y enfermedades infecciosas, Dr. Samuel Ponce de Le\u00f3n, coordinador del programa universitario de investigaci\u00f3n en salud y coordinador del programa de respuesta al COVID-19 en la Universidad Nacional Aut\u00f3noma de M\u00e9xico. El Dr. Ponce de Le\u00f3n consider\u00f3 que esta comparaci\u00f3n expresa la falta de uniformidad en los \u00e1mbitos econ\u00f3mico, social, de estructura de salud, y capacitaci\u00f3n de personal sanitario, pero tambi\u00e9n en los sistemas de informaci\u00f3n y vigilancia.<\/p>\n<p>De hecho, Amnist\u00eda Internacional, que ofrece un mapa global interactivo de los casos actualizados, destaca que el registro detallado de las muertes de trabajadores de la salud de M\u00e9xico es ejemplar. &#8220;Esa transparencia es esencial, y todos los pa\u00edses deber\u00edan poner a disposici\u00f3n este tipo de detalles; tambi\u00e9n puede explicar las inquietantes cifras de M\u00e9xico en relaci\u00f3n con otros pa\u00edses&#8221;.<\/p>\n<p>En algunos pa\u00edses el n\u00famero de fallecimientos en personal de la salud puede ser reflejo de la gravedad de la pandemia. En otros, falta de entrenamiento o acceso a equipos de protecci\u00f3n personal adecuados\u00a0o plan de realizaci\u00f3n\u00a0de pruebas de reacci\u00f3n en cadena de la polimerasa. Adem\u00e1s, no existe una \u00fanica definici\u00f3n universal de &#8220;trabajador de la salud&#8221;.<\/p>\n<p>De las v\u00edctimas se dice que son personas y no n\u00fameros, pero a veces ni siquiera eso, porque muchos pa\u00edses no cuentan con datos oficiales completos. El mapa de Amnist\u00eda Internacional se realiza con informaci\u00f3n oficial complementada con datos de otras fuentes, como p\u00e1ginas conmemorativas, listados de asociaciones y sindicatos m\u00e9dicos, y hasta obituarios publicados en medios de comunicaci\u00f3n.<sup>[<a>1<\/a>]<\/sup><\/p>\n<p>Por ejemplo, de Per\u00fa toma datos del Colegio M\u00e9dico; de Brasil, del Sindicato de M\u00e9dicos de Sao Paulo; de Bolivia, del Consejo Federal de Enfermer\u00eda y de la Confederaci\u00f3n Sindical; en Chile y Argentina usa datos propios y oficiales; de\u00a0Venezuela,\u00a0la organizaci\u00f3n no gubernamental M\u00e9dicos Unidos de Venezuela, y para Ecuador, Uruguay y Puerto Rico cita como fuente a <em>Medscape<\/em>.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8220;El hecho de que m\u00e1s de 7.000 personas mueran en su intento por salvar vidas constituye una crisis a escala asombrosa&#8221;, as\u00ed lo destaca un nuevo an\u00e1lisis de Amnist\u00eda Internacional, que revela que al menos 7.000 trabajadores de la salud han muerto en todo el mundo tras enfermar por COVID-19. M\u00e9xico es el pa\u00eds con [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":696,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lo-que-se-dice-por-ahi"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/comments?post=1655"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1655\/revisions"}],"predecessor-version":[{"id":1656,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1655\/revisions\/1656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/media\/696"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/media?parent=1655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/categories?post=1655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/tags?post=1655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}