{"id":1671,"date":"2021-01-14T19:05:30","date_gmt":"2021-01-14T18:05:30","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/?p=1671"},"modified":"2021-01-14T19:05:30","modified_gmt":"2021-01-14T18:05:30","slug":"del-thc-a-la-marihuana-vaporizada-los-cannabinoides-como-alternativa-para-el-tratamiento-del-dolor-neuropatico","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/2021\/01\/14\/del-thc-a-la-marihuana-vaporizada-los-cannabinoides-como-alternativa-para-el-tratamiento-del-dolor-neuropatico\/","title":{"rendered":"Del THC a la marihuana vaporizada: los cannabinoides como alternativa para el tratamiento del dolor neurop\u00e1tico"},"content":{"rendered":"<div class=\"new-article__content-cms\">\n<div class=\"content first-click-free__article-content--target\">\n<div class=\"wysiwyg\">\n<p>El cannabis es una popular\u00edsima planta herb\u00e1cea cuyos efectos psicoactivos son de sobra conocidos entre la poblaci\u00f3n. Desde hace algunos a\u00f1os, la utilizaci\u00f3n de esta planta y de las sustancias que de ella se derivan, los cannabinoides, ha generado un gran inter\u00e9s como alternativa terap\u00e9utica para el tratamiento del dolor neurop\u00e1tico, del dolor oncol\u00f3gico, de la epilepsia o de la esclerosis m\u00faltiple. De hecho, existen cada vez m\u00e1s estudios cl\u00ednicos y precl\u00ednicos que parecen avalar su eficacia y la comunidad cient\u00edfica se encuentra cada vez menos dividida pese a que su utilizaci\u00f3n es ilegal en muchos pa\u00edses.<\/p>\n<p>Pero, \u00bfse sabe con total certeza c\u00f3mo act\u00faan los cannabinoides en nuestro organismo? \u00bfPor qu\u00e9 se deber\u00edan considerar el THC o la marihuana para el tratamiento del dolor cr\u00f3nico? \u00bfCu\u00e1les son los posibles riesgos derivados de tratar a un paciente con este tipo de sustancias? Estos fueron algunos de los interrogantes a los que trat\u00f3 de dar respuesta la doctora Alba C\u00e1rcamo, de la Unidad del Dolor del Hospital Universitario de Getafe, en la revisi\u00f3n que realiz\u00f3 durante la <a href=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2021\/01\/cannabinoides.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1672 alignleft\" src=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2021\/01\/cannabinoides.jpg\" alt=\"\" width=\"275\" height=\"183\" \/><\/a>segunda jornada de la LXXII Reuni\u00f3n Anual de la Sociedad Espa\u00f1ola de Neurolog\u00eda (SEN), que tuvo lugar el pasado 24 de noviembre.<\/p>\n<p>La consideraci\u00f3n cada vez mayor del uso de los cannabinoides para el tratamiento del dolor neurop\u00e1tico se debe principalmente a lo que la neur\u00f3loga bautiz\u00f3 como \u2018crisis opioide\u2019. \u201cLos f\u00e1rmacos opioides son causantes de una gran morbi-mortalidad. La realidad es que hay escasas alternativas no opioides para tratar el dolor y las que tenemos son poco efectivas y tienen efectos secundarios\u201d, lament\u00f3 C\u00e1rcamo. Adem\u00e1s, tampoco hay datos que avalen la seguridad y eficacia a largo plazo de los opioides en el dolor cr\u00f3nico que no sea oncol\u00f3gico y tampoco parece que en el futuro se vayan a desarrollar otros f\u00e1rmacos que alteren este horizonte.<\/p>\n<p>En este contexto es en el que se plantea un uso cada vez mayor del cannabis medicinal, que est\u00e1 ampliamente extendido en todo el mundo y sobre el que se han realizado estudios observacionales y ensayos cl\u00ednicos que apuntan a su posible eficacia frente al dolor neurop\u00e1tico. Sin embargo, tambi\u00e9n son numerosas las voces que abogan por la cautela y muestran su preocupaci\u00f3n por los efectos a largo plazo de los cannabinoides, cuyo consumo ha sido relacionado con trastornos neuropsiqui\u00e1trico tales como la ansiedad, la despersonalizaci\u00f3n, con un mayor riesgo de psicosis en ciertos individuos o el empeoramiento de los s\u00edntomas positivos de esquizofrenia.<\/p>\n<p>Los estudios cl\u00ednicos sobre cannabinoides que se han desarrollado en los \u00faltimos a\u00f1os han analizado tanto su eficacia ante el dolor como la tolerabilidad de los individuos, la seguridad o los efectos a trav\u00e9s de las distintas v\u00edas de administraci\u00f3n. Adem\u00e1s, tambi\u00e9n se ha evaluado su efecto ante las n\u00e1useas o v\u00f3mitos por la quimioterapia, frente a la esclerosis m\u00faltiple, los trastornos del sue\u00f1o, la psicosis y el dolor neurop\u00e1tico y oncol\u00f3gico. Pese a que la calidad de la evidencia de estos estudios es a\u00fan baja -salvo en los de dolor cr\u00f3nico y la espasticidad, que es moderada-, seg\u00fan C\u00e1rcamo, en general \u201cse puede decir que el uso de cannabinoides para el dolor es mejor frente al placebo\u201d.<\/p>\n<p>As\u00ed lo apunta un metan\u00e1lisis publicado en la revista <em>JAMA<\/em> en 2015, en el que se recogen los resultados de 28 ensayos cl\u00ednicos en los que se utilizaron cannabinoides para el tratamiento del dolor cr\u00f3nico y la espasticidad. Concretamente, en ocho de estos estudios los pacientes reportaron una mejor\u00eda de al menos un 30% en la intensidad del dolor. Por el contrario, otros trabajos cient\u00edficos en los que se ha comparado el uso de cannabinoides frente a tratamientos activos con code\u00edna para el control del dolor sugieren que los primeros no son mejores que los segundos y, en cambio, tienen un peor perfil de seguridad.<\/p>\n<p>Seg\u00fan explic\u00f3 C\u00e1rcamo, la marihuana fumada es la v\u00eda de administraci\u00f3n m\u00e1s com\u00fan entre los pacientes con dolor neurop\u00e1tico y es la que obtiene mejores resultados en las investigaciones realizadas hasta la fecha. \u201cAlgunos estudios sugieren que el consumo de THC tres veces al d\u00eda reduce la intensidad del dolor y mejora el sue\u00f1o frente al placebo\u201d, explic\u00f3 la neur\u00f3loga del Hospital Universitario de Getafe. Tambi\u00e9n algunas investigaciones realizadas sobre el cannabis vaporizado -en el que se eliminan los compuestos procedentes de la combusti\u00f3n del cigarro- sugieren que tanto las dosis medias como bajas mejoran las escalas de dolor de los pacientes sin grandes efectos secundarios.<\/p>\n<p>Las evidencias sobre los posibles beneficios del uso de estas sustancias para mejorar el tratamiento de los pacientes con dolor son cada vez mayores. Sin embargo, tal y como destac\u00f3 C\u00e1rcamo, conviene recordar que los estudios cl\u00ednicos en dolor tienen algunas limitaciones: suelen estar hechos con muestras peque\u00f1as, abordan s\u00edndromes dolorosos muy heterog\u00e9neos y existe una diferente caracterizaci\u00f3n de la importancia de los efectos adversos y un escaso o nulo seguimiento de efectos a largo plazo. \u201cSi tenemos en cuenta que los efectos psicoactivos no pasan desapercibidos, es dif\u00edcil mantener el doble ciego y se complica la interpretaci\u00f3n de los efectos analg\u00e9sicos\u201d, advirti\u00f3 la especialista.<\/p>\n<p>Aun as\u00ed, C\u00e1rcamo subray\u00f3 los avances que se est\u00e1n produciendo en la investigaci\u00f3n, donde se reporta el potencial inter\u00e9s de estos compuestos. No obstante, la neur\u00f3loga advirti\u00f3 de que hay que tener muy en cuenta tanto su perfil de seguridad como sus potenciales efectos adversos. Por el momento, dijo, se requieren m\u00e1s estudios para establecer la duraci\u00f3n del tratamiento, dosis, v\u00edas de administraci\u00f3n \u00f3ptimas y seguridad de estas sustancias.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<footer class=\"new-article__footer sticky-tools-share-stopper\">\n<section class=\"new-article-footer__content\">\n<ul class=\"new-article-footer__list-link\">\n<li><\/li>\n<\/ul>\n<\/section>\n<section class=\"new-article-footer__disclaimer\">\n<div class=\"gcol\">\n<div class=\"references_disclaimer ui-tabs ui-corner-all ui-widget ui-widget-content\">\n<ul class=\"tabs_constrols ui-tabs-nav ui-corner-all ui-helper-reset ui-helper-clearfix ui-widget-header\" role=\"tablist\">\n<li class=\"ui-tabs-tab ui-corner-top ui-state-default ui-tab ui-tabs-active ui-state-active\" role=\"tab\">Referencias<\/li>\n<\/ul>\n<div id=\"tab_reference\" class=\"ui-tabs-panel ui-corner-bottom ui-widget-content\" role=\"tabpanel\">\n<p>Whiting PF, Wolff RF, Deshpande S, et al. Cannabinoids for Medical Use: A Systematic Review and Meta-analysis. JAMA. 2015;313(24):2456\u20132473. doi:10.1001\/jama.2015.6358<\/p>\n<p>Campbell FA, Tram\u00e8r MR, Carroll D, Reynolds DJ, Moore RA, McQuay HJ. Are cannabinoids an effective and safe treatment option in the management of pain? A qualitative systematic review. BMJ. 2001 Jul 7;323(7303):13-6. doi: 10.1136\/bmj.323.7303.13. PMID: 11440935; PMCID: PMC34324.<\/p>\n<p>Ware MA, Wang T, Shapiro S, Robinson A, Ducruet T, Huynh T, Gamsa A, Bennett GJ, Collet JP. Smoked cannabis for chronic neuropathic pain: a randomized controlled trial. CMAJ. 2010 Oct 5;182(14):E694-701. doi: 10.1503\/cmaj.091414. Epub 2010 Aug 30. PMID: 20805210; PMCID: PMC2950205.<\/p>\n<p>Wilsey B, Marcotte T, Deutsch R, Gouaux B, Sakai S, Donaghe H. Low-dose vaporized cannabis significantly improves neuropathic pain. J Pain. 2013 Feb;14(2):136-48. doi: 10.1016\/j.jpain.2012.10.009. Epub 2012 Dec 11. PMID: 23237736; PMCID: PMC3566631.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/footer>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El cannabis es una popular\u00edsima planta herb\u00e1cea cuyos efectos psicoactivos son de sobra conocidos entre la poblaci\u00f3n. Desde hace algunos a\u00f1os, la utilizaci\u00f3n de esta planta y de las sustancias que de ella se derivan, los cannabinoides, ha generado un gran inter\u00e9s como alternativa terap\u00e9utica para el tratamiento del dolor neurop\u00e1tico, del dolor oncol\u00f3gico, de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1671","post","type-post","status-publish","format-standard","hentry","category-medicina-para-todos"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/comments?post=1671"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1671\/revisions"}],"predecessor-version":[{"id":1673,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1671\/revisions\/1673"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/media?parent=1671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/categories?post=1671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/tags?post=1671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}