{"id":1684,"date":"2021-01-29T20:55:20","date_gmt":"2021-01-29T19:55:20","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/?p=1684"},"modified":"2021-01-29T20:55:20","modified_gmt":"2021-01-29T19:55:20","slug":"hipertension-arterial-y-deterioro-cognitivo","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/2021\/01\/29\/hipertension-arterial-y-deterioro-cognitivo\/","title":{"rendered":"Hipertensi\u00f3n arterial y deterioro cognitivo"},"content":{"rendered":"<div id=\"contenido_contenedor\">\n<div id=\"articulo_texto\">\n<table cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td><strong>Resumen<\/strong><\/p>\n<p>La hipertensi\u00f3n, particularmente en la mediana edad, se ha asociado con una peor funci\u00f3n cognitiva, pero la evidencia no es concluyente. Este estudio investig\u00f3 si la hipertensi\u00f3n, la prehipertensi\u00f3n, la edad y la duraci\u00f3n del diagn\u00f3stico, as\u00ed como el control de la presi\u00f3n arterial, est\u00e1n asociados con una disminuci\u00f3n del rendimiento cognitivo en los participantes de ELSA-Brasil. Este estudio longitudinal incluy\u00f3 a 7063 participantes, con una edad media de 58,9 a\u00f1os al inicio del estudio (2008-2010), que asistieron a la visita 2 (2012-2014).<\/p>\n<p>El rendimiento cognitivo se midi\u00f3 en ambas visitas y se evalu\u00f3 mediante las puntuaciones estandarizadas de memoria, fluidez verbal, pruebas de ruta B y puntuaci\u00f3n cognitiva global. Las asociaciones se investigaron utilizando modelos lineales mixtos.<\/p>\n<p>La hipertensi\u00f3n y la prehipertensi\u00f3n al inicio del estudio se asociaron con una disminuci\u00f3n en la puntuaci\u00f3n cognitiva global; ser hipertensi\u00f3n asociada con reducci\u00f3n en la prueba de memoria; y prehipertensi\u00f3n con reducci\u00f3n en la prueba de fluidez.<\/p>\n<p>El diagn\u00f3stico de hipertensi\u00f3n \u226555 a\u00f1os se asoci\u00f3 con puntuaciones m\u00e1s bajas en las pruebas cognitivas y de memoria globales, y el diagn\u00f3stico de hipertensi\u00f3n &lt;55 a\u00f1os con puntuaciones m\u00e1s bajas en las pruebas de memoria.<\/p>\n<p>La duraci\u00f3n de los diagn\u00f3sticos de hipertensi\u00f3n no se asoci\u00f3 con ning\u00fan marcador de deterioro de la funci\u00f3n cognitiva. Entre los individuos tratados, el control de la presi\u00f3n arterial al inicio del estudio se asoci\u00f3 inversamente con la disminuci\u00f3n de las puntuaciones de las pruebas cognitivas y de memoria globales.<\/p>\n<p>En esta cohorte relativamente joven, la hipertensi\u00f3n, la prehipertensi\u00f3n y el control de la presi\u00f3n arterial fueron predictores independientes del deterioro cognitivo en distintas capacidades. Nuestros hallazgos sugieren que tanto la edad m\u00e1s baja como la mayor de la hipertensi\u00f3n, pero no la duraci\u00f3n del diagn\u00f3stico, se asociaron con el deterioro cognitivo en diferentes habilidades.<\/p>\n<p>Adem\u00e1s de la hipertensi\u00f3n, la prehipertensi\u00f3n y el control de la presi\u00f3n pueden ser fundamentales para la preservaci\u00f3n de la funci\u00f3n cognitiva.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<blockquote><p>Ca<a href=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1169 alignleft\" src=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA-300x169.jpg 300w, https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA-768x432.jpg 768w, https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA-1024x576.jpg 1024w, https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-content\/uploads\/sites\/22\/2018\/09\/HTA.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>si la mitad de los adultos estadounidenses tienen presi\u00f3n arterial alta o hipertensi\u00f3n.<\/p><\/blockquote>\n<p>Tener presi\u00f3n arterial alta es un factor de riesgo de deterioro cognitivo, que incluye cosas como la memoria, la fluidez verbal, la atenci\u00f3n y la concentraci\u00f3n. La presi\u00f3n arterial sist\u00f3lica de 120 mmHg a 129 mmHg (el n\u00famero superior en una lectura) o superior se considera elevada. La presi\u00f3n sist\u00f3lica por encima de 130 mmHg o la presi\u00f3n diast\u00f3lica (el n\u00famero inferior) de 80 mmHg o m\u00e1s se considera hipertensi\u00f3n.<\/p>\n<p>&#8220;Inicialmente anticipamos que los efectos negativos de la hipertensi\u00f3n sobre la funci\u00f3n cognitiva ser\u00edan m\u00e1s cr\u00edticos cuando la hipertensi\u00f3n comenzara a una edad m\u00e1s temprana, sin embargo, nuestros resultados muestran una disminuci\u00f3n similar acelerada del rendimiento cognitivo, ya sea que la hipertensi\u00f3n comience en la mediana edad o en edades mayores&#8221;, dijo el autor del estudio Sandhi M. Barreto, MD, M.Sc., Ph.D., profesor de medicina en la Universidade Federal de Minas Gerais en Belo Horizonte, Brasil. &#8220;Tambi\u00e9n descubrimos que el tratamiento eficaz de la presi\u00f3n arterial alta a cualquier edad en la edad adulta podr\u00eda reducir o prevenir esta aceleraci\u00f3n. En conjunto, los hallazgos sugieren que la hipertensi\u00f3n debe prevenirse, diagnosticarse y tratarse eficazmente en adultos de cualquier edad para preservar la funci\u00f3n cognitiva&#8221;.<\/p>\n<p>Barreto y sus colegas analizaron los hallazgos de un estudio existente que inclu\u00eda informaci\u00f3n sobre la presi\u00f3n arterial y la salud cognitiva de m\u00e1s de 7.000 adultos en Brasil, cuya edad promedio era de 59 a\u00f1os al inicio del estudio. Los participantes del estudio fueron seguidos durante un promedio de casi 4 a\u00f1os; Las pruebas incluyeron el an\u00e1lisis de la memoria, la fluidez verbal y la funci\u00f3n ejecutiva, que incluye atenci\u00f3n, concentraci\u00f3n y otros factores asociados con el pensamiento y el razonamiento.<\/p>\n<table cellspacing=\"1\" cellpadding=\"1\">\n<tbody>\n<tr>\n<td>Su an\u00e1lisis encontr\u00f3:<\/p>\n<ul>\n<li>La presi\u00f3n arterial sist\u00f3lica entre 121 y 139 mmHg o la presi\u00f3n arterial diast\u00f3lica entre 81 y 89 mmHg sin el uso de medicamentos antihipertensivos se asoci\u00f3 con una disminuci\u00f3n acelerada del rendimiento cognitivo entre las personas de mediana edad y mayores.<\/li>\n<li>La velocidad de disminuci\u00f3n de la cognici\u00f3n ocurri\u00f3 independientemente de la duraci\u00f3n de la hipertensi\u00f3n, lo que significa que la presi\u00f3n arterial alta durante cualquier per\u00edodo de tiempo, incluso por un per\u00edodo corto, podr\u00eda afectar la velocidad de disminuci\u00f3n cognitiva de una persona.<\/li>\n<li>Los adultos con hipertensi\u00f3n no controlada tend\u00edan a experimentar disminuciones notablemente m\u00e1s r\u00e1pidas en la memoria y la funci\u00f3n cognitiva global que los adultos que ten\u00edan hipertensi\u00f3n controlada.<\/li>\n<li>&#8220;Adem\u00e1s de otros beneficios comprobados del control de la presi\u00f3n arterial, nuestros resultados destacan la importancia de diagnosticar y controlar la hipertensi\u00f3n en pacientes de cualquier edad para prevenir o ralentizar el deterioro cognitivo&#8221;, dijo Barreto. &#8220;Nuestros resultados tambi\u00e9n refuerzan la necesidad de mantener niveles m\u00e1s bajos de presi\u00f3n arterial durante toda la vida, ya que incluso los niveles de prehipertensi\u00f3n se asociaron con el deterioro cognitivo&#8221;.<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Seg\u00fan Barreto, algunas de las limitaciones del estudio son el per\u00edodo de seguimiento relativamente corto y que los participantes autoinformaron el diagn\u00f3stico de hipertensi\u00f3n al inicio del estudio.<\/p>\n<p>&#8220;Aunque los participantes de nuestro estudio son adultos de Brasil, creemos que nuestros hallazgos son aplicables a otras regiones. Estudios anteriores han demostrado que comportamientos nocivos y factores de riesgo similares, incluida la hipertensi\u00f3n, son comunes en el desarrollo de enfermedades cardiovasculares en diferentes poblaciones de todo el mundo. el mundo &#8220;, dijo Barreto.<\/p>\n<\/div>\n<div id=\"banner\">\n<div id=\"eplAdDivInterna_22\"><\/div>\n<\/div>\n<\/div>\n<p><a name=\"comentarios\"><\/a><\/p>\n<div id=\"comentarios_form_contenedor\"><\/div>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Resumen La hipertensi\u00f3n, particularmente en la mediana edad, se ha asociado con una peor funci\u00f3n cognitiva, pero la evidencia no es concluyente. Este estudio investig\u00f3 si la hipertensi\u00f3n, la prehipertensi\u00f3n, la edad y la duraci\u00f3n del diagn\u00f3stico, as\u00ed como el control de la presi\u00f3n arterial, est\u00e1n asociados con una disminuci\u00f3n del rendimiento cognitivo en los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1684","post","type-post","status-publish","format-standard","hentry","category-medicina-para-todos"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/comments?post=1684"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1684\/revisions"}],"predecessor-version":[{"id":1685,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/posts\/1684\/revisions\/1685"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/media?parent=1684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/categories?post=1684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/fonendoscopio\/wp-json\/wp\/v2\/tags?post=1684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}