{"id":1037,"date":"2019-01-15T14:28:33","date_gmt":"2019-01-15T13:28:33","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/hispadata\/?p=1037"},"modified":"2019-01-15T14:28:33","modified_gmt":"2019-01-15T13:28:33","slug":"el-emprendimiento-en-asturias","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/hispadata\/2019\/01\/15\/el-emprendimiento-en-asturias\/","title":{"rendered":"EL EMPRENDIMIENTO EN ASTURIAS"},"content":{"rendered":"<p>El pasado 18 de diciembre, asist\u00ed en el Hotel de la Reconquista,\u00a0a la presentaci\u00f3n que organiz\u00f3 la\u00a0<em>Consejer\u00eda de Empleo, Industria y Turismo del Principado de Asturias<\/em><em>\u00a0y\u00a0<\/em>la<em>\u00a0Asociaci\u00f3n de Centros de Empresas P\u00fablicos del Principado de Asturias (ACEPPA)<\/em>\u00a0del\u00a0<strong>Premio Asturias Regi\u00f3n Emprendedora Europea 2019,<\/strong>\u00a0otorgado por el\u00a0<em>Comit\u00e9 de las Regiones<\/em><em>.<\/em> En este acto, se presentaron tambi\u00e9n a los once embajadores que han sido elegidos para representar los valores de la Asturias innovadora y emprendedora.<\/p>\n<p>A m\u00ed me parece bien que diecinueve entidades asturianas, entre ellas la Universidad de Oviedo, las C\u00e1maras de Comercio y la Fade, hayan apoyado esta candidatura. Tambi\u00e9n me parece estupendo que, desde el plano te\u00f3rico, la candidatura se haya basado en tres pilares, cuales son: La innovaci\u00f3n, la inclusi\u00f3n social y la sostenibilidad\u201d, algo que permita obtener la visi\u00f3n de una regi\u00f3n que apuesta por el desarrollo equilibrado.<\/p>\n<p>Ojal\u00e1 que, tras este premio, de verdad se coja el toro por los cuernos y se empiece a hacer algo por incrementar el nivel de emprendimiento en Asturias, porque hasta ahora, los datos estad\u00edsticos que tenemos son demoledores. Y digo esto porque, tristemente, en emprendimiento, nuestra regi\u00f3n est\u00e1 situada en la pen\u00faltima posici\u00f3n de las regiones espa\u00f1olas. En resumen, sorprendentemente, se nos ha otorgado un premio como regi\u00f3n emprendedora europea, aun cuando en emprendimiento somos los pen\u00faltimos de la fila.<\/p>\n<p>No hace mucho tiempo atr\u00e1s, hab\u00eda asistido a la presentaci\u00f3n de los resultados 2017\/2018, del GEM (Global Entrepreneurship Monitor), presentados por la directora de la C\u00e1tedra de Emprendimiento Capgemini-Caja Rural de Asturias, Beatriz Junquera, resultados que, contrariamente al optimismo visto en el acto de la presentaci\u00f3n del premio anterior, son verdaderamente desoladores para nuestra regi\u00f3n.<\/p>\n<p>Entre los datos m\u00e1s relevantes que recoge el estudio presentado, destaca el porcentaje de poblaci\u00f3n involucrada en iniciativas emprendedoras. En Asturias este porcentaje es s\u00f3lo del 3,26%, casi la mitad del espa\u00f1ol, que est\u00e1 situado en el 6,2 y mucho m\u00e1s alejado del europeo que est\u00e1 en el 8,1%. Este dato coloca a Asturias en el pen\u00faltimo lugar de las posiciones espa\u00f1olas, s\u00f3lo por delante de Melilla. Analizando las percepciones y actitudes de la poblaci\u00f3n asturiana hacia el emprendimiento, el porcentaje de poblaci\u00f3n que percibe oportunidades de negocio es el 22% en Asturias, frente al 34% del conjunto de Espa\u00f1a, dato este que nos coloca en el \u00faltimo puesto del conjunto de las comunidades espa\u00f1olas. El informe delata tambi\u00e9n una sociedad insegura ante su propia capacidad para emprender y denota igualmente el miedo al fracaso, muy superior en Asturias al resto de Espa\u00f1a.<\/p>\n<p>Este bajo nivel de emprendimiento lo detectamos tambi\u00e9n en Secot, organizaci\u00f3n a la que pertenezco y donde asesoramos a emprendedores. En los datos internos que manejamos, por supuesto sin poder ser comparables al completo informe del GEM, tambi\u00e9n podemos extraer que, comparando unas delegaciones con otras, en estos cuatro \u00faltimos a\u00f1os, Asturias tambi\u00e9n est\u00e1 en la cola del emprendimiento entre los datos de todas nuestras delegaciones. En nuestros datos internos igualmente observamos que Asturias tambi\u00e9n destaca por su tendencia al emprendimiento de baja calidad.<\/p>\n<p>A toda esta informaci\u00f3n estad\u00edstica comentada, nada favorable para Asturias, hemos de a\u00f1adir tambi\u00e9n, el poco positivo dato del n\u00famero de aut\u00f3nomos que est\u00e1 perdiendo nuestra comunidad y digo que han de a\u00f1adirse porque todos estos aut\u00f3nomos son aut\u00e9nticos emprendedores. Conforme a los \u00faltimos datos de los que se disponen, de enero a septiembre de 2018, Asturias ha perdido 118 trabajadores aut\u00f3nomos y eso pese a las ventajas que introdujo la nueva \u201cLey del Aut\u00f3nomo\u201d que se reforz\u00f3 con la denominada tarifa plana para los emprendedores. Esta ayuda extra no ha sido aprovechada de modo que, de los 2.040.000 euros presupuestados para este complemento, s\u00f3lo se han adjudicado 668.400\u20ac, concedidos s\u00f3lo a 1.344 solicitantes, n\u00famero muy inferior al esperado. En resumen, no s\u00f3lo se ha conseguido incrementar el n\u00famero de trabajadores aut\u00f3nomos, sino que, en sentido contrario, los seguimos perdiendo.<\/p>\n<p>En consecuencia, la cuesti\u00f3n parece clara y, por tanto, si queremos que haya m\u00e1s j\u00f3venes emprendedores, que a la larga son los que van a generar nuevos empleos (las peque\u00f1as Pymes son las que m\u00e1s empleo generan), es preciso ir cambiando esta mentalidad para que tanto desde la Administraci\u00f3n, como desde la ense\u00f1anza universitaria y de FP, se empiece a dar valor a la actividad emprendedora. Cambiando esa mentalidad en las aulas, poco a poco y haciendo que la Administraci\u00f3n vaya reduciendo ese complejo marco jur\u00eddico, lleno de normas mercantiles, laborales, fiscales y lleno tambi\u00e9n de una enorme y dispersa normativa, con leyes, reglamentos auton\u00f3micos u ordenanzas locales, se podr\u00e1 ir abriendo el camino para que las personas emprendan negocios, sin necesidad de tanta burocracia administrativa que, muchas veces, desalienta hasta a los m\u00e1s valientes y arriesgados.<\/p>\n<p>&nbsp;<\/p>\n<p>Pienso que, potenciar la cultura emprendedora, es algo que deber\u00edan de asumir como misi\u00f3n, tanto los responsables de la educaci\u00f3n formal, ya que esta ha de potenciarse en las aulas, como la propia administraci\u00f3n tanto estatal como auton\u00f3mica y local, para eliminar barreras burocr\u00e1ticas y facilitar el inicio de las actividades de emprendimiento. La participaci\u00f3n en programas dentro de las aulas que fomenten el esp\u00edritu emprendedor, seguro que traer\u00e1 consecuencias positivas en el futuro. En la Uni\u00f3n Europea estas pol\u00edticas son claras en el sentido que, animan a los estados miembros a que incluyan en los sistemas de ense\u00f1anza obligatoria, programas para promover esta cultura, siguiendo las directrices que marca la propia OCDE.<\/p>\n<p>En este momento, en Secot estamos colaborando con algunos centros de FP, impartiendo p\u00edldoras formativas dirigidas al emprendimiento. Tambi\u00e9n, en esta misma direcci\u00f3n, estamos negociando con la Universidad de Oviedo, la posibilidad de que utilicen nuestros servicios altruistas y voluntarios para colaborar dentro de nuestras posibilidades, en el desarrollo de esa cultura. Sabemos que nuestra aportaci\u00f3n puede ser s\u00f3lo una gota de agua en el oc\u00e9ano, pero, algo es algo y por algo hay que empezar. En Secot estamos dispuestos arrimar el hombro y una vez m\u00e1s, ponemos a disposici\u00f3n de las Administraciones, nuestra experiencia en gesti\u00f3n de negocios \u00a0y nuestros servicios altruistas, para colaborar abiertamente en esa necesaria mejora del emprendimiento asturiano.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El pasado 18 de diciembre, asist\u00ed en el Hotel de la Reconquista,\u00a0a la presentaci\u00f3n que organiz\u00f3 la\u00a0Consejer\u00eda de Empleo, Industria y Turismo del Principado de Asturias\u00a0y\u00a0la\u00a0Asociaci\u00f3n de Centros de Empresas P\u00fablicos del Principado de Asturias (ACEPPA)\u00a0del\u00a0Premio Asturias Regi\u00f3n Emprendedora Europea 2019,\u00a0otorgado por el\u00a0Comit\u00e9 de las Regiones. En este acto, se presentaron tambi\u00e9n a los once [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,6,7],"tags":[],"class_list":["post-1037","post","type-post","status-publish","format-standard","hentry","category-economia","category-empresa","category-formacion"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/posts\/1037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/comments?post=1037"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/posts\/1037\/revisions"}],"predecessor-version":[{"id":1038,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/posts\/1037\/revisions\/1038"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/media?parent=1037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/categories?post=1037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/hispadata\/wp-json\/wp\/v2\/tags?post=1037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}