{"id":16,"date":"2013-03-10T16:54:30","date_gmt":"2013-03-10T16:54:30","guid":{"rendered":"http:\/\/blog.elcomercio.es\/ivandesantiago\/?p=16"},"modified":"2013-03-10T16:54:30","modified_gmt":"2013-03-10T16:54:30","slug":"mercados-navidenos","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/2013\/03\/10\/mercados-navidenos\/","title":{"rendered":"MERCADOS NAVIDE\u00d1OS"},"content":{"rendered":"<p align=\"center\"><strong><span style=\"text-decoration: underline\">MERCADOS NAVIDE\u00d1OS<\/span><\/strong><\/p>\n<p align=\"center\"><strong><span style=\"text-decoration: underline\">\u00a0<\/span><\/strong><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Hace apenas cuatro a\u00f1os, cuando todos \u00e9ramos ricos, cuando el trabajo y el dinero no eran una preocupaci\u00f3n, sino un obst\u00e1culo o algo que se encontraba en nuestros bolsillos sin mucho esfuerzo, unos amigos planearon un viaje a los tradicionales mercados navide\u00f1os del norte de Europa.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El viaje finalmente no pudo realizarse, porque los controladores (o los pilotos, o los sobrecargos, o ya no s\u00e9 bien qui\u00e9n era el culpable esta vez ) de Iberia se empe\u00f1aron en hacer una huelga en esas fechas y trastornaron todo el espacio a\u00e9reo antes de Navidad. Lo que s\u00ed recuerdo era que la ruta comprend\u00eda 11 d\u00edas, part\u00eda de cerca de Berl\u00edn, visitaba pueblos del norte de Alemania, para luego pasar a la tradici\u00f3n suiza, recorrer algunas villas emblem\u00e1ticas de Chequia y acabar en Austria, en un precioso pueblo de monta\u00f1a con un mercado de casi 500 a\u00f1os de historia.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 De aquellos amigos que en su d\u00eda planeaban un viaje precioso hoy la mayor\u00eda no tienen trabajo, pero siguen teniendo ni\u00f1os e hipoteca. Otros est\u00e1n en ERE y dan gracias al cielo por trabajar media jornada. Sus parejas hace tiempo que ya ni sue\u00f1an con encontrar un empleo y miran diariamente los anuncios en los que, o bien no hay nada, o bien no hay nada. Esta es la oferta cotidiana.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Los que a\u00fan tenemos la suerte de trabajar, lo hacemos m\u00e1s por la fe en que este pa\u00eds necesita que nos levantemos todas las ma\u00f1anas y vayamos a luchar al foro de los tribunales que, en ocasiones, por el pago que recibimos por ello. A todos nos asola un virus pseudodepresivo para el que a\u00fan no se conoce antibi\u00f3tico dispensable.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pero lo que nadie nos va a quitar son las ganas y la imaginaci\u00f3n. Ni las fuerzas para seguir pensando que todos los d\u00edas sale el sol y habr\u00e1 un d\u00eda en que no se ponga, o cuando lo haga, nos volver\u00e1 a coger con el mojito en la mano, acompa\u00f1ados de buenos amigos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 As\u00ed que uno de aquellos que ahora malvive ha decidido que, para tiempos extremos, soluciones extremas, pero en casa no hay nada que ver, y la vida est\u00e1 en la calle, junto a aquellos que quieres. Y si hay que tomar una ca\u00f1a entre tres, pues se toma. Y si hay que llevarse el bocata, a nadie se le caen los anillos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Y por eso este fin de semana hab\u00eda mercadillo navide\u00f1o enla Iglesiade San L\u00e1zaro y otro en Colombres, preciosa villa llanisca casi en el l\u00edmite c\u00e1ntabro, famosa por su feria de indianos. Y creo que el fin de semana que viene otro en San Claudio y en Colloto. Y otro que hacen los ni\u00f1os de un instituto para pagar su jefe de estudios en el centro de Oviedo \u2026.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 As\u00ed que, para los que tengan esperanza y sigan queriendo vivirla Navidad, siempre hay hueco. Y si eso lo completan con la lectura de la novela o la visi\u00f3n de \u201cGrandes esperanzas\u201d, puede hacer una Navidad plena y por poco dinero. Porque esta situaci\u00f3n podr\u00e1 quitarnos muchas cosas, pero seguiremos inventando.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dice Luis Garc\u00eda Montero en su libro \u201cMa\u00f1ana no ser\u00e1 lo que dios quiera\u201d que, \u201c<em>para seguir viviendo, hay que aprender a aplazar los desenlaces<\/em>\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pues lo aplazamos, no pasa nada. Vendr\u00e1 otro tiempo y seguro que otras navidades, pero esta no nos la quita nadie.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Y los mercadillos del norte de Europa van a seguir ah\u00ed toda la vida. Los nuestros quiz\u00e1 no, porque sus ni\u00f1os crecer\u00e1n. Aprovechemos pues los malos momentos para buenas experiencias. Aunque no lo crean, nos lo merecemos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>MERCADOS NAVIDE\u00d1OS \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Hace apenas cuatro a\u00f1os, cuando todos \u00e9ramos ricos, cuando el trabajo y el dinero no eran una preocupaci\u00f3n, sino un obst\u00e1culo o algo que se encontraba en nuestros bolsillos sin mucho esfuerzo, unos amigos planearon un viaje a los tradicionales mercados navide\u00f1os del norte de Europa. &nbsp; \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El viaje finalmente [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-16","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts\/16\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/media?parent=16"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/categories?post=16"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/tags?post=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}