{"id":34,"date":"2013-03-10T17:10:43","date_gmt":"2013-03-10T17:10:43","guid":{"rendered":"http:\/\/blog.elcomercio.es\/ivandesantiago\/?p=34"},"modified":"2013-03-10T17:10:43","modified_gmt":"2013-03-10T17:10:43","slug":"la-calle-de-macano","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/2013\/03\/10\/la-calle-de-macano\/","title":{"rendered":"LA CALLE DE MACANO"},"content":{"rendered":"<p align=\"center\"><strong><span style=\"text-decoration: underline\">LA CALLE<\/span><\/strong><strong><span style=\"text-decoration: underline\"> DE<\/span><\/strong><strong><span style=\"text-decoration: underline\"> MACANO<\/span><\/strong><\/p>\n<p align=\"center\"><strong><span style=\"text-decoration: underline\">\u00a0<\/span><\/strong><\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El pasado viernes,la Juntade Gobierno del Ayuntamiento de Oviedo aprob\u00f3 otorgar el nombre de una calle a D. Eduardo Gonz\u00e1lez, m\u00e9dico cardi\u00f3logo que nos dej\u00f3 el pasado mes de septiembre v\u00edctima, c\u00f3mo no, de un c\u00e1ncer, esa pandemia que nos asola a diario, que se lleva a los buenos, a los mediocres y a los malos y contra la que no somos capaces de luchar m\u00e1s all\u00e1 de hacerle peque\u00f1as heridas, mientras nos devuelve dentelladas mortales.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tuve ocasi\u00f3n de glosar la figura de D. Eduardo el pasado mes de septiembre y, siendo concejal de Estad\u00edstica del Ayuntamiento de Oviedo,\u00a0 aprobar la concesi\u00f3n de una calle al padre de D. Eduardo, tambi\u00e9n m\u00e9dico ejemplar y, como su hijo, humanista del siglo XX en el m\u00e1s amplio sentido de la palabra. De los que trabaja la medicina, cultiva el deporte, apoya la cultura y a\u00fan tiene tiempo para ayudar a los dem\u00e1s siempre que puede.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Es una gran iniciativa, pero si me permiten una recomendaci\u00f3n, ll\u00e1menla calle de Macano. Quienes ten\u00edamos el orgullo de considerarnos sus amigos, siempre le llamamos as\u00ed. D. Eduardo en su consulta, pero Macano en cuanto se retiraba la bata. Creo que uno merece que le recuerden en sus mejores facetas, aunque para D. Eduardo eran todas. Hac\u00eda sencillo lo dif\u00edcil.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Y creo esta una ocasi\u00f3n apropiada para defender fervientemente que las calles de nuestra ciudad lleven el nombre de nuestros insignes conciudadanos. Olvidemos ya aquellas guerras fratricidas, tan alejadas de los ciudadanos, sobre si hay que mantener o retirar el nombre a Fern\u00e1ndez Capalleja por su pasado franquista. Yo prefiero que Fernando \u201cEl Pistolu\u201d tenga una calle en Montecerrao, que \u201cEl Tarangu\u201d est\u00e9 presente enLa Corredoria, que haya dos insignes obispos enLa Floridao que una preciosa plaza deLa Arga\u00f1osase llame \u201c\u00c1ngel Gonz\u00e1lez\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Considero que a la gente debe estimularle saber que grandes ovetenses fueron hombres que dejaron huella. Y que el callejero les recuerda por c\u00f3mo fueron y por c\u00f3mo vivieron. Los futuros campos deLa Pixarra(bendita Emilia, cu\u00e1ntos recuerdos te\u00f1idos de azul) llevar\u00e1n el nombre de Tensi y enLa Corredoriase homenajea a nuestro \u00e1rbitro m\u00e1s internacional.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Si nuestros ciudadanos pasaron a la historia, no seamos tan quijotes como para que sean otros quien lo reconozcan. Tenemos callejero bastante. Oviedo crece, poco a poco, pero el nomencl\u00e1tor sigue teniendo huecos que tienen aspirantes sobradamente meritorios para ocuparlo.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 De momento, Macano ya se queda para siempre en su ciudad.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>LA CALLE DE MACANO \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 El pasado viernes,la Juntade Gobierno del Ayuntamiento de Oviedo aprob\u00f3 otorgar el nombre de una calle a D. Eduardo Gonz\u00e1lez, m\u00e9dico cardi\u00f3logo que nos dej\u00f3 el pasado mes de septiembre v\u00edctima, c\u00f3mo no, de un c\u00e1ncer, esa pandemia que nos asola a diario, que se lleva a los buenos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/ivandesantiago\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}