{"id":10384,"date":"2024-10-13T21:05:51","date_gmt":"2024-10-13T19:05:51","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=10384"},"modified":"2024-10-13T21:05:51","modified_gmt":"2024-10-13T19:05:51","slug":"la-fiesta-y-el-drama","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2024\/10\/13\/la-fiesta-y-el-drama\/","title":{"rendered":"LA FIESTA Y EL DRAMA"},"content":{"rendered":"<p>Doce de octubre, Fiesta Nacional de Espa\u00f1a, tal como viene recogido en el Bolet\u00edn Oficial del Estado. Me parece m\u00e1s precisa la denominaci\u00f3n D\u00eda de la Hispanidad, porque es una alusi\u00f3n al v\u00ednculo hispanoamericano, que se empez\u00f3 a tejer cuando Rodrigo de Triana grit\u00f3 &#8216;\u00a1Tierra, tierra!&#8217;. Ma\u00f1ana de lluvia intensa en Madrid que no arredr\u00f3 al p\u00fablico, api\u00f1ado en las vallas, con impermeables transparentes, tan baratos como eficaces (no digan eficientes, por favor). Desde hace horas, m\u00e1s de 4.000 miembros de las Fuerzas Armadas est\u00e1n concentrados al fondo del Paseo del Prado, preparados para desfilar.<\/p>\n<p>En la tribuna de autoridades la pose y la gestualidad de los invitados denota la tensi\u00f3n de los \u00faltimos d\u00edas, tras filtrarse datos de la investigaci\u00f3n de la Unidad Central Operativa (UCO) de la Guardia Civil sobre las andanzas de Jos\u00e9 Luis \u00c1balos, Koldo Garc\u00eda, V\u00edctor de Aldama, Delcy Rodr\u00edguez, Javier Hidalgo, etc\u00e9tera. Los ministros hablan, m\u00e1s bien cuchichean, de dos en dos: Isabel Rodr\u00edguez y Carlos Cuerpo, Pilar Alegr\u00eda y Grande-Marlaska. Entre ellos vaga la gabardina de Salvador Illa, con una media sonrisa, como si recordara un sue\u00f1o de la madrugada. Como mucho hab\u00eda grupos de tres: Teresa Ribera, F\u00e9lix Bola\u00f1os y Pablo Bustinduy (ni un 5% de espa\u00f1oles saben que Bustinduy tiene asiento en el Consejo de ministros). Los ministros no miran para el entorno, forman sobre el estrado unidades cerradas, portadoras de secretos.<\/p>\n<p><strong>Barb\u00f3n<\/strong><br \/>\nA su espalda, la normalidad de la Fiesta Nacional: un almirante, un capit\u00e1n de nav\u00edo y un general del Ej\u00e9rcito de Tierra compart\u00edan conversaci\u00f3n con Josep Borrell y Adri\u00e1n Barb\u00f3n. No hay secretos, menudean las risas, el presidente asturiano est\u00e1 totalmente desinhibido, se dirige a los militares de alta graduaci\u00f3n con la camarader\u00eda propia de los que han hecho muchas guardias juntos. Se nota que le encanta hablar con Borrell. En el segundo semestre de 2018 y primeros meses de 2019 hab\u00eda un hombre m\u00e1s inteligente que el resto en el Gobierno de Pedro S\u00e1nchez. Y en cuanto pudo march\u00f3 a Bruselas. Era Borrell. Si me dejo guiar por las im\u00e1genes, todos esos ministros cuchicheando parecen pol\u00edticos de provincias y Barb\u00f3n es el \u00fanico pol\u00edtico madrile\u00f1o, con mando en plaza. Todo el mundo tiene fortalezas y debilidades. Entre las primeras, en el caso de Barb\u00f3n, est\u00e1 la espontaneidad en el trato, la calidez en la corta distancia, dosis altas de optimismo y facilidad de palabra. Los flancos d\u00e9biles ya los conocen ustedes, de sobra.<\/p>\n<p><strong>S\u00e1nchez<\/strong><br \/>\nLlega Pedro S\u00e1nchez unos segundos antes que los reyes de Espa\u00f1a, para opacar los abucheos. El presidente sigue los consejos de la Pantoja, &#8216;dientes, dientes&#8217;, y est\u00e1 todo el tiempo ri\u00e9ndose, como si estuviera pasando una semana feliz. Empieza la liturgia militar que deja poco margen para la improvisaci\u00f3n. Felipe VI y la Princesa de Asturias cantan &#8216;La muerte no es el final&#8217;; tambi\u00e9n lo hace Ayuso. La lluvia se hace m\u00e1s intensa y hay un peque\u00f1o c\u00f3nclave \u2013Rey, presidente de Gobierno, ministra de Defensa\u2013 sobre mantener o alterar el desfile. Al menos eso es lo que parece. Al final, todo sigue su curso. No se entender\u00eda que los ciudadanos aguantaran reclinados sobre las vallas y las autoridades no soportaran un chaparr\u00f3n.<\/p>\n<p>Veo fotos de la recepci\u00f3n en el Palacio Real. Est\u00e1 Alberto Garz\u00f3n, una especie de Bustinduy, pero con la camiseta de IU. No conozco mejor definici\u00f3n para el ser humano: animal de contradicciones. Cu\u00e1ntas veces hizo Garz\u00f3n profesi\u00f3n de fe republicana. Cuando era ministro acus\u00f3 al Rey de \u00abmaniobrar contra el Gobierno democr\u00e1ticamente elegido\u00bb. Y ahora que ha vuelto a ser un peat\u00f3n de la ciudad, se pone traje y corbata para hacer cola en el Palacio Real y participar en el besamanos de los Reyes. A unos los descubrimos cuando compraron un casopl\u00f3n en la sierra y a otros basta con verlos con gesto sumiso, que evoca al Pem\u00e1n de los a\u00f1os cincuenta, en Estoril, ante don Juan de Borb\u00f3n.<\/p>\n<p><strong>Ausencia<\/strong><br \/>\nPrimero pens\u00e9 que, producto de mis distracciones, no la hab\u00eda visto en la tribuna. Recapacit\u00e9: demasiado alta para no reconocerla. En la galer\u00eda de fotos no estaba; sin embargo, Pedro S\u00e1nchez luc\u00eda en varias con un chambergo para el agua, propio de los d\u00edas de asueto. No da una puntada sin hilo. Como en la \u00faltima ceremonia del Premio Cervantes, cuando recibi\u00f3 al Rey con las manos metidas en los bolsillos del pantal\u00f3n. El equipo de Moncloa cuida todos los detalles.<\/p>\n<p>No hay duda: Bego\u00f1a G\u00f3mez no asisti\u00f3 a la doble ceremonia, militar y palaciega. A falta de un parte m\u00e9dico que explique su ausencia, me inclino a pensar que la retirada es estrat\u00e9gica. No es oportuno estar bajo los focos cuando la gente se entera de que S\u00e1nchez negoci\u00f3 el rescate de Air Europa el mismo d\u00eda que Bego\u00f1a G\u00f3mez se vio con Hidalgo y, a la vez, conoce la p\u00e9rdida de la c\u00e1tedra en la Universidad Complutense por falta de alumnos. Hasta en las escuelas rurales asturianas hay una ratio m\u00e1s elevada de alumnos por maestro.<\/p>\n<p>Hac\u00eda muchos a\u00f1os que no ve\u00eda el desfile militar del 12 de octubre. La seriedad de los pol\u00edticos (Feij\u00f3o y Tellado), el malestar de Pachi L\u00f3pez (a su lado estaba Santiago Abascal), el gesto grave del Rey, delatan que las vigas del Estado soportan m\u00e1s carga que nunca. En solo 15 meses desde las \u00faltimas elecciones la situaci\u00f3n ha empeorado por decisiones del Gobierno que no estaban en la hoja de ruta. Malas leyes, peores acuerdos y ni uno solo de los c\u00f3mplices estaba en el estrado. Por lo menos descubrimos Am\u00e9rica.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Doce de octubre, Fiesta Nacional de Espa\u00f1a, tal como viene recogido en el Bolet\u00edn Oficial del Estado. Me parece m\u00e1s precisa la denominaci\u00f3n D\u00eda de la Hispanidad, porque es una alusi\u00f3n al v\u00ednculo hispanoamericano, que se empez\u00f3 a tejer cuando Rodrigo de Triana grit\u00f3 &#8216;\u00a1Tierra, tierra!&#8217;. Ma\u00f1ana de lluvia intensa en Madrid que no arredr\u00f3 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10384","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=10384"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10384\/revisions"}],"predecessor-version":[{"id":10385,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10384\/revisions\/10385"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=10384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=10384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=10384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}