{"id":10676,"date":"2025-02-15T22:47:19","date_gmt":"2025-02-15T21:47:19","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=10676"},"modified":"2025-02-15T22:47:19","modified_gmt":"2025-02-15T21:47:19","slug":"los-deficits-del-bienestar-oficial","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2025\/02\/15\/los-deficits-del-bienestar-oficial\/","title":{"rendered":"LOS D\u00c9FICITS DEL BIENESTAR OFICIAL"},"content":{"rendered":"\n<p>El brote de sarna que empez\u00f3 en la residencia Mixta de Pumar\u00edn (Gij\u00f3n), la que tiene m\u00e1s capacidad de albergar a personas dependientes de la red de Establecimientos Residenciales para Ancianos (ERA), se ha extendido a otros centros. Hay tres casos activos, dos en un centro de menores de Oviedo y otro en Gij\u00f3n. La Consejer\u00eda de Derechos Sociales y Bienestar deja la cifra en dos. En la Mixta hay, actualmente, cuatro residentes afectados y un trabajador. La informaci\u00f3n no es buena porque por un lado est\u00e1 lo que dicen fuentes sindicales y los trabajadores de los centros y por el otro, la consejera, Marta del Arco, y su equipo, que siempre rebajan o niegan las cifras (\u00abya no hay casos\u00bb) que proporcionan las personas que conviven con los residentes. Nos encontramos ante un cl\u00e1sico: nunca los pol\u00edticos y los gestores reconocen las dimensiones exactas de los problemas. Pasaba con la covid y aquel infausto doctor Sim\u00f3n. El brote del centro de menores de Oviedo empez\u00f3 en octubre y dicen los trabajadores que, todav\u00eda, no ha finalizado, pero la consejer\u00eda lo niega. Seg\u00fan los empleados, no estamos ante un problema de limpieza, sino de personal. Se increment\u00f3 la n\u00f3mina de atenci\u00f3n directa, pero en cocina y limpieza est\u00e1n bajo m\u00ednimos. Conclusi\u00f3n: es un problema de limpieza causado por la falta de personal.<\/p>\n\n\n\n<p>En la consejer\u00eda se acumulan las quejas. Hace unos meses tuvimos informaci\u00f3n sobre la particular forma que tiene el departamento de Bienestar de financiar las sentencias judiciales adversas con los recursos destinados a la alimentaci\u00f3n de los residentes del ERA. Por esa v\u00eda se fueron 1,3 millones. Tambi\u00e9n se desviaron recursos del ERA para satisfacer objetivos de gesti\u00f3n. Los problemas con la empresa adjudicataria del catering, que no cumpli\u00f3 el contrato, influyeron en el men\u00fa que sirven en las mesas.<\/p>\n\n\n\n<p>La pasada semana se informaba en estas p\u00e1ginas de la carencia de papel higi\u00e9nico en las escuelas infantiles, as\u00ed como centros de menores sin leche ni pan. Los proveedores afirmaron que hay facturas de productos b\u00e1sicos sin pagar desde hace dos a\u00f1os, elev\u00e1ndose la deuda a 90.000 euros. No entiendo nada. Se aprob\u00f3 el presupuesto del Principado con m\u00e1s recursos financieros de la etapa auton\u00f3mica; hay m\u00e1s dinero destinado a sanidad, educaci\u00f3n y servicios sociales que nunca, y resulta que ancianos, beb\u00e9s y menores acogidos tienen las carencias propias de un Gobierno que tiene bajos ingresos y deudas abultadas. Sospecho que hay empresas que con menos recursos prestan mejor servicio.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El brote de sarna que empez\u00f3 en la residencia Mixta de Pumar\u00edn (Gij\u00f3n), la que tiene m\u00e1s capacidad de albergar a personas dependientes de la red de Establecimientos Residenciales para Ancianos (ERA), se ha extendido a otros centros. Hay tres casos activos, dos en un centro de menores de Oviedo y otro en Gij\u00f3n. La [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10676"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=10676"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10676\/revisions"}],"predecessor-version":[{"id":10677,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10676\/revisions\/10677"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=10676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=10676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=10676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}