{"id":10685,"date":"2025-02-18T23:41:06","date_gmt":"2025-02-18T22:41:06","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=10685"},"modified":"2025-02-18T23:41:07","modified_gmt":"2025-02-18T22:41:07","slug":"energia-del-siglo-xxi","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2025\/02\/18\/energia-del-siglo-xxi\/","title":{"rendered":"ENERGIA DEL SIGLO XXI"},"content":{"rendered":"\n<p>El Principado ha dado el visto bueno a los dos primeros proyectos de parque de bater\u00edas. Uno en Granda (Siero) y el otro en Trasona (Corvera). Para finalizar la tramitaci\u00f3n administrativa s\u00f3lo queda la concesi\u00f3n de la licencia que es de competencia municipal. Los dos alcaldes, \u00c1ngel Garc\u00eda e Iv\u00e1n Fern\u00e1ndez, han hecho declaraciones favorables. Veinticuatro horas antes, cuatrocientos ciudadanos se manifestaron siguiendo la llamada de la plataforma Stop Bater\u00edas, que quiere detener todos los proyectos, incluyendo los que se van a ubicar en los pol\u00edgonos industriales, por razones de salud y de la supuesta existencia de alternativas \u00abm\u00e1s eficientes\u00bb. La nueva consejera de Transici\u00f3n Ecol\u00f3gica, Belarmina D\u00edaz, entiende que los dos parques cumplen con los requisitos previstos para ser construidos. As\u00ed estrena el cargo.<\/p>\n\n\n\n<p>Los parques de bater\u00edas son instrumentos necesarios para aprovechar las energ\u00edas renovables que se alimentan del sol y del viento. Con este tipo de herramientas so\u00f1aron siempre los ecologistas para dejar de depender de las energ\u00edas f\u00f3siles, causantes del efecto invernadero. A la hora de replantear el &#8216;mix&#8217; energ\u00e9tico las bater\u00edas resultan imprescindibles. En una regi\u00f3n donde hay una oferta variada de cursos de formaci\u00f3n, de todo tipo, ser\u00eda bueno que a alcaldes, concejales y vecinos les diera el Principado la oportunidad de tener un conocimiento riguroso sobre las ventajas e inconvenientes de esta tecnolog\u00eda. Miedos y prejuicios, sin base real, son propios del oscurantismo de las sociedades del pasado. Pronto se cumplir\u00e1n veinticinco a\u00f1os de la entrada en funcionamiento de Pico Gallo, primer campo e\u00f3lico asturiano, en Tineo, con capacidad para suministrar energ\u00eda el\u00e9ctrica a 25.000 hogares. Tambi\u00e9n entonces hab\u00eda plataformas contra los aerogeneradores. \u00bfCu\u00e1l ser\u00eda el futuro de Asturias sin energ\u00eda e\u00f3lica y sin bater\u00edas para almacenarla?<\/p>\n\n\n\n<p>En Espa\u00f1a, en proyectos de bater\u00edas, hay solicitados 22.000 megavatios de capacidad para conectarse a la red. Pocos instrumentos energ\u00e9ticos han tenido una respuesta tan r\u00e1pida por parte de los inversores. La cifra de megavatios demandada era la prevista por el Gobierno para el a\u00f1o 2030. Con las bater\u00edas la eficiencia energ\u00e9tica dar\u00e1 un salto espectacular y todo el mundo quiere beneficiarse de ella. Se est\u00e1 redise\u00f1ando el mapa de la energ\u00eda. Desde la revoluci\u00f3n industrial, Asturias fue la regi\u00f3n con m\u00e1s vocaci\u00f3n energ\u00e9tica de Espa\u00f1a: alumbramos el camino. No vamos a quedarnos atr\u00e1s.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El Principado ha dado el visto bueno a los dos primeros proyectos de parque de bater\u00edas. Uno en Granda (Siero) y el otro en Trasona (Corvera). Para finalizar la tramitaci\u00f3n administrativa s\u00f3lo queda la concesi\u00f3n de la licencia que es de competencia municipal. Los dos alcaldes, \u00c1ngel Garc\u00eda e Iv\u00e1n Fern\u00e1ndez, han hecho declaraciones favorables. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10685"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=10685"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10685\/revisions"}],"predecessor-version":[{"id":10687,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/10685\/revisions\/10687"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=10685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=10685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=10685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}