{"id":3534,"date":"2016-09-18T17:46:18","date_gmt":"2016-09-18T15:46:18","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=3534"},"modified":"2016-09-18T17:46:18","modified_gmt":"2016-09-18T15:46:18","slug":"una-inercia-fatal","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2016\/09\/18\/una-inercia-fatal\/","title":{"rendered":"UNA INERCIA FATAL"},"content":{"rendered":"<p>De r\u00e9cord en r\u00e9cord. La deuda del Principado se eleva a los 4.278 millones de euros. El dato es del pasado 30 de junio y lo acabamos de conocer ahora. Los n\u00fameros rojos de la Administraci\u00f3n auton\u00f3mica aumentan, ininterrumpidamente, sin una leve pausa para la esperanza. Trimestre a trimestre, como pelda\u00f1os de una escalera que nos lleva al abismo, la cifra engorda sin cesar. Del primer trimestre al segundo, la deuda ha crecido en 188 millones. En 2008, al empezar la crisis, deb\u00edamos 770 millones, y ocho a\u00f1os m\u00e1s tarde debemos 4.278 millones. Hemos m\u00e1s que quintuplicado la cantidad que adeud\u00e1bamos en 2008.<br \/>\n<strong>\u00a0 500 MILLONES ANUALES<\/strong><br \/>\nSi comparamos la deuda que arrastr\u00e1bamos el 30 de junio del pasado a\u00f1o y la que soportamos al finalizar el segundo trimestre del presente ejercicio, comprobamos que aument\u00f3 en casi 500 millones de euros. Para ser exactos en 489 millones en doce meses. Divididos por los d\u00edas que tiene el a\u00f1o descubrimos que un domingo, como hoy, un lluvioso martes de invierno o un prometedor s\u00e1bado de primavera, el Principado acrecienta sus n\u00fameros rojos en 1,3 millones de euros.<br \/>\n\u00bfC\u00f3mo puede ser? \u00bfC\u00f3mo se las arreglan Javier Fern\u00e1ndez y sus consejeros para que cada d\u00eda que pasa debamos 1,3 millones m\u00e1s, si la vida pol\u00edtica est\u00e1 detenida, el Principado no invierte pr\u00e1cticamente nada y el presupuesto est\u00e1 prorrogado? Luego contestaremos a los interrogantes.<br \/>\nPrimero veamos la respuesta pol\u00edtica que nos da el Principado, cada tres meses, al comprobar que su deuda valida aquel cursi slogan para novios del tardofranquismo: \u201choy m\u00e1s que ayer pero menos que ma\u00f1ana\u201d. De la medallita del amor a la deuda socialista. Los portavoces oficiales nos dicen invariablemente que tenemos un bajo nivel de deuda, de los m\u00e1s bajos de Espa\u00f1a.<br \/>\nNos obsequiaban con este argumento cuando la deuda asturiana equival\u00eda al 9% sobre el PIB. Actualmente est\u00e1 en el 19,5% del PIB, y siguen con la misma monserga. En aquella \u00e9poca afirmaban los dirigentes socialistas que est\u00e1bamos muy alejados de la media de endeudamiento del resto de regiones, y en la actualidad estamos ya a s\u00f3lo cinco puntos porcentuales.<br \/>\nSiempre pens\u00e9, y el paso del tiempo lo demuestra, que lo preocupante no era el volumen de la deuda sino el fuerte ritmo de su crecimiento. Ya hay cinco comunidades aut\u00f3nomas que est\u00e1n menos endeudas (Madrid, Pa\u00eds Vasco, Galicia, Canarias y La Rioja) que Asturias. En el \u00faltimo trimestre (abril-mayo-junio) la tasa de crecimiento de la deuda asturiana fue del 12,9%, \u00fanicamente superada por Extremadura.<br \/>\nVamos con los interrogantes. \u00bfQu\u00e9 hizo el Principado en la pasada primavera para ser la segunda regi\u00f3n espa\u00f1ola que m\u00e1s elev\u00f3 porcentualmente su deuda? Sorprendentemente la respuesta es nada. O nada especial. O, si se quiere, lo mismo que hace siempre, mantener inc\u00f3lume el sector p\u00fablico auton\u00f3mico.<br \/>\nHace mucho tiempo que la inversi\u00f3n p\u00fablica est\u00e1 en m\u00ednimos hist\u00f3ricos, el Principado no desarrolla ning\u00fan proyecto, y ni siquiera hace ya viajes con s\u00e9quito al extranjero. No es preciso que haga nada extra\u00f1o, basta con que financie el sector p\u00fablico para que autom\u00e1ticamente se eleve la deuda en otros 500 millones de euros.<br \/>\n<strong>SECTOR P\u00daBLICO<\/strong><br \/>\nLos ingresos fiscales no dan para financiar una Administraci\u00f3n tan costosa. El gasto corriente es tan elevado (sueldos, mantenimiento, intereses) que el Gobierno socialista lo paga pidiendo cr\u00e9ditos. Ninguna familia procede as\u00ed. Se recurre a distintas modalidades de cr\u00e9dito para adquirir casas, autom\u00f3viles, frigor\u00edficos o batidoras, pero la gente no se endeuda para financiar la compra de la comida o pagar la factura del suministro el\u00e9ctrico. Cuando hay sentido com\u00fan, en el caso de que los gastos excedan a los ingresos, se reducen los gastos, no se mantiene el mismo nivel de vida (de consumo) pidiendo ayuda a los bancos. Por esta v\u00eda, las fiestas de hoy se convierten en las penurias del ma\u00f1ana. El Gobierno de Javier Fern\u00e1ndez piensa distinto.<br \/>\nAl llegar al poder, el Gobierno de Rajoy hizo un plan de reducci\u00f3n del sector p\u00fablico auton\u00f3mico, dando libertad a los ejecutivos regionales para fijar la cuant\u00eda del recorte y los ritmos de ejecuci\u00f3n. Las 17 comunidades aut\u00f3nomas se pusieron a ello. El Principado fue el territorio que m\u00e1s tard\u00f3 en cumplir el plan comprometido y que se fij\u00f3 unos objetivos m\u00e1s modestos. La media regional de cierre de entes p\u00fablicos fue del 37,6% y el Principado se conform\u00f3 con cerrar el 16,6%. Como dice un amigo m\u00edo, los socialistas protegen m\u00e1s al sector p\u00fablico que a las joyas del Prerrom\u00e1nico.<br \/>\nUna deuda tan elevada origina unos desembolsos, entre intereses y amortizaciones, que suponen la tercera fuente de gasto del Principado, tras Sanidad y Educaci\u00f3n, y por delante de los Servicios Sociales. Vamos camino de entrar en el circuito de la pobreza: los impuestos que pagan los asturianos son transferidos por el Gobierno a los bancos.<br \/>\nYa es hora de que la oposici\u00f3n se tome en serio su papel y en vez de negociar sobre los impuestos a las hamburguesas, ponga a Javier Fern\u00e1ndez como condici\u00f3n ineludible para discutir el presupuesto de 2017 la presentaci\u00f3n de un plan cre\u00edble de reducci\u00f3n de deuda que pase por el cierre de chiringuitos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>De r\u00e9cord en r\u00e9cord. La deuda del Principado se eleva a los 4.278 millones de euros. El dato es del pasado 30 de junio y lo acabamos de conocer ahora. Los n\u00fameros rojos de la Administraci\u00f3n auton\u00f3mica aumentan, ininterrumpidamente, sin una leve pausa para la esperanza. Trimestre a trimestre, como pelda\u00f1os de una escalera que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3534","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/3534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=3534"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/3534\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=3534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=3534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=3534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}