{"id":9143,"date":"2023-04-24T20:12:48","date_gmt":"2023-04-24T18:12:48","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=9143"},"modified":"2023-04-24T20:12:48","modified_gmt":"2023-04-24T18:12:48","slug":"el-encierro-noticia-nacional","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2023\/04\/24\/el-encierro-noticia-nacional\/","title":{"rendered":"EL ENCIERRO, NOTICIA NACIONAL"},"content":{"rendered":"<p class=\"v-p\">Se celebran en Oviedo unas jornadas de trabajo sobre la situaci\u00f3n actual y perspectivas de futuro de los cuidados de larga duraci\u00f3n y el envejecimiento activo. La inauguraci\u00f3n corri\u00f3 a cargo de la consejera de Bienestar del Principado, Melania \u00c1lvarez, el alcalde, Alfredo Canteli, y el presidente de la C\u00e1mara de Comercio de Oviedo, Carlos Paniceres. En el sector hay una acertada participaci\u00f3n p\u00fablico-privada; las tres c\u00e1maras asturianas firmaron un convenio con el Principado que es pionero a escala nacional.<\/p>\n<p class=\"v-p\">La consejera aport\u00f3 algunos datos que sirven para dimensionar el problema. Hay 13.000 personas en residencias geri\u00e1tricas y otras tantas reciben ayuda a domicilio. Para el a\u00f1o 2030 se estima que ser\u00e1n, en conjunto, 40.000 personas. El Principado ha gastado en esta legislatura 1.000 millones de euros en las prestaciones de la Dependencia. Para dentro de siete a\u00f1os har\u00e1n falta 12.000 profesionales, s\u00f3lo, para la ayuda a domicilio. En la actualidad no hay, pr\u00e1cticamente, trabajadores sin emplear. La consejera sac\u00f3 conclusiones de las cifras: \u00abAsturias se consolida en Europa como centro de envejecimiento activo\u00bb. Los promotores de las jornadas valoraron que el sector sociosanitario mover\u00e1 la econom\u00eda regional a medio plazo. Carlos Paniceres estima que \u00abel sector crecer\u00e1 dos d\u00edgitos en los pr\u00f3ximos a\u00f1os\u00bb.<\/p>\n<p class=\"v-p\">Los datos y las declaraciones sugieren dos l\u00edneas de reflexi\u00f3n. La primera tiene que ver con el esfuerzo a realizar para satisfacer una demanda creciente. Hay que dedicar muchos m\u00e1s recursos humanos y materiales para atender a la gente impedida. La regi\u00f3n de la tercera edad debe tener unos servicios a la altura de esa realidad. Hay que habilitar a muchos m\u00e1s profesionales, para ello hace falta m\u00e1s gente que los instruya, centros de estudio, as\u00ed como m\u00e1s geri\u00e1tricos, centros de d\u00eda, etc. Hay que huir de la tentaci\u00f3n de creer que todo eso lo puede resolver el Principado. De esa forma crecen las listas de espera, con ofertas muy por debajo de las demandas. En el caso de la tercera edad la espera prolongada termina en muerte.<\/p>\n<p class=\"v-p\">La otra reflexi\u00f3n tiene que ver con la financiaci\u00f3n. \u00bfC\u00f3mo se paga todo esto? Si tenemos unos servicios muy destacados, si somos una regi\u00f3n de referencia en la materia, podremos llegar a captar demanda del exterior y por ah\u00ed entrar\u00e1n recursos. La econom\u00eda de un geri\u00e1trico es como la de un hotel. No obstante, ser\u00eda bueno que vayamos pensando en tener una econom\u00eda m\u00e1s productiva para poder financiar, v\u00eda impuestos, unos servicios sociales que crecer\u00e1n s\u00ed o s\u00ed.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Se celebran en Oviedo unas jornadas de trabajo sobre la situaci\u00f3n actual y perspectivas de futuro de los cuidados de larga duraci\u00f3n y el envejecimiento activo. La inauguraci\u00f3n corri\u00f3 a cargo de la consejera de Bienestar del Principado, Melania \u00c1lvarez, el alcalde, Alfredo Canteli, y el presidente de la C\u00e1mara de Comercio de Oviedo, Carlos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9143"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=9143"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9143\/revisions"}],"predecessor-version":[{"id":9144,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9143\/revisions\/9144"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=9143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=9143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=9143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}