{"id":9167,"date":"2023-05-05T22:53:15","date_gmt":"2023-05-05T20:53:15","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=9167"},"modified":"2023-05-05T22:53:15","modified_gmt":"2023-05-05T20:53:15","slug":"fecha-para-sacar-billete","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2023\/05\/05\/fecha-para-sacar-billete\/","title":{"rendered":"FECHA PARA SACAR BILLETE"},"content":{"rendered":"<p class=\"v-p\">No vamos a retrotraernos a los tiempos en que Zapatero dec\u00eda que en 2010 entrar\u00eda en uso la variante de Pajares, sino al pasado mes de noviembre, cuando en el convoy de pruebas iban el presidente del Principado y la ministra de Transportes, acompa\u00f1ados del s\u00e9quito oficial. Un viaje pleno de optimismo, posando ante la boca del t\u00fanel con el chaleco reflectante y la mirada te\u00f1ida por la Historia, como Napole\u00f3n ante las Pir\u00e1mides: \u00abEs el fin del aislamiento y se abrir\u00e1 una etapa de oportunidades\u00bb. El aislamiento acabar\u00eda en mayo. No hab\u00eda duda, los trenes vendr\u00edan cargados de turistas, como anticipo de un verano tur\u00edstico sin precedentes.<\/p>\n<p class=\"v-p\">Lleg\u00f3 mayo y en los t\u00faneles siguen los trabajos, perforando galer\u00edas de evacuaci\u00f3n y trazando rutas de escape para las ambulancias. En definitiva, trabajos de seguridad que ya estaban previstos cuando se realiz\u00f3 el viaje de pruebas en noviembre. Al parecer, la ministra y sus altos cargos manejaban una informaci\u00f3n incorrecta. No estamos ante un suceso imprevisto, como los trenes que no cab\u00edan por los t\u00faneles, sino ante una secuencia de trabajos normal, que, valorada por un capataz con experiencia, hubiera dado como resultado descartar mayo como fecha de finalizaci\u00f3n de la obra. Desde el Ministerio de Transportes se anuncia, ahora, el fin de los simulacros de seguridad para septiembre, pero no nos han dicho la causa que demor\u00f3 en cuatro meses los trabajos en los t\u00faneles.<\/p>\n<p class=\"v-p\">Para realizar el anuncio oficial de la apertura de la variante viajan hasta Asturias, el secretario general de Infraestructuras, Xavier Flores, y la presidenta de Adif, Mar\u00eda Luisa Dom\u00ednguez. El plan inicial sufri\u00f3 una peque\u00f1a modificaci\u00f3n, pura minucia: no sabremos cu\u00e1ndo empezar\u00e1n a entrar los trenes en servicio (la fecha que le interesa conocer a los asturianos), sino cu\u00e1ndo el expediente de la variante quedar\u00e1 en manos de la Agencia Estatal de Seguridad Ferroviaria. Bienvenidos sean los avances en las ventanillas administrativas, pero la clave est\u00e1 en conocer el mes, d\u00eda y hora en que los trenes atravesar\u00e1n la variante. Metidos, otra vez, en los laberintos de la burocracia, se abre un nuevo interrogante sobre la inauguraci\u00f3n de los t\u00faneles. La experiencia reciente, en otras l\u00edneas de alta velocidad, cifra entre dos y cuatro meses el tiempo que transcurre entre los simulacros de seguridad y el funcionamiento de la l\u00ednea. Dicen que ahora se sigue una variante burocr\u00e1tica m\u00e1s r\u00e1pida, pero no ser\u00e9 yo quien ponga la mano en el fuego por el acortamiento del plazo.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No vamos a retrotraernos a los tiempos en que Zapatero dec\u00eda que en 2010 entrar\u00eda en uso la variante de Pajares, sino al pasado mes de noviembre, cuando en el convoy de pruebas iban el presidente del Principado y la ministra de Transportes, acompa\u00f1ados del s\u00e9quito oficial. Un viaje pleno de optimismo, posando ante la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9167"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=9167"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9167\/revisions"}],"predecessor-version":[{"id":9168,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9167\/revisions\/9168"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=9167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=9167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=9167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}