{"id":9228,"date":"2023-05-30T22:37:25","date_gmt":"2023-05-30T20:37:25","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/?p=9228"},"modified":"2023-05-30T22:37:25","modified_gmt":"2023-05-30T20:37:25","slug":"la-gran-ausente","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/2023\/05\/30\/la-gran-ausente\/","title":{"rendered":"LA GRAN AUSENTE"},"content":{"rendered":"<p class=\"v-p\">Termin\u00f3 la campa\u00f1a electoral, un tiempo en que los candidatos, por propia iniciativa o requeridos por los medios, hablaron de cosas muy diversas. La sanidad, el declive demogr\u00e1fico, la industria, los problemas del campo, los fondos europeos, la movilidad, los trenes, las residencias de tercera edad, la vivienda, el medio ambiente, la innovaci\u00f3n, el turismo, la cooficialidad del bable, los impuestos, la ayuda a las empresas y un largo etc\u00e9tera en el que est\u00e1 incluido el voto \u00fatil y el rechazo a las coaliciones de gobierno.<\/p>\n<p class=\"v-p\">No digo que hayan aportado soluciones o que trataran con suficiente rigor los asuntos citados, pero, al menos, hablaron de ellos. Por eso resulta inexplicable que, una vez m\u00e1s, la educaci\u00f3n no estuviera en las agendas de la campa\u00f1a. La gran ausente.<\/p>\n<p class=\"v-p\">A lo largo de la legislatura tampoco se discuti\u00f3 sobre educaci\u00f3n, aunque s\u00ed surgieron asuntos relacionados con la actividad educativa, como cualquier incidencia en los autobuses que llevan a los ni\u00f1os a los colegios, la sustituci\u00f3n de las bajas de maestros y profesores, las becas para los comedores, etc\u00e9tera. Tambi\u00e9n en la Junta General del Principado se hacen referencias a cuestiones relacionadas con nuestro sistema educativo, como el gasto por alumno, las escuelas rurales o la necesidad de extender la red p\u00fablica del primer ciclo de Infantil. Todo eso est\u00e1 relacionado con la escolarizaci\u00f3n, en sentido amplio, pero no es el centro de la educaci\u00f3n. De educaci\u00f3n no se habla en Asturias ni durante las legislaturas ni en periodos electorales.<\/p>\n<div class=\"v-c-cmp v-n-mrg\">\n<h3 class=\"v-d-cmp-sub-hl\">Discurso \u00fanico<\/h3>\n<\/div>\n<p class=\"v-p\">Cuando el 15 de septiembre de 2008 se hundi\u00f3 Lehman Brothers, dirigentes pol\u00edticos y pueblo llano entraron en p\u00e1nico. En los informativos de mediod\u00eda, tras hablar de la quiebra, hac\u00edan referencia a que en Espa\u00f1a estaban asegurados los dep\u00f3sitos bancarios hasta los 20.000 euros, por el Fondo de Garant\u00eda de Dep\u00f3sitos. En los seis meses siguientes se perdieron 900.000 empleos. Entonces hizo fortuna la expresi\u00f3n de &#8216;la tormenta perfecta&#8217;.<\/p>\n<p class=\"v-p\">Ante un panorama tan negro se alz\u00f3 un discurso \u00fanico: hay que cambiar el modelo productivo. Lo repet\u00edan jefes y subordinados. El cambio de modelo productivo s\u00f3lo ser\u00eda posible dejando de apostar por la construcci\u00f3n y especializ\u00e1ndose en actividades que aportan m\u00e1s valor a\u00f1adido.<\/p>\n<p class=\"v-p\">En la base de ese discurso \u00fanico estaba la educaci\u00f3n. Sin una mejora del nuestro sistema educativo, sin una juventud m\u00e1s cualificada, no se puede cambiar el modelo productivo. Pasaron quince a\u00f1os y estamos como entonces, con el a\u00f1adido de la LOMLOE que es un desgraciado producto de la pandemia. En un contexto excepcional se aprob\u00f3, por primera vez, una ley de Educaci\u00f3n sin informe del Consejo de Estado.<\/p>\n<div class=\"v-c-cmp v-n-mrg\">\n<h3 class=\"v-d-cmp-sub-hl\">Curr\u00edculo<\/h3>\n<\/div>\n<p class=\"v-p\">No entiendo c\u00f3mo nuestros representantes en la Junta General del Principado se atreven a discutir de la descarbonizaci\u00f3n o se ilusionan con el hidr\u00f3geno, mientras muestran un desinter\u00e9s absoluto por lo que estudian sus hijos o nietos.<\/p>\n<p class=\"v-p\">Una y otra vez, a\u00f1o tras a\u00f1o, eluden discutir sobre el curr\u00edculo (objetivos, contenidos, metodolog\u00edas, sistemas de evaluaci\u00f3n), elemento central en la transmisi\u00f3n del conocimiento de unas generaciones a otras. Hay una autocensura generalizada que les impide hablar de planes de estudio, de las asignaturas, de lo que aprenden o ignoran en las aulas. Tambi\u00e9n se autoimponen no discutir sobre los criterios de evaluaci\u00f3n. Se inhiben ante la promoci\u00f3n de curso casi autom\u00e1tica de los alumnos, pero sobre sobre el despliegue de los aerogeneradores e\u00f3licos hay un mont\u00f3n de preguntas en la Junta.<\/p>\n<p class=\"v-p\">El profesorado ha mostrado su parecer sobre normas, m\u00e9todos y calificaciones, aunque de forma aislada. No se pueden pedir heroicidades. Ah\u00ed est\u00e1n los cualificados funcionarios del Centro de Investigaciones Sociol\u00f3gicas (CIS) que observan la degradaci\u00f3n de su organismo, sondeo tras sondeo, sin decir ni p\u00edo. El problema no es de profesionales ni de gremios, sino de nuestra clase pol\u00edtica que muestra un desinter\u00e9s asombroso por la educaci\u00f3n.<\/p>\n<div class=\"v-c-cmp v-n-mrg\">\n<h3 class=\"v-d-cmp-sub-hl\">Eficiencia<\/h3>\n<\/div>\n<p class=\"v-p\">Cuando a nuestros parlamentarios no les queda otro remedio que decir algo sobre la educaci\u00f3n, unos presumen de gastar mucho y otros exigen gastar m\u00e1s. Y a otra cosa. Hace alg\u00fan tiempo le\u00ed un estudio de la Universidad de Comillas sobre la eficiencia del gasto de las comunidades aut\u00f3nomas en educaci\u00f3n, con datos de 2016. Entre las tres regiones m\u00e1s eficientes estaba Navarra, a la cabeza del gasto por alumno, y Madrid, que era la que menos gastaba. Las 17 comunidades, de media, pod\u00edan haberse ahorrado un 19% del gasto y obtener los mismos resultados. No consiste en cu\u00e1nto, sino en c\u00f3mo.<\/p>\n<p class=\"v-p\">En el \u00faltimo estudio del Banco de Espa\u00f1a se constata que en la primera d\u00e9cada del siglo est\u00e1bamos 9 puntos por debajo de la media europea en PIB per c\u00e1pita. Ahora estamos 17 puntos por debajo. Para mejorar, cita tres reformas, entre ellas, \u00abrevisar la eficiencia en el gasto en educaci\u00f3n\u00bb. Recuerda nuestros dos d\u00e9ficits cr\u00f3nicos: bajas tasas de productividad y empleo, que s\u00f3lo se remedian mejorando la educaci\u00f3n.<\/p>\n<p class=\"v-p\">La pol\u00edtica se verifica en ciclos de cuatro a\u00f1os, lo que va de elecci\u00f3n a elecci\u00f3n. Las reformas en educaci\u00f3n necesitan veinticinco a\u00f1os para madurar. Quiz\u00e1s por eso los pol\u00edticos se olvidan de ella.<\/p>\n<p class=\"v-p\">Sin embargo, todas las promesas de futuro realizadas en la campa\u00f1a s\u00f3lo se llevar\u00e1n a cabo si se cambia la educaci\u00f3n, con otros contenidos y m\u00e9todos. Hace falta m\u00e1s gente para levantar Asturias, s\u00ed, pero, sobre todo, m\u00e1s cualificada.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Termin\u00f3 la campa\u00f1a electoral, un tiempo en que los candidatos, por propia iniciativa o requeridos por los medios, hablaron de cosas muy diversas. La sanidad, el declive demogr\u00e1fico, la industria, los problemas del campo, los fondos europeos, la movilidad, los trenes, las residencias de tercera edad, la vivienda, el medio ambiente, la innovaci\u00f3n, el turismo, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9228"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/comments?post=9228"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9228\/revisions"}],"predecessor-version":[{"id":9229,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/posts\/9228\/revisions\/9229"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/media?parent=9228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/categories?post=9228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/largo_de_cafe\/wp-json\/wp\/v2\/tags?post=9228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}