{"id":1916,"date":"2024-07-27T17:32:48","date_gmt":"2024-07-27T15:32:48","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/?p=1916"},"modified":"2024-07-27T17:32:48","modified_gmt":"2024-07-27T15:32:48","slug":"prepararse-para-la-soledad","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/2024\/07\/27\/prepararse-para-la-soledad\/","title":{"rendered":"PREPARARSE PARA LA SOLEDAD"},"content":{"rendered":"<p>No es que los l\u00edos de familia, las separaciones y las relaciones familiares complicadas sean algo nuevo y exclusivo de nuestra sociedad ni mucho menos. Forman parte de la historia. Pero es cierto que hoy abundan m\u00e1s en comparaci\u00f3n con otras \u00e9pocas pues los v\u00ednculos afectivos se han debilitado debido a la mayor fragilidad y complicaci\u00f3n de las relaciones personales. Hay hijos que se desvinculan totalmente de los dos o de uno de los progenitores. Hay padres o madres que hacen lo propio si tienen que vivir con hijo o yerno o nuera insoportables. Al aumentar las separaciones y la debilitaci\u00f3n de la instituci\u00f3n familiar hoy resulta m\u00e1s dif\u00edcil vivir satisfactoriamente todas nuestras relaciones familiares. Hay un cruce amplio de intereses y por tanto de posibles conflictos. Eso hace que el apoyo buscado y deseado as\u00ed como el amparo que todos necesitamos est\u00e9 m\u00e1s deteriorado y muchos vivan un aislamiento o soledad anticipada mayor de la que resulta deseable.<\/p>\n<p>Es un avance de la soledad que se va extendiendo en amplias capas y estratos sociales desde el \u00e1mbito de la pobreza a la riqueza. Nadie escapa de esa lacra.<\/p>\n<p>Es necesario tomarlo como un entrenamiento, pues a la vejez la soledad ser\u00e1 mucho m\u00e1s dolorosa, muy lejos de las familias de anta\u00f1o con numerosos miembros y donde la estabilidad era mayor y el entorno m\u00e1s c\u00e1lido y emocionalmente m\u00e1s seguro y previsible.<\/p>\n<p>Si uno no acierta a vivir su soledad tempranamente sin perturbarse, dif\u00edcilmente soportar\u00e1 la soledad impuesta en sus \u00faltimos a\u00f1os, si no se tienen hijos o cuando estos est\u00e9n lejos por motivos laborales, las familias est\u00e9n m\u00e1s desarticuladas o el ego\u00edsmo y las tensiones afloren por herencias u otras causas.<\/p>\n<p>Es signo de los tiempos y ante lo inevitable uno debe aprender a aceptar y adaptarse a los hechos, si no pueden cambiarse.<\/p>\n<p>No pretendo echar un jarro de agua fr\u00eda ni quiero ventilar el pesimismo. Se trata de tener en cuenta los hechos actuales y los que se avecinan para estar preparados, por si acaso.<\/p>\n<p>Y los que tengan la suerte de vivir relaciones armoniosas que disfruten cuanto puedan de ese privilegio y de esa suerte, negada a muchos otros.<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No es que los l\u00edos de familia, las separaciones y las relaciones familiares complicadas sean algo nuevo y exclusivo de nuestra sociedad ni mucho menos. Forman parte de la historia. Pero es cierto que hoy abundan m\u00e1s en comparaci\u00f3n con otras \u00e9pocas pues los v\u00ednculos afectivos se han debilitado debido a la mayor fragilidad y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9,18,48],"tags":[226,425,472,598,654,842],"class_list":["post-1916","post","type-post","status-publish","format-standard","hentry","category-amor","category-contratiempos","category-familia","category-soledad","tag-conflictos","tag-familia-2","tag-hijos-2","tag-miguel-silveira","tag-padres","tag-soledad-2"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"predecessor-version":[{"id":1918,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1916\/revisions\/1918"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}