{"id":1954,"date":"2024-12-22T20:18:19","date_gmt":"2024-12-22T19:18:19","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/?p=1954"},"modified":"2024-12-22T20:18:19","modified_gmt":"2024-12-22T19:18:19","slug":"que-puedes-hacer-tu","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/2024\/12\/22\/que-puedes-hacer-tu\/","title":{"rendered":"\u00bfQU\u00c9 PUEDES HACER TU?"},"content":{"rendered":"\n<p><br><br>Fue John F. Kennedy quien en su discurso inaugural dijo \u201cNo te preguntes qu\u00e9 puede hacer tu pa\u00eds por ti sino qu\u00e9 puedes hacer tu por tu pa\u00eds\u201d Ocurre en todas las latitudes. Si nos ponemos a escuchar u observar el comportamiento colectivo es altamente frecuente que los ciudadanos tendamos a preguntarnos, esperar y protestar por lo que los dem\u00e1s pueden y deben hacer por nosotros. Las quejas surgen diariamente en nuestra conciencia y emergen en  nuestras conversaciones por los incumplimientos de los dem\u00e1s en todos los niveles. Y llevamos raz\u00f3n pero ese malestar no  sirve m\u00e1s  all\u00e1 del puro desahogo, al contrario, la irritabilidad y la agresividad se extienden envenenando el ambiente social y personal.<br>Por eso viene bien recordar las palabras de aquel ilustre presidente y pasar a la acci\u00f3n de preguntarse \u00bfqu\u00e9 estoy haciendo yo\u2026bla, bla, bla? para implicarse y empezar a cambiar la parte que nos toca. <br>Se puede aplicar este comportamiento en la familia y  en todas las instituciones pues todos somos miembros de varias de ellas a distintos niveles. Somos usuarios, miembros de diferentes comunidades y finalmente ciudadanos de un estado.<br>En lugar de esperar a que otros cumplan sus obligaciones o criticar se deber\u00eda  empezar por uno mismo a cumplir la parte  que nos toca en todos los aspectos. Si es en el terreno sanitario, poniendo los cuidados pertinentes. Si es en la pareja o en la familia, aportando nuestra parte positiva y cumpliendo bien nuestras obligaciones. Como empleados \u00eddem de lienzo, sin tener que esperar a que cambien los jefes. Si es en la circulaci\u00f3n no esperar a que el Ministerio arregle las carreteras. Si en la limpieza de la ciudad no ensuciando, escupiendo o arrojando el vaciado paquete de tabaco en una acera o limpiando las cacas de nuestro can. Y as\u00ed sucesivamente. Cada cual puede decir que su acci\u00f3n es peque\u00f1a y limitada y es cierto, pero tambi\u00e9n lo es que la suma de miles y millones de actuaciones en la direcci\u00f3n apropiada y constructiva consigue un cambio progresivo, pudiendo llegar al conocido  efecto mariposa y recodando que muchos pocos hacen un mucho. <br>El caso es que existe una tendencia a centrarse en exigir responsabilidades obviando comenzar por cumplir las propias para ir contribuyendo a resolver los distintos problemas. \t<br><br><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Fue John F. Kennedy quien en su discurso inaugural dijo \u201cNo te preguntes qu\u00e9 puede hacer tu pa\u00eds por ti sino qu\u00e9 puedes hacer tu por tu pa\u00eds\u201d Ocurre en todas las latitudes. Si nos ponemos a escuchar u observar el comportamiento colectivo es altamente frecuente que los ciudadanos tendamos a preguntarnos, esperar y protestar [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[598],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1954"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/comments?post=1954"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1954\/revisions"}],"predecessor-version":[{"id":1959,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/1954\/revisions\/1959"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/media?parent=1954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/categories?post=1954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/tags?post=1954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}