{"id":314,"date":"2012-05-21T21:40:52","date_gmt":"2012-05-21T20:40:52","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/?p=314"},"modified":"2012-05-21T21:40:52","modified_gmt":"2012-05-21T20:40:52","slug":"que-hicimos-mal","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/2012\/05\/21\/que-hicimos-mal\/","title":{"rendered":"\u00bfQU\u00c9 HICIMOS MAL?"},"content":{"rendered":"<p align=\"center\"><a href=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2012\/05\/PADRES-CULPABLE.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-315\" title=\"PADRES CULPABLE\" src=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2012\/05\/PADRES-CULPABLE.jpg\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/7\/2012\/05\/PADRES-CULPABLE.jpg 670w, https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/7\/2012\/05\/PADRES-CULPABLE-300x179.jpg 300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Me dan mucha pena esos padres que habiendo procedido en conciencia y con esmero en la educaci\u00f3n de sus hijos, en cuanto uno de estos se desv\u00eda del camino y pierde el control de sus estribos con conductas impropias de quien ha sido educado razonablemente, se sienten muy culpables y se preguntan reiteradamente en qu\u00e9 habr\u00e1n fallado para que se de tal resultado. Si unos padres han procedido bien seg\u00fan su entendimiento y en conciencia y ocurre tal desenlace es l\u00f3gico que sufran al verse malogrados sus intentos de que el hijo sea una persona hecha y derecha, pero les conviene pensar que lo que sea su hijo en el futuro no depende \u00fanicamente de su labor educativa en cuanto padres. Esta es muy importante hacerla bien pero hay que tener presente<br \/>\nque hay tambi\u00e9n otras influencias ambientales, otros factores externos a la familia, otras personas con las que esos hijos se van relacionando (las malas compa\u00f1\u00edas por ejemplo) y todo ello va dejando un poso de influencia no siempre en la l\u00ednea deseada. Pero adem\u00e1s existen los genes que ejercen su fuerza en las conductas y por si fuera poco hay que tener tambi\u00e9n en cuenta la propia<br \/>\nelaboraci\u00f3n que ese hijo ir\u00e1 haciendo con todo lo que\u00a0aprende y con todo lo que le llega desde fuera. El producto final puede no parecerse al sano intento de los padres y por ello no deber\u00edan sentirse tan culpables. No es sorprendente que en cuanto un hijo falla en sus comportamientos y se aleja de la normalidad los padres se pregunten \u00bfqu\u00e9 hicimos mal? pero ser\u00eda muy \u00fatil que de inmediato considerasen que no hay una relaci\u00f3n perfecta \u00a0y lineal entre la educaci\u00f3n familiar y el resultado derivado. La culpa en esos casos puede arruinar a las familias y no conseguir que el hijo enderece su rumbo. Hay que ser fr\u00edos y fuertes para no sucumbir al sentimiento de la culpa pero es preciso ser claros. Uno no puede cargar con culpas que no tiene. Si las tiene se deben reparar en lo posible, pero si no, hay que arrojarlas a la basura y seguir disfrutando de la vida, aunque no sea lo mismo que si todo saliese conforme a lo esperado y deseado.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Me dan mucha pena esos padres que habiendo procedido en conciencia y con esmero en la educaci\u00f3n de sus hijos, en cuanto uno de estos se desv\u00eda del camino y pierde el control de sus estribos con conductas impropias de quien ha sido educado razonablemente, se sienten muy culpables y se preguntan reiteradamente en qu\u00e9 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[12,51],"tags":[259,342,378,424,472,598,654],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/314"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/comments?post=314"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/314\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/categories?post=314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/tags?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}