{"id":327,"date":"2012-06-17T20:37:01","date_gmt":"2012-06-17T19:37:01","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/?p=327"},"modified":"2012-06-17T20:37:01","modified_gmt":"2012-06-17T19:37:01","slug":"espera","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/2012\/06\/17\/espera\/","title":{"rendered":"\u00a1ESPERA!"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2012\/06\/Esperare-a27762941.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-328\" title=\"Esperare-a27762941\" src=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2012\/06\/Esperare-a27762941.jpg\" alt=\"\" width=\"300\" height=\"238\" srcset=\"https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/7\/2012\/06\/Esperare-a27762941.jpg 1000w, https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/7\/2012\/06\/Esperare-a27762941-300x239.jpg 300w, https:\/\/static-blogs.elcomercio.es\/wp-content\/uploads\/sites\/7\/2012\/06\/Esperare-a27762941-768x611.jpg 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A que todo el mundo est\u00e9 sentado a la mesa para empezar a<br \/>\ncomer<\/p>\n<p>A que amanezca para que no lo veas tan negro<\/p>\n<p>A que te llegue el turno para hacer tu gesti\u00f3n<\/p>\n<p>A que suene el m\u00f3vil tres veces antes de contestar<\/p>\n<p>A que el otro termine para intervenir en vez de \u00a0interrumpirle<\/p>\n<p>A pensarlo dos veces antes de reaccionar a una provocaci\u00f3n<\/p>\n<p>A que se abra el sem\u00e1foro para meter la primera<\/p>\n<p>A que acabe de pasar el peat\u00f3n en el paso de cebra<\/p>\n<p>A cruzar los puentes cuando llegues a ellos en vez de<br \/>\nanticipar y preocuparte<\/p>\n<p>A estar seguro de algo antes de acusar<\/p>\n<p>A que pase el tiempo para que te asista la raz\u00f3n<\/p>\n<p>A que transcurra el tiempo para que tu dolor se aten\u00fae<\/p>\n<p>A tener algo ahorrado para meterte en un gran gasto<\/p>\n<p>A que llegue el momento oportuno para actuar de manera<br \/>\nacertada<\/p>\n<p>A ver pasar delante de tu casa el cad\u00e1ver de tu enemigo<\/p>\n<p>A que se te pase el enfado para hablar con mesura, con<br \/>\nobjetividad<\/p>\n<p>A conseguir tu meta a base de tu esfuerzo sostenido y tu<br \/>\nperseverancia<\/p>\n<p>A que pase la tormenta para que llegue la calma.<\/p>\n<p>A que crezca la flor sin estirarla<\/p>\n<p>Espera que algo bueno te suceda. Espera, que da tranquilidad,<br \/>\nque da serenidad, que la precipitaci\u00f3n nunca es recomendable. Espera, ten<br \/>\npaciencia, todo se arreglar\u00e1. La espera aumenta los aciertos y disipa las dudas.<br \/>\nEspera, \u00bfA d\u00f3nde vas con tanta prisa?<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A que todo el mundo est\u00e9 sentado a la mesa para empezar a comer A que amanezca para que no lo veas tan negro A que te llegue el turno para hacer tu gesti\u00f3n A que suene el m\u00f3vil tres veces antes de contestar A que el otro termine para intervenir en vez de \u00a0interrumpirle [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[42,53],"tags":[388,490,598,652,711,879],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/327"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/comments?post=327"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/327\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/media?parent=327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/categories?post=327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/tags?post=327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}