{"id":479,"date":"2013-02-26T13:46:24","date_gmt":"2013-02-26T12:46:24","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/?p=479"},"modified":"2013-02-26T13:46:24","modified_gmt":"2013-02-26T12:46:24","slug":"prever-para-no-llorar","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/2013\/02\/26\/prever-para-no-llorar\/","title":{"rendered":"PREVER PARA NO LLORAR"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2013\/02\/PREVENIR.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-480\" title=\"PREVENIR\" src=\"\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2013\/02\/PREVENIR.jpg\" alt=\"\" width=\"300\" height=\"277\" srcset=\"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2013\/02\/PREVENIR.jpg 600w, https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-content\/uploads\/sites\/7\/2013\/02\/PREVENIR-300x278.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Fue en Inglaterra donde o\u00ed por primera vez este refr\u00e1n que me qued\u00f3 grabado: &#8220;No merece la pena llorar sobre la leche derramada&#8221;. Fant\u00e1stico refr\u00e1n que refleja c\u00f3mo la falta de previsi\u00f3n lleva a algunas personas a llorar y lamentarse cuando algo no tiene ya remedio y lo habr\u00eda tenido de haber puesto el cuidado necesario antes de decidir precipitadamente. Cuando algo no tiene ya remedio puede uno pedir perd\u00f3n, sentir el peso de la culpa o flagelarse, pensando qu\u00e9 tonto ha sido o qu\u00e9 precipitado o inconsciente. Son naturales esos sentimientos pues la desaz\u00f3n del fallo cometido necesita psicol\u00f3gicamente una reacci\u00f3n emocional acorde con la desesperaci\u00f3n de lo inevitable ya. Por eso, aunque el ser humano no es dado a prevenir y adelantarse porque cuesta trabajo, esfuerzo o sacrificio o porque pensamos que quiz\u00e1s no vaya a ocurrir nada, la mejor estrategia es la de adelantarse en temas delicados y analizar las posibles consecuencias que tienen nuestros actos, para no tener que exponernos al dolor de la culpa o la impotencia. Como quiera que la naturaleza es neutra y no perdona sino que aplica las consecuencias independientemente del sexo, de la edad o la condici\u00f3n del\u00a0 agente es bueno acostumbrarse a mirar el corto o el medio y largo plazo e imaginar qu\u00e9 pasar\u00e1 si transgredimos las normas que tiene bien dispuestas. Ser\u00eda largo y prolijo, a fuer de innecesario, citar aqu\u00ed la lista de acciones que encierran riesgos indeseables para todos nosotros. M\u00e1s que de hacer la lista cada cual, de lo que m\u00e1s se trata es de acostumbrarse a pensar y preguntarse, de cuando en cuando, qu\u00e9 nos puede ocurrir o a qu\u00e9 nos exponemos al actuar de ciertas formas y maneras. Es decir acostumbrar a nuestros hijos y a nosotros mismos a prevenir males futuros en lugar de tener que afrontar quiz\u00e1s imposibles remedios a posteriori. Es pr\u00e1ctica corriente liarse la manta a la cabeza y no querer pensar ni imaginar los males que pueden derivarse, pero luego no deber\u00edamos prorrumpir en lamentos o en sollozos a los ojos de todos para inspirar l\u00e1stima o volcar sobre otros angustias de las que solo nosotros somos los responsables. Entre las decisiones que m\u00e1s tienen que ver con la previsi\u00f3n y que m\u00e1s da\u00f1o nos hacen est\u00e1n las referentes a la salud, el dinero y el amor, los tres temas siempre candentes y motivos de miles de canciones y de creaciones literarias. Prever, prevenir, adelantarse, esa es la cuesti\u00f3n para evitar caer, romper el recipiente y derramar la leche. Esto no es nuevo, como la Coca Cola, pero conviene recordarlo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&nbsp; Fue en Inglaterra donde o\u00ed por primera vez este refr\u00e1n que me qued\u00f3 grabado: &#8220;No merece la pena llorar sobre la leche derramada&#8221;. Fant\u00e1stico refr\u00e1n que refleja c\u00f3mo la falta de previsi\u00f3n lleva a algunas personas a llorar y lamentarse cuando algo no tiene ya remedio y lo habr\u00eda tenido de haber puesto el [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,25,43],"tags":[117,227,345,402,507,598,707],"class_list":["post-479","post","type-post","status-publish","format-standard","hentry","category-bienestar","category-inteligencia","category-razonar","tag-anticiparse","tag-consecuencias","tag-efectos","tag-evitar","tag-inevitable","tag-miguel-silveira","tag-prevenir"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/psicologo-de-cabecera\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}