{"id":672,"date":"2016-06-07T18:43:12","date_gmt":"2016-06-07T16:43:12","guid":{"rendered":"http:\/\/blogs.elcomercio.es\/que-nos-pasa\/?p=672"},"modified":"2016-06-07T18:43:12","modified_gmt":"2016-06-07T16:43:12","slug":"mas-alla-del-area-metropolitana-un-proyecto-para-asturias","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/2016\/06\/07\/mas-alla-del-area-metropolitana-un-proyecto-para-asturias\/","title":{"rendered":"M\u00e1s all\u00e1 del \u00c1rea Metropolitana: un proyecto para Asturias"},"content":{"rendered":"<p style=\"text-align: left\">La presentaci\u00f3n de estrategias para el \u00e1rea metropolitana de Asturias, elaboradas por t\u00e9cnicos del Principado y de la Universidad, \u00a0ha sido recibida por ciudadan\u00eda, sociedad civil, clase pol\u00edtica y ayuntamientos implicados, con m\u00e1s escepticismo que ilusi\u00f3n, quiz\u00e1 porque conceptos tan abstractos\u00a0 no se comprendan f\u00e1cilmente.<\/p>\n<p style=\"text-align: left\">Lo primero que cabe plantearse es \u00bfqu\u00e9 es un \u00e1rea metropolitana? \u00a0Tenemos que olvidar el concepto tradicional de ciudad, f\u00edsico, finito, limitado, subsidiario de la vieja ciudad preindustral, m\u00e1s que compacta, amurallada. La ciudad se define desde hace d\u00e9cadas, en t\u00e9rminos funcionales, de relaci\u00f3n, de intensidad de intercambios entre n\u00facleos urbanos o municipios. Era un concepto reservado a \u00e1reas urbanas con cientos de miles o millones de habitantes.\u00a0 Pero, desde 2001, los use\u00f1os definen a las peque\u00f1as \u2013unas docenas de miles de habitantes- \u00a0como \u00e1reas micropolitanas.<\/p>\n<p style=\"text-align: left\">La siguiente pregunta es \u00bfy es el \u00e1rea central de Asturias un \u00e1rea metropolitana? La\u00a0 respuesta es: s\u00ed.\u00a0 Otros pa\u00edses nos llevan ventaja en esto de ahormarlas (y gestionarlas). Los criterios son muchos, pero casi todos coinciden en considerar que se da relaci\u00f3n metropolitana cuando se supera \u00a0un umbral de entre el 25% y el 40% de trabajadores residentes en un municipio trabajando en otro cercano. Pues bien, todos los concejos del \u00e1rea central superan el umbral m\u00e1s exigente. Oviedo y Gij\u00f3n est\u00e1n por debajo, pero superan el \u00a025%, pese a cierta tendencia insular de Gij\u00f3n. Y la intensidad de la relaci\u00f3n crece d\u00e9cada a d\u00e9cada.\u00a0 M\u00e1s a\u00fan, el \u00e1rea central cumple con los requisitos establecidos por la UE para ser considerada Metropolitan Growth Area (MEGA). Por tanto, la ambici\u00f3n metropolitana no es algo que nos venga grande. \u00a0Alguno dir\u00e1 que en Asturias no hay ninguna ciudad dominante, como en Bilbao, Madrid o Barcelona. \u00a0Pero son innumerables los ejemplos de sistemas urbanos sin ciudad dominante. Ejemplos: en Espa\u00f1a, la Bah\u00eda de C\u00e1diz. O Pontevedra-Vigo. Como el R\u00fchr en Alemania. O las Twin Cities \u2013St. Louis-Minneapolis- en Estados Unidos. El \u00e1rea asturiana no es una rareza.<\/p>\n<p style=\"text-align: left\">Tercero, hay que pensar en las consecuencias. El \u00e1rea central de Asturias implica gestionar un mill\u00f3n de desplazamientos diarios. Esos que provocan atascos en la \u201cY\u201d o las entradas a Oviedo.\u00a0 O el uso de equipamientos de \u00e1mbito supramunicipal. El problema es que Asturias no lo hace bien.\u00a0 En nuestros desplazamientos, utilizamos el coche m\u00e1s que cualquiera de las metr\u00f3polis espa\u00f1olas. Y apenas disponemos de equipamientos de referencia metropolitana, especialmente p\u00fablicos. Tendemos a duplicarlos e incluso a multiplicarlos. Palacios de Congresos, Feriales, Centros Culturales\u2026 El resultado es un espacio metropolitano ineficiente y ca\u00f3tico. El centro de Asturias parece un inmenso contenedor donde las distintas administraciones han ido autorizando la multiplicaci\u00f3n de autopistas (tres entre Oviedo y Gij\u00f3n para asombro de extra\u00f1os) de superficies comerciales, de suelos industriales, de urbanizaciones residenciales, de equipamientos singulares, de industrias salubres e insalubres. Incluso de puertos y superpuertos. Pero sin orden l\u00f3gico alguno, superponi\u00e9ndose unos a otros, mezcl\u00e1ndose incluso. \u00a0\u00a0Y sin disfrutar de equipamiento alguno que\u00a0 identifique a nuestro \u00e1rea metropolitana y, lo que es peor, con dificultades para competir con ellos \u00a0con \u00e1reas urbanas de tama\u00f1o similar pero que han cumplido exitosamente sus deberes.<\/p>\n<p style=\"text-align: left\">Por tanto, y como cuarto punto, \u00a0es necesario poner orden en el caos. O, al menos intentarlo. Para ello es capital disponer de instrumentos y entidades de planeamiento y gesti\u00f3n. Algunos llevamos lustros reivindic\u00e1ndolos, incluyendo la figura del consorcio, que tan buenas experiencias ha proporcionado en Asturias.\u00a0 Es necesario evitar\u00a0 disparates como el \u201cCalatrava\u201d de Oviedo, tan alejado adem\u00e1s del a\u00f1ejo ferial gijon\u00e9s y su minipalacio de congresos. O la proliferaci\u00f3n de campus universitarios en puntos alejados de las redes de transporte.\u00a0 O la eclosi\u00f3n de centros comerciales que a duras penas subsisten. O esa menguante red de cercan\u00edas. Desprop\u00f3sitos que nos llevan\u00a0 a pensar si no ser\u00e1 demasiado tarde para ordenar el \u00e1rea central. Quiz\u00e1 hace quince a\u00f1os o veinte a\u00f1os, antes de la burbuja inmobiliaria y de tantas otras burbujas, hubiera sido el momento. Algunos lo intentamos, como otros antes que nosotros.<\/p>\n<p style=\"text-align: left\">Ahora bien, apunta el refr\u00e1n que nunca es tarde si la dicha es buena. Y la propuesta (\u00a1por fin!) de un \u00f3rgano de gesti\u00f3n metropolitano debe ser bien recibida. En mi opini\u00f3n sus misiones deber\u00edan centrarse en dos planos. Uno, la coordinaci\u00f3n del planeamiento urban\u00edstico, ahorm\u00e1ndolo a estrategias territoriales (por cierto, ya se elabor\u00f3 un documento hace diez a\u00f1os, en alg\u00fan caj\u00f3n andar\u00e1) y velando por su cumplimiento, pero tambi\u00e9n coordinando el planeamiento entre concejos lim\u00edtrofes. Todos conocemos las dificultades para acceder a Parque Principado, en Siero, desde Oviedo, a trav\u00e9s de un pol\u00edgono industrial, o la desconexi\u00f3n entre Lugones y La Corredoria, comunicados s\u00f3lo a trav\u00e9s de la vieja N-630.\u00a0 Incluir\u00eda, por supuesto, la coordinaci\u00f3n con el CTA. Otro, la gesti\u00f3n consorciada de equipamientos estrat\u00e9gicos p\u00fablicos, evitando duplicidades y compartiendo riesgo y ventura. Quiz\u00e1 nos habr\u00edamos evitado fiascos como el ya citado del \u201cCalatrava\u201d y dispondr\u00edamos ahora de equipamientos capaces de competir con, sin ir m\u00e1s lejos, los de un Bilbao que, por poblaci\u00f3n, anda a la par del \u00e1rea central.<\/p>\n<p style=\"text-align: left\">Pero todo ello implica un cambio de visi\u00f3n: las ciudades asturianas deben olvidarse de competir entre s\u00ed \u2013haciendo todas lo mismo- y convencerse de la necesidad de cooperar para aprovechar oportunidades que nos permitan competir en un mundo global, donde las ciudades son la referencia a la hora de invertir. Y, por desgracia, Oporto, Bilbao, Burdeos, Cardiff o Cork, por limitarnos al Arco Atl\u00e1ntico consiguen visualizarse a nivel europeo o incluso mundial. Nuestro \u00e1rea central, no.<\/p>\n<p style=\"text-align: left\">Es objetivo que \u00a0requiere de ambici\u00f3n y liderazgo pol\u00edtico. Que no consiste en presentar el documento en un acto quiz\u00e1 con excesivo protagonismo gubernamental, sino en sumar previamente a la ciudadan\u00eda, a los grupos pol\u00edticos, a la sociedad civil y, sobre todo, a los ayuntamientos, convenciendo de la bondad de coordinarse, concedi\u00e9ndoles, incluso, la paternidad de la idea (\u00bfQui\u00e9n est\u00e1 pensando en Bilbao?). Respetando sus competencias e integr\u00e1ndolas en estructuras de gobierno multinivel. Optimizando recursos p\u00fablicos escasos soslayando el riesgo de un macroorganismo. Implica ideas claras sobre\u00a0 qu\u00e9 hacer, asumiendo que fen\u00f3menos como la suburbanizaci\u00f3n son universales, desde Yakarta a Varsovia, pasando por Estocolmo o Coru\u00f1a. Evitando efectos como el \u201csprawl\u201d, armonizando redes de transporte, suelos residenciales e industriales y equipamientos. Y \u00a0aportando ambici\u00f3n para ir m\u00e1s all\u00e1 de algo que sirva para captar financiaci\u00f3n europea.\u00a0 Requiere, sobre todo, un proyecto que vislumbre la Asturias del 2050 en unas directrices regionales que actualicen las actuales \u00a1de 1991! recogiendo\u00a0 el \u00e1rea central y sus equipamientos estrat\u00e9gicos, pero tambi\u00e9n alternativas para nuestro moribundo medio rural y su relaci\u00f3n con lo urbano, identificando las potencialidades de las micr\u00f3polis y comarcas astures.<\/p>\n<p style=\"text-align: left\">Esperemos, por tanto, que este en\u00e9simo intento metropolitano tome el rumbo correcto y sea el definitivo.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La presentaci\u00f3n de estrategias para el \u00e1rea metropolitana de Asturias, elaboradas por t\u00e9cnicos del Principado y de la Universidad, \u00a0ha sido recibida por ciudadan\u00eda, sociedad civil, clase pol\u00edtica y ayuntamientos implicados, con m\u00e1s escepticismo que ilusi\u00f3n, quiz\u00e1 porque conceptos tan abstractos\u00a0 no se comprendan f\u00e1cilmente. Lo primero que cabe plantearse es \u00bfqu\u00e9 es un \u00e1rea [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/posts\/672"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/comments?post=672"}],"version-history":[{"count":0,"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/posts\/672\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/media?parent=672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/categories?post=672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/que-nos-pasa\/wp-json\/wp\/v2\/tags?post=672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}