{"id":17542,"date":"2021-10-01T09:41:20","date_gmt":"2021-10-01T07:41:20","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17542"},"modified":"2021-10-01T09:41:20","modified_gmt":"2021-10-01T07:41:20","slug":"el-volcan-intensifica-su-poder-nueva-boca-de-lava-avanza-hacia-la-palma-azufre-por-encima-de-150","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/01\/el-volcan-intensifica-su-poder-nueva-boca-de-lava-avanza-hacia-la-palma-azufre-por-encima-de-150\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1EL VOLCAN INTENSIFICA SU PODER.- NUEVA BOCA DE LAVA AVANZA HACIA LA PALMA.- AZUFRE POR ENCIMA DE 150 !!!"},"content":{"rendered":"<p><strong>Hoy ,desde las 6 de la ma\u00f1ana, se informa que el volc\u00e1n de Cumbre Vieja(mientras no se le cambie el nombre) ha intensificado su actividad en forma tal que ha abierto una nueva boca hacia el norte, hacia la Palma obligandose a confinarse a los vecinos, que pudieran ser desalojados ene el curso del d\u00eda.<\/strong><\/p>\n<p><b>Adem\u00e1s la calidad del aire ha empeorado hasta llegar a los 130, cuando se ha informad que 120 era el l\u00edmite\u00a0para no perjudicar la salud.<\/b><\/p>\n<p><strong>Los volcanes, como los huracanes, no tienen palabra. Act\u00faan por si s\u00f3lo en el marco de su entorno y de los vientos.<\/strong><\/p>\n<p><strong>Hoy el nivel de alarma de ayer ha crecido.<\/strong><\/p>\n<p><b>Se espera una orientaci\u00f3n de las autoridades sobre el nivel de azufre, pero una nueva boca del volc\u00e1n\u00a0puede llegar a nuevas zonas pobladas, como la Palma.<\/b><\/p>\n<p><strong>Por primera vez se mueve hacia el norte la nueva lava.<\/strong><\/p>\n<p><strong>Psicologicamente, la decisi\u00f3n del Consejo de Ministros, de enviar 10 millones de euros, no s\u00f3lo es insuficiente, sino que tiene a la poblaci\u00f3n con el miedo de que, una vez m\u00e1s, una cosa sean las palabras y otras las hechos de los gobiernos.<\/strong><\/p>\n<p><strong>Esperemos que la estancia all\u00ed de Felix Bola\u00f1os, haga que el martes pr\u00f3ximo se tomen m\u00e1s medidas.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy ,desde las 6 de la ma\u00f1ana, se informa que el volc\u00e1n de Cumbre Vieja(mientras no se le cambie el nombre) ha intensificado su actividad en forma tal que ha abierto una nueva boca hacia el norte, hacia la Palma obligandose a confinarse a los vecinos, que pudieran ser desalojados ene el curso del d\u00eda. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17542"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17542"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17542\/revisions"}],"predecessor-version":[{"id":17544,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17542\/revisions\/17544"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}