{"id":17557,"date":"2021-10-02T09:25:25","date_gmt":"2021-10-02T07:25:25","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17557"},"modified":"2021-10-02T09:25:25","modified_gmt":"2021-10-02T07:25:25","slug":"el-volcan-sigue-rugiendo-con-dos-bocas-nuevas-mientras-preocupan-los-sismos-del-sur","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/02\/el-volcan-sigue-rugiendo-con-dos-bocas-nuevas-mientras-preocupan-los-sismos-del-sur\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1EL VOLCAN SIGUE RUGIENDO CON DOS BOCAS NUEVAS, MIENTRAS PREOCUPAN LOS SISMOS DEL SUR !!!"},"content":{"rendered":"<p><strong>Ayer, la magma expulsada hacia el mar, duplicaba ya, en 15 d\u00edas, la que se form\u00f3 en los 24 d\u00edas de la antigua erupci\u00f3n hace 50 a\u00f1os, mientras que no se s\u00f3lo menguaba sino arreciaba su fuerza, abriendo dos\u00a0 bocas nuevas que avanzan sobre otros barrios poblados. Son ya 10 los confinamientos en la Isla.<\/strong><\/p>\n<p><b>Sin embargo, deber\u00edamos\u00a0estar atentos\u00a0a la comicidad\u00a0cada vez m\u00e1s intensa que se produce en el sur de la Palma, donde est\u00e1n los enjambres s\u00edsmicos, a 10 kms de profundidad.<\/b><\/p>\n<p><b>Recordamos los estudios del 2001 de aquellos cient\u00edficos brit\u00e1nicos que alertaban que si la isla se partiese, habr\u00eda olas de 25 metros que crear\u00edan un tsunami que azotar\u00eda\u00a0la costa este de los EE:UU.<\/b><\/p>\n<p><b>Hemos mentido que est\u00e1bamos\u00a0lejos de aquellos par\u00e1metros, pero el volcan tiene herida la zona de baja de Cumbre vieja, y que a la gran mancha de lava que avanza ya 500 metros dentro del mar se le incorporaron dos nuevas bocas que paralela a las primera coladas unidas, avanzan por el lado norte con m\u00e1s velocidad.<\/b><\/p>\n<p><strong>Todos estamos informados, pero llamo la atenci\u00f3n a la fuerte sismicidad que se esta\u00b4produciendo en el sur a centenares de metros, justamente donde est\u00e1 el enjambre volc\u00e1nico del que se ha alertado.<\/strong><\/p>\n<p><strong>La erupci\u00f3n de hace 50 a\u00f1os dur\u00f3 24 d\u00edas. Esta en tan s\u00f3lo 15 ha duplicado la fajana(es portugu\u00e9s el t\u00e9rmino, dec\u00eda alarmado un cient\u00edfico buscando el nombre en espa\u00f1ol, pero que has quedado por la difusi\u00f3n de los medios en fajana) de aquel temible de hace 50 a\u00f1os y sigue avanzando sin muestras de un termino pr\u00f3ximo.<\/strong><\/p>\n<p><strong>Mientras Pedro S\u00e1nchez visitar\u00e1 este fin de semana a la zona, la percepci\u00f3n inicial es de que los 10 millones de euros enviados, son muy insuficientes.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ayer, la magma expulsada hacia el mar, duplicaba ya, en 15 d\u00edas, la que se form\u00f3 en los 24 d\u00edas de la antigua erupci\u00f3n hace 50 a\u00f1os, mientras que no se s\u00f3lo menguaba sino arreciaba su fuerza, abriendo dos\u00a0 bocas nuevas que avanzan sobre otros barrios poblados. Son ya 10 los confinamientos en la Isla. [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17557"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17557"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17557\/revisions"}],"predecessor-version":[{"id":17558,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17557\/revisions\/17558"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}