{"id":17559,"date":"2021-10-02T09:33:27","date_gmt":"2021-10-02T07:33:27","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17559"},"modified":"2021-10-02T09:33:27","modified_gmt":"2021-10-02T07:33:27","slug":"que-poco-se-conoce-a-madrid-en-estados-unidos-mientras-surgia-a-la-luz-la-mediocridad-de-la-famosa-gira-por-nueva-york","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/02\/que-poco-se-conoce-a-madrid-en-estados-unidos-mientras-surgia-a-la-luz-la-mediocridad-de-la-famosa-gira-por-nueva-york\/","title":{"rendered":"\u00a1\u00a1&#8221; QUE POCO SE CONOCE A MADRID EN ESTADOS UNIDOS&#8221; MIENTRAS SURG\u00cdA A LA LUZ LA MEDIOCRIDAD DE LA FAMOSA GIRA POR NUEVA YORK ?"},"content":{"rendered":"<p><b>Y, por fin, la tan anunciada gira de Isabel D\u00edaz Ayuso a Nueva York, que parec\u00eda la de un jefe de Estado, termin\u00f3 y hoy estar\u00e1\u00b4, m\u00e1s humilde en Valencia con Casado.<\/b><\/p>\n<p><strong>Ante una indiferencia general, sin llegar a ninguno de los grandes medios de los EE:UU., D\u00edaz Ayuso se logr\u00f3 reunirse con miembros de la C\u00e1mara Baja(diputados) donde de 250 asistieron 8.<\/strong><\/p>\n<p><b>Fue all\u00ed, donde marc\u00f3 para la historia la frase: &#8221; Los ind\u00edgenas\u00a0eran el comunismo y Espa\u00f1a, les dio Libertad, Paz y Prosperidad&#8221;, que repetir\u00eda anteayer Jos\u00e9 Mar\u00eda Aznar..<\/b><\/p>\n<p><strong>Casado habr\u00e1 respirado.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Y, por fin, la tan anunciada gira de Isabel D\u00edaz Ayuso a Nueva York, que parec\u00eda la de un jefe de Estado, termin\u00f3 y hoy estar\u00e1\u00b4, m\u00e1s humilde en Valencia con Casado. Ante una indiferencia general, sin llegar a ninguno de los grandes medios de los EE:UU., D\u00edaz Ayuso se logr\u00f3 reunirse con miembros de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17559"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17559"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17559\/revisions"}],"predecessor-version":[{"id":17560,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17559\/revisions\/17560"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}