{"id":17598,"date":"2021-10-04T19:06:59","date_gmt":"2021-10-04T17:06:59","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17598"},"modified":"2021-10-04T19:06:59","modified_gmt":"2021-10-04T17:06:59","slug":"invitado-de-honor-de-casado-felipe-calderon-ex-presidente-de-emexico-ligado-al-narco-y-con-100000-fallecidos-a-sus-espaldas","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/04\/invitado-de-honor-de-casado-felipe-calderon-ex-presidente-de-emexico-ligado-al-narco-y-con-100000-fallecidos-a-sus-espaldas\/","title":{"rendered":"\u00a1\u00a1\u00a1INVITADO DE HONOR DE CASADO, FELIPE CALDERON EX PRESIDENTE DE EMEXICO LIGADO AL NARCO Y CON 100,000 FALLECIDOS A SUS ESPALDAS !!"},"content":{"rendered":"<p><strong>Compartimos la misma legislatura la LIV de la C\u00e1mara de Diputados en M\u00e9xico y tambi\u00e9n a los dos nos toc\u00f3 presidir la\u00a0<\/strong><b>C\u00e1mara.Se, como todo M\u00e9xico, su historia. La forma como apoy\u00f3 a &#8220;su cartel&#8221;, la respuesta del Chapo tir\u00e1ndole el avi\u00f3n donde iba su segundo nacido en Madrid en Paseo de la Reforma y Periferico, y como al final de su fracasado mandato, lo encontraron, en su \u00faltimo d\u00eda, totalmente borracho, con el tequila, su preferido.<\/b><\/p>\n<p><strong>En M\u00e9xico, todos lo saben.Dej\u00f3 tras de si, aunque usted no lo crea, 100,000 fallecidos por la lucha entre narcos.Su nombre Felipe Calderon Hinojosa.<\/strong><\/p>\n<p><strong>De pronto, observamos la filmaci\u00f3n. Apresurado Casado, recib\u00eda con alegr\u00eda tras de su viaje a Estados Unidos a Isabel D\u00edaz Ayuso, tomando del brazo al que parec\u00eda el principal invitado de la Convenci\u00f3n. Era \u00e9l.<\/strong><\/p>\n<p><strong>De esa forma, supimos de como, por fin sonriente, aparec\u00eda de nuevo ante las c\u00e1maras, Don Felipe Calder\u00f3n Hinojosa<\/strong><\/p>\n<p><strong>Se ha hablado del error de hablar con Sarkosy en el Convenci\u00f3n, pero, \u00bf sab\u00eda usted quien era casi su invitado de honor?<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Compartimos la misma legislatura la LIV de la C\u00e1mara de Diputados en M\u00e9xico y tambi\u00e9n a los dos nos toc\u00f3 presidir la\u00a0C\u00e1mara.Se, como todo M\u00e9xico, su historia. La forma como apoy\u00f3 a &#8220;su cartel&#8221;, la respuesta del Chapo tir\u00e1ndole el avi\u00f3n donde iba su segundo nacido en Madrid en Paseo de la Reforma y Periferico, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17598"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17598"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17598\/revisions"}],"predecessor-version":[{"id":17600,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17598\/revisions\/17600"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}