{"id":17655,"date":"2021-10-07T12:56:45","date_gmt":"2021-10-07T10:56:45","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17655"},"modified":"2021-10-07T12:56:45","modified_gmt":"2021-10-07T10:56:45","slug":"corrijo-la-hija-de-regis-debray-no-es-amante-de-juan-carlos-i","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/07\/corrijo-la-hija-de-regis-debray-no-es-amante-de-juan-carlos-i\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1CORRIJO: LA HIJA DE REGIS DEBRAY  NO ES AMANTE DE JUAN CARLOS I !!!"},"content":{"rendered":"<p><b>Ayer en la vor\u00e1gine\u00a0de la informaci\u00f3n sobre el nuevo libro del Rey, hecho por una francesa de 49 a\u00f1os, yo mismo, escrib\u00ed que ser\u00eda, por la trayectoria de \u00e9l, su nueva amante para estos a\u00f1os finales.<\/b><\/p>\n<p><strong>Pero cuando tuve mayor informaci\u00f3n de quien era, quien hab\u00eda sido su padre y sus desmentidos de ella y su marido con 4 hijos, cambie de opini\u00f3n.<\/strong><\/p>\n<p><b>Hoy corrijo en este blog que la hija de Regis Debray, el destacado\u00a0 escritor franc\u00e9s\u00a0tan amigo y cercano al Che Guevara, no pod\u00eda haber dado este giro.Ya quisiera Juan Carlos I, una mujer como ella, bella, de 49 a\u00f1os, para sus deteriorados(12 kilos menos) 83 a\u00f1os<\/b><\/p>\n<p><b>Al verla a ella y a su marido, delgado en su moto, la familia que han formado, me llevan al inter\u00e9s period\u00edstico\u00a0, y a su primer contacto hace 15 a\u00f1os en Madrid, de donde surgi\u00f3 la solicitud al rey de hacerle esta entrevista.<\/b><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ayer en la vor\u00e1gine\u00a0de la informaci\u00f3n sobre el nuevo libro del Rey, hecho por una francesa de 49 a\u00f1os, yo mismo, escrib\u00ed que ser\u00eda, por la trayectoria de \u00e9l, su nueva amante para estos a\u00f1os finales. Pero cuando tuve mayor informaci\u00f3n de quien era, quien hab\u00eda sido su padre y sus desmentidos de ella y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17655"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17655"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17655\/revisions"}],"predecessor-version":[{"id":17656,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17655\/revisions\/17656"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}