{"id":17667,"date":"2021-10-08T12:10:34","date_gmt":"2021-10-08T10:10:34","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17667"},"modified":"2021-10-08T12:10:34","modified_gmt":"2021-10-08T10:10:34","slug":"era-azacarraga-milmo-no-vidaurreta-la-historia-del-primo-y-del-narco-mo","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/08\/era-azacarraga-milmo-no-vidaurreta-la-historia-del-primo-y-del-narco-mo\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1ERA AZACARRAGA MILMO, NO VIDAURRETA-LA HISTORIA DEL PRIMO Y DEL NARCO !!!MO !!!"},"content":{"rendered":"<p><strong>Rectifico. El emigrante vasco que fund\u00f3 la Radio y la Televisi\u00f3n en M\u00e9xico, fue Emilio Azcarraga Vidaurreta.<\/strong><\/p>\n<p><b>El tuvo dos hijos: Emilio Azcarraga Milmo, amo y se\u00f1or de la televisi\u00f3n latinoamericana y una que ser\u00eda la madre del Guero Burillo, que buscar\u00eda otros caminos ligados al f\u00fatbol\u00a0y algo m\u00e1s.<\/b><\/p>\n<p><b>El Atlante, el equipo del pueblo mexicano, &#8220;los prietitos&#8221;, un d\u00eda, sin decir &#8220;agua va &#8221; hace 20 a\u00f1os, se trasladaba a Cancun, para tristeza de mi hermano Jorge hincha,el y sus hijos, y para ventaja para mi que elevaba el nivel del f\u00fatbol\u00a0donde yo residia. En aquel Atlante del D:F. vi jugar, hace 20 a\u00f1os al Kun Aguero.<\/b><\/p>\n<p><strong>Un d\u00eda domingo, un amigo gallego, me invit\u00f3 a ver un partido de la Liga Espa\u00f1ola y me llev\u00f3 a un lugar que no olvidar\u00e9. En una manzana entera llena de negocios, hab\u00eda un restaurante para 1,000 comensales dentro y\u00a0 en el jard\u00edn.<\/strong><\/p>\n<p><b>Entramos y nos encontramos con que eramos los UNICOS\u00a0 \u00a0 comensales.Las superpantallas, que parec\u00edan de cine, eran para ver el box y el f\u00fatbol\u00a0espa\u00f1ol.<\/b><\/p>\n<p><b>Mi amigo gallego y yo nos sentamos asombrados. No s\u00f3lo ten\u00edamos\u00a0100 meseros a nuestras ordenes sino que, cuando quer\u00edamos, nos cambiaban de\u00a0 partido del Madrid o del Barcelona, al gusto.<\/b><\/p>\n<p><b>En el piso superior, como en palcos, estaban varios dedicados a deportistas, pero hab\u00eda uno, el m\u00e1s importante: &#8221; PARA EL JEFE&#8221;. Era el &#8220;g\u00fcero&#8221;\u00a0Burillo, con tremenda foto del primo de Emilio Azcarraga Milmo<\/b><\/p>\n<p><strong>Aquella manzana entera y aquel restaurante, era el precio que el corrupto gobernador de Quintana Roo donde est\u00e1\u00a0 Canc\u00fan , le hab\u00eda dado\u00a0 a cambio de que llevase su equipo para all\u00e1<\/strong><\/p>\n<p><strong>A CAMBIO DE BLANQUEAR DINERO DEL NARCOTRAFICO.<\/strong><\/p>\n<p><b>El presidente del Atlante, empleado de dos paraguayos, los segundos del Guero, ven\u00eda\u00a0una vez al a\u00f1o a Asturias, en el cumplea\u00f1os de su padre creo que a Boal. Invitado por un amigo, familiar de ellos, me encontr\u00e9\u00a0la casa donde se hacia el festejo, con unas 100 personas.<\/b><\/p>\n<p><strong>En la parte de atr\u00e1s, alguien pregunta por aquel Jose Antonio, el presidente de facto del Atl\u00e1nte, y su hijo le dice, delante de mi: &#8220;Est\u00e1 adelante con los narcos(los 2 paraguayos, empleados de Burillo)&#8221;<\/strong><\/p>\n<p><strong>Ese era el M\u00e9xico que todos tienen en la memoria. Una minor\u00eda de ricos, el narco en apogeo, y unos cuantos, due\u00f1os de las concesiones que les daban los gobierno en turno, para garantizar\u00a0 su poder.<\/strong><\/p>\n<p><strong>Ese es el M\u00e9xico por lo que existe la Cuarta Transformaci\u00f3n. Nunca m\u00e1s.<\/strong><\/p>\n<p><strong>Don Jos\u00e9 Mar\u00eda Aznar, no pudo. Lo logr\u00f3 en 2006, pero lleva 3 a\u00f1os su gran enemigo Andr\u00e9s Manuel L\u00f3pez Obrador,\u00a0 como presidente de M\u00e9xico.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Rectifico. El emigrante vasco que fund\u00f3 la Radio y la Televisi\u00f3n en M\u00e9xico, fue Emilio Azcarraga Vidaurreta. El tuvo dos hijos: Emilio Azcarraga Milmo, amo y se\u00f1or de la televisi\u00f3n latinoamericana y una que ser\u00eda la madre del Guero Burillo, que buscar\u00eda otros caminos ligados al f\u00fatbol\u00a0y algo m\u00e1s. El Atlante, el equipo del pueblo [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17667"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17667"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17667\/revisions"}],"predecessor-version":[{"id":17670,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17667\/revisions\/17670"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}