{"id":17683,"date":"2021-10-09T10:16:59","date_gmt":"2021-10-09T08:16:59","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17683"},"modified":"2021-10-09T10:16:59","modified_gmt":"2021-10-09T08:16:59","slug":"somos-un-pais-de-126-millones-de-habitantes-15000-haitianos-no-son-problema-da-asilo-a-15000-y-no-regresa-a-nadie-a-su-pais","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/09\/somos-un-pais-de-126-millones-de-habitantes-15000-haitianos-no-son-problema-da-asilo-a-15000-y-no-regresa-a-nadie-a-su-pais\/","title":{"rendered":"\u00a1\u00a1\u00a1&#8221;SOMOS UN PAIS DE 126 MILLONES DE HABITANTES. 15,000 HAITIANOS NO SON PROBLEMA. DA ASILO A 15,000 Y NO REGRESA A NADIE A SU PA\u00cdS&#8221;!!"},"content":{"rendered":"<p><strong>Ayer, tras los acuerdos en la reuni\u00f3n del Entendimiento Centenario, tras las duras palabras de Antonhy Blinken secretario de Estado, de que no recibir\u00e1 a nadie en los EE:UU, que no sea legal, el Canciller Marcelo Ebrard, dej\u00f3 clara la posici\u00f3n del gobierno mexicano que acaba de dar asilo a 15,000 de loa haitianos que con los caballos expuls\u00f3 el puente los Estados Unidos.<\/strong><\/p>\n<p><b>&#8221; En M\u00e9xico somos 126 millones de habitantes y podemos absorber a los 15,000 haitianos. A\u00a0nadie se le ha enviado a su pa\u00eds&#8221;.<\/b><\/p>\n<p><strong>M\u00e9xico ha mantenido el reto de los 3,250 kms de frontera con la mayor potencia de la historia, y la base ha sido actuar con principios y sin temor.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ayer, tras los acuerdos en la reuni\u00f3n del Entendimiento Centenario, tras las duras palabras de Antonhy Blinken secretario de Estado, de que no recibir\u00e1 a nadie en los EE:UU, que no sea legal, el Canciller Marcelo Ebrard, dej\u00f3 clara la posici\u00f3n del gobierno mexicano que acaba de dar asilo a 15,000 de loa haitianos que [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17683"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17683"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17683\/revisions"}],"predecessor-version":[{"id":17684,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17683\/revisions\/17684"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}