{"id":17865,"date":"2021-10-22T11:36:59","date_gmt":"2021-10-22T09:36:59","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17865"},"modified":"2021-10-22T11:36:59","modified_gmt":"2021-10-22T09:36:59","slug":"10-millones-de-fallecidos-en-el-mundo-sino-se-distribuyen-bien-las-vacunas-oms","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/22\/10-millones-de-fallecidos-en-el-mundo-sino-se-distribuyen-bien-las-vacunas-oms\/","title":{"rendered":"\u00a1\u00a1\u00a1&#8221;10 MILLONES DE FALLECIDOS EN EL MUNDO SINO SE DISTRIBUYEN BIEN LAS VACUNAS &#8221; OMS!!!"},"content":{"rendered":"<p><b>Ya el mundo rico el de la OCDE(los 40, que tienen la riqueza igual a la de 150 pa\u00edses), est\u00e1 dando hasta la tercera dosis, y, como en Estados Unidos hay casi 80 millones que no desean vacunarse y el pa\u00eds almacena 600 millones de vacunas que pueden caducar, mientras\u00a0 en Africa s\u00f3lo se ha vacunado al 10 % del continente.\u00a0<\/b><\/p>\n<p><strong>Esta miope visi\u00f3n de los 40, no perciben que si el Reino Unido est\u00e1 hoy en 50,000 contagios diarios , es debido a las nuevas variantes en aquellos dos tercios de la humanidad, casi 4,000 millones.<\/strong><\/p>\n<p><strong>En el pecado llevaremos la penitencia.<\/strong><\/p>\n<p><strong>La Organizaci\u00f3n Mundial acaba de informar que si no se distribuyen en todo el mundo las vacunas, la pandemia nos dejara 10 millones de muertos.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ya el mundo rico el de la OCDE(los 40, que tienen la riqueza igual a la de 150 pa\u00edses), est\u00e1 dando hasta la tercera dosis, y, como en Estados Unidos hay casi 80 millones que no desean vacunarse y el pa\u00eds almacena 600 millones de vacunas que pueden caducar, mientras\u00a0 en Africa s\u00f3lo se ha [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17865"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17865"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17865\/revisions"}],"predecessor-version":[{"id":17866,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17865\/revisions\/17866"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}