{"id":17972,"date":"2021-10-28T16:54:29","date_gmt":"2021-10-28T14:54:29","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=17972"},"modified":"2021-10-28T16:54:29","modified_gmt":"2021-10-28T14:54:29","slug":"la-audiencia-nacional-condena-a-barcenas-y-al-partido-popular-por-el-dinero-negro-de-la-obra-de-genova","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2021\/10\/28\/la-audiencia-nacional-condena-a-barcenas-y-al-partido-popular-por-el-dinero-negro-de-la-obra-de-genova\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1LA AUDIENCIA NACIONAL CONDENA A BARCENAS Y AL PARTIDO POPULAR POR EL DINERO NEGRO DE LA OBRA DE G\u00c9NOVA!!"},"content":{"rendered":"<p><strong>Hoy en la ma\u00f1ana la Audiencia Nacional ha condenado a Luis B\u00e1rcenas por dos a\u00f1os y al Partido Popular por haber realizado en negro la obra de G\u00e9nova, sede del Partido Popular.<\/strong><\/p>\n<p><strong>Para B\u00e1rcenas es una de tantas piezas de su proceso.<\/strong><\/p>\n<p><strong>Para el Partido Popular, el m\u00e1s corrupto en la historia de Espa\u00f1a, se le condena por responsabilidad civil subsidiaria.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy en la ma\u00f1ana la Audiencia Nacional ha condenado a Luis B\u00e1rcenas por dos a\u00f1os y al Partido Popular por haber realizado en negro la obra de G\u00e9nova, sede del Partido Popular. Para B\u00e1rcenas es una de tantas piezas de su proceso. Para el Partido Popular, el m\u00e1s corrupto en la historia de Espa\u00f1a, se [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17972"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=17972"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17972\/revisions"}],"predecessor-version":[{"id":17973,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/17972\/revisions\/17973"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=17972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=17972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=17972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}