{"id":27126,"date":"2022-12-14T12:17:28","date_gmt":"2022-12-14T11:17:28","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=27126"},"modified":"2022-12-14T12:17:28","modified_gmt":"2022-12-14T11:17:28","slug":"un-maracanazo-el-domingo","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2022\/12\/14\/un-maracanazo-el-domingo\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1 \u00bf UN MARACANAZO EL DOMINGO ?!!!"},"content":{"rendered":"<p><b>Ante la anomia de los 8,000 seres\u00a0humanos y el miedo de todas las\u00a0\u00e9pocas a lo incierto, ha hecho que\u00a0la mayor\u00eda de los hombres y\u00a0mujeres tengan la\u00a0\u00a0necesidad de trasladar algo de nuestra vida diaria, la mayor\u00eda\u00a0dura y dif\u00edcil\u00a0a trasladar una parte de los afectos, que nos permita, aunque sea por\u00a0horas ser victoriosos, a riesgo de la depresi\u00f3n que puede surgir. Ese primer caso lo vemos reflejado en los\u00a0 deportes y en la b\u00fasqueda\u00a0de aparecer en la\u00a0televisi\u00f3n en aquellas transmisiones\u00a0grandes, lejanas, o ya sea en la misma calle de la ciudad.Quien no sale en la televisi\u00f3n, pareciese\u00a0 decirse, no es nadie en la vida.<\/b><\/p>\n<p><b>En el Mundial de F\u00fatbol, con transmisiones\u00a0millonarias, aflora esa necesidad de, como parte de un grupo, de una naci\u00f3n, seamos por\u00a0momentos superiores a los dem\u00e1s, dejando atr\u00e1s nuestra realidad.<\/b><\/p>\n<p><b>Uruguay es un peque\u00f1o pa\u00eds sudamericano de 5 millones de habitantes, que vive de ser para\u00edso\u00a0fiscal, pero tambi\u00e9n de el recuerdo de\u00a0aquel 1950.<\/b><\/p>\n<p><b>Se inauguraba el tremendo estadio de Maracan\u00e1\u00a0en Brasil, con capacidad para 125,000 espectadores, cuando aquella\u00a0naci\u00f3n anfitriona, tan segura\u00a0estaba de ganar el mundial, que la final Brasil-Uruguay, estaba\u00a0tan segura\u00a0que los diarios ten\u00edan ya los titulares, para\u00a0anunciarlo, faltando s\u00f3lo el marcador final.<\/b><\/p>\n<p><b>Y, por sorpresa\u00a0Uruguay\u00a0los derrot\u00f3, en lo que se conoce como el Maracanazo.<\/b><\/p>\n<p><strong>Durante 70 a\u00f1os, los uruguayos han vivido, en su ilusi\u00f3n, no de ser un gran pa\u00eds, sino del RECUERDO DE AQUELLA PROEZA.<\/strong><\/p>\n<p><b>Y ,hasta hoy. Por ello las imagenes de, al perder en la primera ronda, Cavani, rompiese el televisor del VAR, y sus jugadores persiguieron\u00a0y golpearon\u00a0a los organizadores y a quienes encontraron\u00a0en el camino, mientras Luis Suarez, lloraba desconsolado.La realidad los dejo en su lugar.<\/b><\/p>\n<p><b>Pero Argentina, hundida econ\u00f3micamente, con una deuda para 20 a\u00f1os, sin resolver el problema del &#8220;peronismo&#8221;, s\u00f3lo tiene un camino para salir del bache, aunque sea por unos d\u00edas ganar el Mundial<\/b><\/p>\n<p><b>La locura de los argentinos, de sus cronistas ayer tras el triunfo sobre Croacia, fue de tal desborde que mostraron los cronistas y los hinchas que recorri\u00f3\u00a0todo el mundo, en una mezcla que lleg\u00f3 hasta el rid\u00edculo.<\/b><\/p>\n<p><b>Es lo \u00fanico que tienen, tras\u00a0haber sido hace 100 a\u00f1os la octava potencia mundial.<\/b><\/p>\n<p><b>Pero, igual que se apoyaron en Maradona, ahora es con Messi y la locura est\u00e1 desatada.<\/b><\/p>\n<p><b>Pero si el domingo no derrotan a Francia, que creemos\u00a0ser\u00e1 el otro finalista, lo que suceder\u00e1\u00a0en el pa\u00eds quiz\u00e1s haga que el Maracanazo sea cosa de ni\u00f1os..<\/b><\/p>\n<p><strong>Lo alertamos con tristeza, quienes hemos seguido la trayectoria de uno de los m\u00e1s grandes futbolistas como ha sido Messi que necesita ese final feliz, pero&#8230;..<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Ante la anomia de los 8,000 seres\u00a0humanos y el miedo de todas las\u00a0\u00e9pocas a lo incierto, ha hecho que\u00a0la mayor\u00eda de los hombres y\u00a0mujeres tengan la\u00a0\u00a0necesidad de trasladar algo de nuestra vida diaria, la mayor\u00eda\u00a0dura y dif\u00edcil\u00a0a trasladar una parte de los afectos, que nos permita, aunque sea por\u00a0horas ser victoriosos, a riesgo de la [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27126","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/27126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=27126"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/27126\/revisions"}],"predecessor-version":[{"id":27128,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/27126\/revisions\/27128"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=27126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=27126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=27126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}