{"id":29251,"date":"2023-03-26T17:49:45","date_gmt":"2023-03-26T15:49:45","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=29251"},"modified":"2023-03-26T17:49:45","modified_gmt":"2023-03-26T15:49:45","slug":"acuerdos-rusos-chinos-unidad-ante-la-otan-y-unidad-en-lo-economico","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2023\/03\/26\/acuerdos-rusos-chinos-unidad-ante-la-otan-y-unidad-en-lo-economico\/","title":{"rendered":"\u00a1\u00a1\u00a1 ACUERDOS RUSOS-CHINOS.-&#8221; UNIDAD ANTE LA OTAN Y UNIDAD EN LO ECON\u00d3MICO !!!"},"content":{"rendered":"<p><b>Le dec\u00eda Xi a Vladimir al despedirse: &#8220;Se est\u00e1n produciendo cambios que no hab\u00edamos\u00a0tenido en 100 a\u00f1os, y\u00a0 debemos estar juntos\u00a0pilotando esos cambios &#8220;. Tras cuatro horas y media totalmente solos y dos d\u00edas de sus equipos y ellos preparando la relaci\u00f3n entre ambos han consolidado, no s\u00f3lo estar juntos frente a la OTAN, sino juntos en LO ECON\u00d3MICO, ambos dejaron por escrito.<\/b><\/p>\n<p><b>Xi:&#8221; LOS LAZOS ENTRE MOSC\u00da\u00a0Y PEK\u00cdN\u00a0SON VITALES PARA EL DEVENIR DE LA HUMANIDAD&#8221;<\/b><\/p>\n<p><b> y Vladimir&#8221; LAS RELACIONES RUSIA Y CHINA EST\u00c1N\u00a0EN EL MEJOR MOMENTO\u00a0DE SU HISTORIA &#8220;.<\/b><\/p>\n<p><b>Se ha materializado el Proyecto Siberia 2, gasoducto de 2,600 kms. que\u00a0 unir\u00e1, a trav\u00e9s de Mongolia a ambos paises y donde los 50,000 millones de metros c\u00fabicos\u00a0de gas, que ir\u00edan a Europa a trav\u00e9s del Nord Stream 2, ahora van para China.<\/b><\/p>\n<p><b>Los intercambios comerciales alcanzaron un nivel r\u00e9cord\u00a0de 200,000 millones de d\u00f3lares.<\/b><\/p>\n<p><b>Rusia aceptar\u00e1 yuanes por todo lo que venga de China, pero tambi\u00e9n de lo que\u00a0venga de Asia, Africa y Am\u00e9rica Latina, buscando\u00a0la desdolarizaci\u00f3n del d\u00f3lar\u00a0en la econom\u00eda\u00a0mundial.<\/b><\/p>\n<p><b>Van a redoblar las v\u00edas f\u00e9rreas\u00a0entre ambos paises y Rusia entregar\u00e1 los contratos de las 120 empresas de occidente que se fueron\u00a0a las trasnacionales chinas.<\/b><\/p>\n<p><b>La ex presidenta brasileira Dilma Rousseff\u00a0, acaba de ser elegida la responsable de finanzas de los BRICS( Brasil, Rusia, India, China y Sud\u00e1frica) que ya tienen un PIB mayor que el poderoso G7 Occidental.( EEUU. Canad\u00e1, Jap\u00f3n, Reino Unido, Francia, Alemania e\u00a0Italia )<\/b><\/p>\n<p><b>Lula no ha salido de Brasil hacia Pek\u00edn\u00a0, por su c\u00e1ncer\u00a0en la garganta<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Le dec\u00eda Xi a Vladimir al despedirse: &#8220;Se est\u00e1n produciendo cambios que no hab\u00edamos\u00a0tenido en 100 a\u00f1os, y\u00a0 debemos estar juntos\u00a0pilotando esos cambios &#8220;. Tras cuatro horas y media totalmente solos y dos d\u00edas de sus equipos y ellos preparando la relaci\u00f3n entre ambos han consolidado, no s\u00f3lo estar juntos frente a la OTAN, sino [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29251","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/29251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=29251"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/29251\/revisions"}],"predecessor-version":[{"id":29253,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/29251\/revisions\/29253"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=29251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=29251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=29251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}