{"id":38753,"date":"2024-09-29T11:29:29","date_gmt":"2024-09-29T09:29:29","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=38753"},"modified":"2024-09-29T11:29:29","modified_gmt":"2024-09-29T09:29:29","slug":"la-monarquia-espanola-debilitada-muy-lejana-a-la-sociedad-y-el-ritmo-de-ella","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/09\/29\/la-monarquia-espanola-debilitada-muy-lejana-a-la-sociedad-y-el-ritmo-de-ella\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1\u00a1LA MONARQU\u00cdA ESPA\u00d1OLA, DEBILITADA, MUY LEJANA A LA SOCIEDAD Y EL RITMO DE ELLA !!"},"content":{"rendered":"<p><b>Triunf\u00f3 Franco. En La Paz, mientras el Marqu\u00e9s de Villaverde, su m\u00e9dico, retrasaba su muerte un mes, Carmen Polo y \u00e9ste trataban de que fuera el primo Alfonso, esposo de Carmencita, los herederos para unir monarqu\u00eda con franquismo, Franco dijo que no.<\/b><\/p>\n<p><b>Ah\u00ed empez\u00f3 la Monarqu\u00eda\u00a0Constitucional que ha tenido la Jefatura de Estado desde 1978 hasta hoy. Ella ha tenido dos etapas visibles: la de Juan Carlos I y la de Felipe VI.<\/b><\/p>\n<p><strong>De 1978 a 2014, Juan Carlos I fu\u00e9 la cabeza de un sociedad donde los presidentes, los empresarios, los banqueros, las mujeres, los periodistas y todos los que lo sab\u00edan, callaron. Esa etapa, que est\u00e1 saliendo a la luz, nos muestra la descomposici\u00f3n del aparato del Estado, y el por que , aquella pantanosa etapa donde se edific\u00f3 la llamada Transici\u00f3n, no pudo cimentar la nueva Espa\u00f1a, confundida, enfrentada hoy.<\/strong><\/p>\n<p><b>Tras aquella etapa, entr\u00f3 Felipe VI, con Leticia que ha hecho todo lo posible por mantener\u00a0la instituci\u00f3n, y que llegue Leonor, antes que colapse la monarqu\u00eda.<\/b><\/p>\n<p><b>Pero, en ese inter, abiertos los medios, saliendo\u00a0toda la podredumbre de aquellos primeros a\u00f1os( Sabino dijo a Manglano\u00a0que el\u00a0rey, en aquella \u00e9poca ya ten\u00eda 1,500 millones en Suiza)y que vergonzosamente se enlaza su huida a Abu Dabi, y ahora la Fundaci\u00f3n para manejar su fortuna fuera del alcance del fisco espa\u00f1ol, confirma todo lo que se especulaba: Una fundaci\u00f3n en el extranjero, para dejar el futuro de hijas\u00a0y nietos, asegurado su futuro por generaciones.<\/b><\/p>\n<p><strong>Pero en esa ambici\u00f3n del Em\u00e9rito no s\u00f3lo ha hecho que salga la historia de \u00e9l, sino que un d\u00eda despu\u00e9s de que habla de Sus Memorias, alguien destapa aquellas fotos y de nuevo la monarqu\u00eda se debilita.<\/strong><\/p>\n<p><b>Lo que no sale no son las fotos en la cama del rey con la actriz, SINO LAS GRABACIONES DE LO DICHO EN LA INTIMIDAD por el rey locuaz, que le debe haber soltado &#8220;la sopa&#8221; de todo, incluido\u00a0el 23 F. y los GAL<\/b><\/p>\n<p><b>En 10 a\u00f1os Felipe VI, no ha podido recobrar el prestigio y la necesidad\u00a0de una instituci\u00f3n hereditaria.<\/b><\/p>\n<p><b>Y , entonces, vuelve\u00a0a plantearse, \u00bf para la Nueva Espa\u00f1a, la Monarqu\u00eda aporta algo,?<\/b><\/p>\n<p><b>Sofia, la madre del rey sabe de \u00e9sto. Cuando ella ten\u00eda la edad de Leonor, ni se imaginaba\u00a0 como iba a caer la monarqu\u00eda griega, y como terminar\u00eda en India su madre y lo que ella tendr\u00eda que soportar<\/b><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Triunf\u00f3 Franco. En La Paz, mientras el Marqu\u00e9s de Villaverde, su m\u00e9dico, retrasaba su muerte un mes, Carmen Polo y \u00e9ste trataban de que fuera el primo Alfonso, esposo de Carmencita, los herederos para unir monarqu\u00eda con franquismo, Franco dijo que no. Ah\u00ed empez\u00f3 la Monarqu\u00eda\u00a0Constitucional que ha tenido la Jefatura de Estado desde 1978 [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38753","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=38753"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38753\/revisions"}],"predecessor-version":[{"id":38755,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38753\/revisions\/38755"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=38753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=38753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=38753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}