{"id":38756,"date":"2024-09-29T13:33:11","date_gmt":"2024-09-29T11:33:11","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=38756"},"modified":"2024-09-29T13:33:11","modified_gmt":"2024-09-29T11:33:11","slug":"para-las-y-los-lectores-modesto-analisis-para-entender-que-pasa-entre-espana-y-mexico","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/09\/29\/para-las-y-los-lectores-modesto-analisis-para-entender-que-pasa-entre-espana-y-mexico\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1PARA LAS Y LOS LECTORES.- MODESTO AN\u00c1LISIS PARA ENTENDER QUE PASA ENTRE ESPA\u00d1A Y MEXICO !!!"},"content":{"rendered":"<p><b>Perm\u00edtanme\u00a0ubicar el origen. Como comentamos, Octavio Paz, premio\u00a0Nobel mexicano, en el Laberinto\u00a0de la Soledad, analiz\u00f3 el MESTIZAJE en la llamada\u00a0&#8221; conquista&#8221;. En Espa\u00f1a, en Europa, la RELACI\u00d3N\u00a0ES ENTRE IGUALES. En M\u00e9xico, la relaci\u00f3n\u00a0conquistador\u00a0ind\u00edgena, fue entre DESIGUALES. De ella, surgieron el Macho Mexicano(que viene del\u00a0macho espa\u00f1ol, y este del musulm\u00e1n ) y la Abnegada\u00a0mujercita mexicana.En ello, las figuras centrales, las que siempre estaban ah\u00ed, a las que hab\u00edan\u00a0&#8220;chingado&#8221;(penetrado sin consentimiento los espa\u00f1oles), y que siempre estaban al frente del hogar fueron las MUJERES IND\u00cdGENAS.<\/b><\/p>\n<p><b>En su larga lucha, un hombre descendientes de un santanderino comunista exiliado en M\u00e9xico, cuya madre ya\u00a0 fue mexicana, durante 21 a\u00f1os de lucha, recorri\u00f3 dos veces,como nadie, los 2,280 municipios del pa\u00eds, y comprendi\u00f3 que en esa base de los pueblos originarios NO EXIST\u00cdA\u00a0LA CULTURA\u00a0DE LA\u00a0<\/b><b>CORRUPCI\u00d3N\u00a0 y hab\u00eda una moral diferente a las clases dominantes.<\/b><\/p>\n<p><b>Por ello gan\u00f3 la presidencia L\u00f3pez Obrador, a pesar de todos los obst\u00e1culos\u00a0en M\u00e9xico, en EE:UU y Espa\u00f1a. Confi\u00f3 en esas mujeres y hombres, a punto de la desesperaci\u00f3n, violencia, falta de futuro y el pueblo mexicano, jug\u00f3 su \u00faltima carta, antes del estallido social: LAS ELECCIONES\u00a0DEL 2018.<\/b><\/p>\n<p><b>Y entonces, ese pueblo siempre marginado CONFI\u00d3 en quien daba el ejemplo, contra la corrupci\u00f3n la austeridad republicana, y que supo comunicarse con ellos, y que en el curso de 6 a\u00f1os LES DIO ESPERANZA.<\/b><\/p>\n<p><b>L\u00f3pez Obrador entend\u00eda muy bien lo sucedido en 30 a\u00f1os\u00a0por los gobiernos neoliberales, y recordaba que desde 1991, en Guadalajara, en las Cumbres Iberoamericanas, las trasnacionales espa\u00f1olas, entraban como cuchillo en la mantequilla, y que aprovechando la corrupci\u00f3n de la oligarqu\u00eda, los compraron, estos vendieron todo, entre ellos se fueron por el petroleo y la electricidad.<\/b><\/p>\n<p><b>En 2018 estaban presentes el rey Juan Carlos I, y en 2019, en enero se present\u00f3 Pedro S\u00e1nchez, y ah\u00ed vino el primer choque. Uno iba a apoyar a OHL, REPSOL, IBERDROLA, NATURGY Y ENDESA. y el otro encabezaba un PROYECTO DE NACI\u00d3N, justamente\u00a0donde no cabian los corruptos nacionales, norteamericanos\u00a0o espa\u00f1oles.<\/b><\/p>\n<p><strong>En ese marco se desarrollaron los a\u00f1os de 2019 a 2024.<\/strong><\/p>\n<p><strong>En el BIcentenario de la Independencia en 2021, en un gran acto en el Z\u00f3calo, con representantes de todo el mundo, se presentaba el nuevo M\u00e9xico, donde hablaba a EE:UU. y a Espa\u00f1a de igualdad y no intervenci\u00f3n.<\/strong><\/p>\n<p><b>Pero conocedor de los pueblos originarios, de que los mayas florec\u00edan en Calakmul cuando los griegos y que Uxmal habia sido construida cuando Europa no exist\u00eda, de c\u00f3mo\u00a0en 100 a\u00f1os, con la s\u00edfilis, la viruela, el caballo, la\u00a0p\u00f3lvora, acabaron\u00a0con el 90 % del pueblo ind\u00edgena. y como en 1528, en Man\u00ed, Yucat\u00e1n, en una Auto de Fe, Fray Diego de Landa quem\u00f3 todos los c\u00f3dices\u00a0mayas y guillotin\u00f3 su historia.<\/b><\/p>\n<p><strong>En el M\u00e9xico, anterior a esta nueva etapa, todav\u00eda los 12 de octubre ERAN EL DIA DE LA RAZA.<\/strong><\/p>\n<p><b>Para este\u00a0bicentenario,L\u00f3pez Obrador\u00a0 mand\u00f3\u00a0dos cartas: Una al Papa Francisco y otra al Rey de Espa\u00f1a, pidi\u00e9ndoles\u00a0en el nuevo marco de igualdad, se disculparan por los excesos de aquellos tres a\u00f1os.<\/b><\/p>\n<p><b>En Gij\u00f3n, este autor vivi\u00f3 toda la ceremonia. El Papa, mand\u00f3\u00a0un enviado espacial de alto nivel con la respuesta a la carta del\u00a0presidente mexicano, en forma inteligente: &#8221; Pedimos disculpas por los\u00a0excesos de la Iglesia, pero tambi\u00e9n recordamos que el cura Hidalgo, al llamar a la Independencia lo hizo con el estandarte de la Virgen de Guadalupe. Tan simple, e inteligente Francisco lo hizo.<\/b><\/p>\n<p><strong>Pero Felipe VI, ni siquiera contest\u00f3 la carta.<\/strong><\/p>\n<p><b>(Mientras el pa\u00eds crec\u00eda, sin corrupci\u00f3n, con autoridad. Aquellos olvidados de siempre supieron lo que era el Estado del Bienestar, que sac\u00f3 9.5 millones de la pobreza, y que con los 100,000 de dolares del combate\u00a0a la corrupci\u00f3, 100,000 millones m\u00e1s de la austeridad, y as\u00ed se crearon programas 20, que llegaron a 25 millones de las 35 familias mexicanas.<\/b><\/p>\n<p><b>Al elevar los ingresos de la base\u00a0de la\u00a0pir\u00e1mide, creci\u00f3\u00a0su capacidad de compra, ganaron los empresarios, los bancos espa\u00f1oles tienen records, el pa\u00eds pas\u00f3 del lugar 16 del PIB mundial(Espa\u00f1a el 15) y ahora\u00a0est\u00e1 en el 12 cerca de Rusia. Todos los recursos del Estado de Bienestar circulan por el BANCO NACIONAL, (todos eran\u00a0privados), a las 2,755 sucursales de todo el pa\u00eds. donde llegan tambi\u00e9n los 62,000 millones de d\u00f3lares de los emigrantes. Acaba de entregar\u00a0el SISTEMA DE SALUD UNIVERSAL Y GRATUITA)<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>Eso sent\u00f3 muy mal a L\u00f3pez Obrador, por que hasta EE:UU: cambio en t\u00e9rminos\u00a0de igualdad, y con ello L\u00f3pez Obrador logr\u00f3\u00a0 que Trump no construyese el Muro aquel.<\/b><\/p>\n<p><b>Terminado el negocio de Repsol, OHL, Naturgy, Endesa y la poderosa Iberdrola que termin\u00f3 vendiendo sus 13 plantas claves, las empresas espa\u00f1olas\u00a0como Santander, BBVA, y las 8,000 empresas espa\u00f1olas, sin ning\u00fan problema,pero L\u00f3pez Obrador hizo la &#8220;pausa&#8221; con el gobierno espa\u00f1ol.<\/b><\/p>\n<p><b>En el neoliberalismo\u00a0que desde 1979, se implant\u00f3 en Espa\u00f1a, donde los presidentes terminan siendo empleados de las transnacionales( hay que ver\u00a0la lista de 30 presidentes, ministros, asesores, donde empezando por Felipe Gonz\u00e1lez y\u00a0 Aznar, al terminar terminaron como asesores de las electricas, en las las llamadas\u00a0puerta giratorias..).<\/b><\/p>\n<p><b>Y cada pais sigui\u00f3 su desarrollo. En 6 a\u00f1os el proyecto de Naci\u00f3n, que no de partido, que encabeza\u00a0L\u00f3pez Obrador con el apoyo del pueblo, y la resistencias de los intereses desplazados.<\/b><\/p>\n<p><b>En junio, habl\u00f3 el pueblo\u00a0mexicano, constitucionalmente, sin violencia y apoy\u00f3 el proyecto del HUMANISMO MEXICANO, y vot\u00f3 por una mujer Claudia Sheinbaum con el 66 % de los votos, lograron los 2\/ 3 de la C\u00e1mara\u00a0de Diputados, de Senadores y los Congresos regionales(ellos y el gobernador, son de 24 estados de los 32). La oposici\u00f3n PRI- PAN- PRD, s\u00f3lo obtuvo el 25 % de la votaci\u00f3n y el PRD perdi\u00f3 el registro.<\/b><\/p>\n<p><b>Con la econom\u00eda\u00a0estatal( recuperados el Petr\u00f3leo\u00a0y la Electricidad y el Litio), m\u00e1s la privada, con Carlos Slim y la mayor\u00eda de los empresarios, el ej\u00e9rcito\u00a0y la marina y dejando una infraestructura, seg\u00fan\u00a0Ana Patricia Bot\u00edn y la OCDE, una de las 3 m\u00e1s atractivas del mundo, mientras Espa\u00f1a segu\u00eda su tortuoso camino, llega el momento de que una mujer de 62 a\u00f1os de origen sefardita, que ha apoyado siempre, por encima del propio L\u00f3pez Obrador, a los pueblos\u00a0originarios Claudia Sheinbaum prepara las invitaciones y le queda muy claro el desaire del Felipe VI, Y NO LO INVITA, Primera vez, en 44 a\u00f1os en que el rey de Espa\u00f1a no es invitado a un\u00a0acto de toma de posesi\u00f3n de un presidente iberoamericano.<\/b><\/p>\n<p><b>Para colmo, Pedro S\u00e1nchez, desde Nueva York, llama a Claudia para que se invite\u00a0al rey. Ella le contesta que no, y S\u00e1nchez\u00a0declara: &#8221; esta mujer tiene detr\u00e1s\u00a0a L\u00f3pez Obrador que odia a Espa\u00f1a&#8221;.<\/b><\/p>\n<p><b>Y lo empeor\u00f3, por que no sabe el nivel que tiene la primera mujer presidenta de Am\u00e9rica del Norte, Claudia Sheinbaum, y empieza mal, pero adem\u00e1s les da al pueblo mexicano un argumento m\u00e1s para un sentimiento muy profundo que tiene el pueblo mexicano, mayoritario y moreno.<\/b><\/p>\n<p><strong>La actual, Secretaria de Relaciones Exteriores ha dicho: &#8220;Tiene que haber un acto de desagravio de Espa\u00f1a, para normalizar las relaciones&#8221;<\/strong><\/p>\n<p><strong>Me pregunto: \u00bf tan f\u00e1cil era para Felipe VI, hacer lo que hizo el Papa?. &#8220;Pedimos una disculpa por los excesos pero recordamos que el espa\u00f1ol uni\u00f3 a M\u00e9xico y la cultura del pais, la creamos nosotros &#8220;(por ejemplo).<\/strong><\/p>\n<p><b>Pero ya sabemos, y ahora es internacional, que la monarqu\u00eda\u00a0espa\u00f1ola no va al corriente de la sociedad.,<\/b><\/p>\n<p><b>Ma\u00f1ana que L\u00f3pez Obrador invite a comer a todos los presidentes de Am\u00e9rica Latina, encabezados por Lula, Petro, Boring\u00a0D\u00edaz\u00a0Canel, el tema surgir\u00e1 y los delegados de los 104 paises que ser\u00e1n invitados a cenar por Claudia, ser\u00e1 el principio de 6 a\u00f1os, de un pueblo que cerr\u00f3 su ciclo.<\/b><\/p>\n<p><b>En Espa\u00f1a estamos entrampados, desgraciadamente.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Perm\u00edtanme\u00a0ubicar el origen. Como comentamos, Octavio Paz, premio\u00a0Nobel mexicano, en el Laberinto\u00a0de la Soledad, analiz\u00f3 el MESTIZAJE en la llamada\u00a0&#8221; conquista&#8221;. En Espa\u00f1a, en Europa, la RELACI\u00d3N\u00a0ES ENTRE IGUALES. En M\u00e9xico, la relaci\u00f3n\u00a0conquistador\u00a0ind\u00edgena, fue entre DESIGUALES. De ella, surgieron el Macho Mexicano(que viene del\u00a0macho espa\u00f1ol, y este del musulm\u00e1n ) y la Abnegada\u00a0mujercita mexicana.En ello, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-38756","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=38756"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38756\/revisions"}],"predecessor-version":[{"id":38759,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/38756\/revisions\/38759"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=38756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=38756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=38756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}