{"id":39202,"date":"2024-10-15T16:33:34","date_gmt":"2024-10-15T14:33:34","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39202"},"modified":"2024-10-15T16:33:34","modified_gmt":"2024-10-15T14:33:34","slug":"ee-uu-eleva-el-tono-contra-mexico-y-la-reforma-judicial-incertidumbre-para-inversiones","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/10\/15\/ee-uu-eleva-el-tono-contra-mexico-y-la-reforma-judicial-incertidumbre-para-inversiones\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1\u00a1EE.UU. ELEVA EL TONO CONTRA MEXICO Y LA REFORMA JUDICIAL. INCERTIDUMBRE PARA INVERSIONES !!!"},"content":{"rendered":"<p><b>Tras la incapacidad de interlocuci\u00f3n del embajador Ken Salazar, los Estados Unidos, han elevado el nivel de amenazas a trav\u00e9s\u00a0de la agregada comercial\u00a0 Katherine Tai.<\/b><\/p>\n<p><strong>El gobierno y los empresarios de nuestro pa\u00eds tienen miedo de la Reforma Judicial, lo que dificulta los negocios con M\u00e9xico y que se pierdan inversiones.<\/strong><\/p>\n<p><strong>M\u00e9xico es nuestro primer socio comercial por encima de China y Canad\u00e1 y con el 16 %. El futuro de nuestro pa\u00eds ante la Presidenta Sheinbaum, va a quedar marcado por esta medida.<\/strong><\/p>\n<p><strong>Es un error,ojal\u00e1 sea modificada.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Tras la incapacidad de interlocuci\u00f3n del embajador Ken Salazar, los Estados Unidos, han elevado el nivel de amenazas a trav\u00e9s\u00a0de la agregada comercial\u00a0 Katherine Tai. El gobierno y los empresarios de nuestro pa\u00eds tienen miedo de la Reforma Judicial, lo que dificulta los negocios con M\u00e9xico y que se pierdan inversiones. M\u00e9xico es nuestro primer [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39202","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39202"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39202\/revisions"}],"predecessor-version":[{"id":39203,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39202\/revisions\/39203"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}