{"id":39207,"date":"2024-10-15T18:04:20","date_gmt":"2024-10-15T16:04:20","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39207"},"modified":"2024-10-15T18:04:20","modified_gmt":"2024-10-15T16:04:20","slug":"los-242-empresarios-mas-importantes-de-ee-uu-y-mexicosus-ceos-reunidos-hoy-en-mexico","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/10\/15\/los-242-empresarios-mas-importantes-de-ee-uu-y-mexicosus-ceos-reunidos-hoy-en-mexico\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1LOS 242 EMPRESARIOS MAS IMPORTANTES DE EE.UU Y MEXICO(SUS CEOS), REUNIDOS HOY EN M\u00c9XICO !!!!"},"content":{"rendered":"<p><b>Cada minuto\u00a0 1.5 millones de dolares se comercian entre M\u00e9xico y Estados Unidos. Al a\u00f1o el comercio bilateral es\u00a0de 415,000 millones\u00a0de d\u00f3lares.<\/b><\/p>\n<p><b>Am\u00e9rica del Norte:(1)\u00a0 EE:UU 22 billones de dolares), (9) Canad\u00e1\u00a0 2.1 B y\u00a0 ( 12 )M\u00e9xico\u00a0 con 1.8 B ) es la zona donde se encuentra el 30 % del PIB mundial y se tiene\u00a0entre los 3 el mayor tratado comercial del mundo conocido como T MEC, con 12 millones de kms cuadrados de superficie.Es decir se trata de una de las regiones m\u00e1s\u00a0fuertes del mundo.<\/b><\/p>\n<p><b>Aunque es anual la\u00a0reuni\u00f3n de ambos Secretarios de Econom\u00eda\u00a0y los principales empresarios(llama la atenci\u00f3n de que sean hoy 242), hay particular inter\u00e9s\u00a0en conocer a la Presidenta Sheinbaum. Por supuesto, antes los ataques que se han recibido, para M\u00e9xico es una gran oportunidad que la presidenta explique dudas sobre la Reforma Judicial en forma directa y les informe que, al rev\u00e9s, no va haber problemas sino que el sistema\u00a0judicial ser\u00e1 m\u00e1s democr\u00e1tico, y agil, que beneficiar\u00e1 los negocios entre ambos paises.<\/b><\/p>\n<p><b>El Secretario Marcelo Ebrard, ha dicho que interes\u00f3 a los empresarios el INTERNET PARA TODOS, donde L\u00f3pez Obrador lo dej\u00f3\u00a0en el 90 % del territorio<\/b><\/p>\n<p><b>Para ambos paises es muy importante compartir 3,250 kms de frontera,lo que\u00a0 profundiza y crece el comercio &#8220;near shoring&#8221;(negocio cercano). ( En M\u00e9xico, transmito, un empresario\u00a0japones dec\u00eda: &#8220;Si nosotros tuvi\u00e9ramos\u00a0tan s\u00f3lo 50 kms de frontera con EE:UU seriamos\u00a0la primer potencia mundial).<\/b><\/p>\n<p><b>La conferencia de prensa se dar\u00e1 a las 10 de la noche(hora de Espa\u00f1a) por ellos, los resultados los transmitiremos\u00a0ma\u00f1ana-<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cada minuto\u00a0 1.5 millones de dolares se comercian entre M\u00e9xico y Estados Unidos. Al a\u00f1o el comercio bilateral es\u00a0de 415,000 millones\u00a0de d\u00f3lares. Am\u00e9rica del Norte:(1)\u00a0 EE:UU 22 billones de dolares), (9) Canad\u00e1\u00a0 2.1 B y\u00a0 ( 12 )M\u00e9xico\u00a0 con 1.8 B ) es la zona donde se encuentra el 30 % del PIB mundial y [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39207","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39207"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39207\/revisions"}],"predecessor-version":[{"id":39208,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39207\/revisions\/39208"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}