{"id":39351,"date":"2024-10-22T20:08:36","date_gmt":"2024-10-22T18:08:36","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39351"},"modified":"2024-10-22T20:08:36","modified_gmt":"2024-10-22T18:08:36","slug":"contra-la-hegemonia-del-dolartras-la-formacion-del-banco-de-desarrollo-de-los-brics","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/10\/22\/contra-la-hegemonia-del-dolartras-la-formacion-del-banco-de-desarrollo-de-los-brics\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1\u00a1CONTRA LA HEGEMON\u00cdA DEL D\u00d3LAR,TRAS LA FORMACI\u00d3N DEL BANCO DE DESARROLLO DE LOS BRICS +!!! !!!"},"content":{"rendered":"<p><b>&#8221; La reuni\u00f3n m\u00e1s importante celebrada nunca en Rusia&#8221; la ha definido el Secretario General de la ONU, Antonio Gutierres, a la que se est\u00e1 celebrando en Kazan. Con Xi, con Modi, el presidente de Sud\u00e1frica y la falta, por un problema dom\u00e9stico\u00a0y que prepara para noviembre\u00a0el G20, en Brasil, Lula, adem\u00e1s de los mandatarios de los\u00a0otros 10 paises, hoy\u00a0 se han reunido con Putin, Erdogan, y el Presidente de Ir\u00e1n.<\/b><\/p>\n<p><b>Hemos hablado desde hace m\u00e1s de un a\u00f1o, del giro del mundo unipolar al multipolar y como, poco a poco, todas las instituciones\u00a0de Bretton Woods iban a ser reemplazadas. Al Banco Mundial, ya est\u00e1 enfrente el Banco de Desarrollo de los Brics que dirige la ex presidenta\u00a0Dilma\u00a0Rousseff y ya Putin habl\u00f3 hoy de sustituir\u00a0el patr\u00f3n\u00a0d\u00f3lar por una canasta\u00a0 de diversas monedas de paises de los BRICS.<\/b><\/p>\n<p><strong>Ante el caos en Medio Oriente, los retos de la OTAN en Ucrania, este potente organismo, va a ir aglutinando al Sur Global. Venezuela y Cuba, invitados hoy.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>&#8221; La reuni\u00f3n m\u00e1s importante celebrada nunca en Rusia&#8221; la ha definido el Secretario General de la ONU, Antonio Gutierres, a la que se est\u00e1 celebrando en Kazan. Con Xi, con Modi, el presidente de Sud\u00e1frica y la falta, por un problema dom\u00e9stico\u00a0y que prepara para noviembre\u00a0el G20, en Brasil, Lula, adem\u00e1s de los mandatarios [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39351","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39351"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39351\/revisions"}],"predecessor-version":[{"id":39352,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39351\/revisions\/39352"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}