{"id":39536,"date":"2024-10-30T16:53:58","date_gmt":"2024-10-30T15:53:58","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39536"},"modified":"2024-10-30T16:53:58","modified_gmt":"2024-10-30T15:53:58","slug":"de-47282-especies-clasificadas-17598-en-riesgo-de-extension-38-de-arboles-en-riesgo-de-desaparecer","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/10\/30\/de-47282-especies-clasificadas-17598-en-riesgo-de-extension-38-de-arboles-en-riesgo-de-desaparecer\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1DE 47,282 ESPECIES CLASIFICADAS, 17,598 EN RIESGO DE EXTENSI\u00d3N. 38 % DE \u00c1RBOLES EN RIESGO DE DESAPARECER  !!!"},"content":{"rendered":"<p><b>La Comisi\u00f3n Mundial de Conservaci\u00f3n Ecol\u00f3gica, acaba de dar la siguiente\u00a0informaci\u00f3n. En el planeta hay identificadas 47,282 ESPECIES y de las cuales 1,1598 EST\u00c1N\u00a0EN RIESGO DE EXTINCI\u00d3N. Adem\u00e1s inform\u00f3 que de la poblaci\u00f3n mundial de \u00e1rboles, el 38 % est\u00e1n en peligro de extinci\u00f2n. \u00bf Nos extra\u00f1a los\u00a0fen\u00f3menos\u00a0 meteorol\u00f3gicos\u00a0mundiales &#8220;nunca antes visto&#8221; ?. S\u00f3lo los necios, LOS NEGACIONISTAS como Trump, o AQUEL &#8220;PRIMO DE RAJOY&#8221; lo niegan.<\/b><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Mundial de Conservaci\u00f3n Ecol\u00f3gica, acaba de dar la siguiente\u00a0informaci\u00f3n. En el planeta hay identificadas 47,282 ESPECIES y de las cuales 1,1598 EST\u00c1N\u00a0EN RIESGO DE EXTINCI\u00d3N. Adem\u00e1s inform\u00f3 que de la poblaci\u00f3n mundial de \u00e1rboles, el 38 % est\u00e1n en peligro de extinci\u00f2n. \u00bf Nos extra\u00f1a los\u00a0fen\u00f3menos\u00a0 meteorol\u00f3gicos\u00a0mundiales &#8220;nunca antes visto&#8221; ?. S\u00f3lo los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39536","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39536"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39536\/revisions"}],"predecessor-version":[{"id":39537,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39536\/revisions\/39537"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}