{"id":39793,"date":"2024-11-08T17:45:43","date_gmt":"2024-11-08T16:45:43","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39793"},"modified":"2024-11-08T17:45:43","modified_gmt":"2024-11-08T16:45:43","slug":"g-20-2-la-presidenta-sheinbaum-estara-solo-el-18-ira-con-5-personas-en-vuelo-comercial-para-regresar-a-los-festejos-de-la-revolucion-mexicana-entrevistas-bilaterales","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/08\/g-20-2-la-presidenta-sheinbaum-estara-solo-el-18-ira-con-5-personas-en-vuelo-comercial-para-regresar-a-los-festejos-de-la-revolucion-mexicana-entrevistas-bilaterales\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1(G 20.- 2) LA PRESIDENTA SHEINBAUM, ESTAR\u00c1 SOLO EL 18.- IRA CON 5 PERSONAS, EN VUELO COMERCIAL, PARA REGRESAR A LOS FESTEJOS DE LA REVOLUCI\u00d3N MEXICANA. ENTREVISTAS BILATERALES !!!!"},"content":{"rendered":"<p><b>Al no confirmar\u00a0Giorgia\u00a0Meloni, LA \u00daNICA\u00a0MUJER PRESIDENTA SER\u00c1\u00a0CLAUDIA SHEINBAUM\u00a0PARDO,\u00a0\u00a0presidenta de M\u00e9xico..<\/b><\/p>\n<p><b>En la Ma\u00f1anera, el Secretario de Relaciones\u00a0Exteriores Juan Ram\u00f3n\u00a0de la Fuente, anterior representante del pa\u00eds en Naciones UNidas, que inclusive presidi\u00f3 el Consejo de Seguridad, con suma sencillez\u00a0inform\u00f3 a todos los mexicanos que es el G 20, quienes asisten, que comisiones, lo que se busca de ellas, y las actividades de la Presidenta, finalmente, los detalles de la visita de ella.<\/b><\/p>\n<p><b>Ella ten\u00eda el 18 la visita del Canciller\u00a0alem\u00e1n, Scholtz\u00a0\u00a0 y el 20 de aniversario, muy importante para el pueblo mexicano que es el aniversario\u00a0de la Revoluci\u00f3n M\u00e9xico(ese d\u00eda, el 20 de noviembre de 1910\u00a0 que iluminaba al pa\u00eds, coincidi\u00f3\u00a0con el fin de la luz de Le\u00f3n\u00a0Tolstoi, en la oficina del Jefe de la oficina de aquel pueblo en Rusia donde parar\u00eda\u00a0el \u00faltimo tren del gran escritor).<\/b><\/p>\n<p><b>Hoy se defini\u00f3 su programa. Se trasladar\u00e1 la visita del Canciller alem\u00e1n a otra fecha y ella asistir\u00e1\u00a0s\u00f3lo a las 2 reuniones plenarias del 18..<\/b><\/p>\n<p><b>En ese d\u00eda se han concretado entre muchas, por la novedad de no conocerla, de ser la primera Presidenta de Am\u00e9rica Latina, y se han concretado las reuniones bilaterales\u00a0que sostendr\u00e1.<\/b><\/p>\n<p><b> Ser\u00e1n con los presidentes de CHINA, FRANCIA, CANAD\u00c1, COREA\u00a0E INDONESIA (Xi Jinping, Macr\u00f3n, Trudeau y los presidentes\u00a0de Corea y de Indonesia, Joko\u00a0Wisboo\u00a0y Moo\u00a0 Jan .-) BIDEN\u00a0 la llam\u00f3 el domingo\u00a0estando ella en Veracruz.<\/b><\/p>\n<p><b>Consecuente, como L\u00f3pez Obrador, con la austeridad\u00a0republicana, ir\u00e1 en vuelo comercial con 5 personas m\u00e1s, y regresar\u00e1 el\u00a0 19.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Al no confirmar\u00a0Giorgia\u00a0Meloni, LA \u00daNICA\u00a0MUJER PRESIDENTA SER\u00c1\u00a0CLAUDIA SHEINBAUM\u00a0PARDO,\u00a0\u00a0presidenta de M\u00e9xico.. En la Ma\u00f1anera, el Secretario de Relaciones\u00a0Exteriores Juan Ram\u00f3n\u00a0de la Fuente, anterior representante del pa\u00eds en Naciones UNidas, que inclusive presidi\u00f3 el Consejo de Seguridad, con suma sencillez\u00a0inform\u00f3 a todos los mexicanos que es el G 20, quienes asisten, que comisiones, lo que se busca [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39793","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39793"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39793\/revisions"}],"predecessor-version":[{"id":39796,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39793\/revisions\/39796"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}