{"id":39797,"date":"2024-11-08T18:07:54","date_gmt":"2024-11-08T17:07:54","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=39797"},"modified":"2024-11-08T18:07:54","modified_gmt":"2024-11-08T17:07:54","slug":"mazon-estuvo-comiendo-de-las-2-a-las-6-con-la-periodista-maribel-vilaplana-su-final-cerca","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/08\/mazon-estuvo-comiendo-de-las-2-a-las-6-con-la-periodista-maribel-vilaplana-su-final-cerca\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1MAZON ESTUVO COMIENDO DE LAS 2 A LAS 6 CON LA PERIODISTA MARIBEL VILAPLANA. SU FINAL, CERCA !!!!"},"content":{"rendered":"<p><b>Cercado hasta por su propio partido, tras la videoconferencia con Feij\u00f3o\u00a0y los Barones\u00a0del PP, Carlos Maz\u00f3n sac\u00f3 a la luz que estuvo de las 2 a las 6 de la tarde comiendo con la periodista Maribel Vilaplana, en un restaurante\u00a0de Valencia.<\/b><\/p>\n<p><b> Insensible a la gravedad de una DANA que dejar\u00e1 300 valencianos muertos o desaparecidos, inform\u00f3 a\u00a0las 10 de la ma\u00f1ana que \u00b7(esto\u00a0se acaba\u00a0a las 6), dej\u00f3 la direcci\u00f3n a la Consellera de Justicia Salom\u00e9\u00a0Pradas, que hasta las 8 de la noche supo por un t\u00e9cnico\u00a0inform\u00e1tico\u00a0quee exist\u00eda el sistema de alerta a\u00a0m\u00f3viles, y lo que hubiera sido una cat\u00e1strofe, no habr\u00eda tenido esas p\u00e9rdidas\u00a0humanas si,hubiera hecho caso a la Delegada del Gobierno que avis\u00f3 desde\u00a0la 10 de la ma\u00f1ana, inclusive\u00a0la UNiversidad de Valencia, desde la noche anterior pidi\u00f3 que nadie fuese a clase al d\u00eda siguiente.<\/b><\/p>\n<p><strong>Hoy se abri\u00f3 a concurso las 15 puestos vacantes de asistencia a emergencias. Una burla<\/strong><\/p>\n<p><b>Es el final de Carlos Maz\u00f3n, de Salom\u00e9 Pradas, quee enfrentan\u00a0denuncias penales\u00a0m\u00faltiples\u00a0de la poblaci\u00f2n afectada.<\/b><\/p>\n<p><b>A 8 d\u00edas la ayuda rebasa la capacidad del gobierno valenciano\u00a0y del nacional.<\/b><\/p>\n<p><b>Quiz\u00e1s ma\u00f1ana\u00a0habr\u00e1 novedades.<\/b><\/p>\n<p><b>Pero el pueblo valenciano sigue luchando, se rescatan cad\u00e1veres\u00a0en La Albufera<\/b><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cercado hasta por su propio partido, tras la videoconferencia con Feij\u00f3o\u00a0y los Barones\u00a0del PP, Carlos Maz\u00f3n sac\u00f3 a la luz que estuvo de las 2 a las 6 de la tarde comiendo con la periodista Maribel Vilaplana, en un restaurante\u00a0de Valencia. Insensible a la gravedad de una DANA que dejar\u00e1 300 valencianos muertos o desaparecidos, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39797","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=39797"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39797\/revisions"}],"predecessor-version":[{"id":39798,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/39797\/revisions\/39798"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=39797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=39797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=39797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}