{"id":40032,"date":"2024-11-16T17:55:09","date_gmt":"2024-11-16T16:55:09","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=40032"},"modified":"2024-11-16T17:55:10","modified_gmt":"2024-11-16T16:55:10","slug":"la-globalizacion-economica-se-enfrenta-a-contracorrientes-xi-y-biden-en-la-apec-en-peru-con-21-paises","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/16\/la-globalizacion-economica-se-enfrenta-a-contracorrientes-xi-y-biden-en-la-apec-en-peru-con-21-paises\/","title":{"rendered":"\u00a1\u00a1\u00a1 &#8220;LA GLOBALIZACI\u00d3N ECON\u00d3MICA SE ENFRENTA A CONTRACORRIENTES&#8221;: XI Y BIDEN EN LA APEC, EN PER\u00da , CON 21 PA\u00cdSES !!!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No lo sab\u00edamos. Habl\u00e1bamos hoy en la ma\u00f1ana de la gira de Xi Jinping con una comitiva de 150 dirigentes, empresarios y funcionarios, primero a Canarias, para descansar del trayecto y gozar el calorcito espa\u00f1ol; luego el viaje a Per\u00fa, donde inaugur\u00f3 el nuevo eslab\u00f3n de la NUEVA RUTA DE LA SEDA en el Puerto de Chancay, pero hubo y habr\u00e1 m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy se celebr\u00f3 la Cumbre Asia- Pacifico, con 21 paises, entre ellos China y Estados Unidos, que tienen el 60 del PIB y el 40 % del comercio mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ah\u00ed se ha dado la \u00faltima reuni\u00f3n entre BIden y Xi, donde ambos expresaron:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La GLOBALIZACI\u00d3N ECON\u00d3MICA EN ENFRENTA A CONTRACORRIENTES., en relaci\u00f3n al triunfo de Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos viajar\u00e1n a R\u00edo de Janeiro, en Brasil, el 18 y 19 de noviembre, pero ya no hablar\u00e1n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No lo sab\u00edamos. Habl\u00e1bamos hoy en la ma\u00f1ana de la gira de Xi Jinping con una comitiva de 150 dirigentes, empresarios y funcionarios, primero a Canarias, para descansar del trayecto y gozar el calorcito espa\u00f1ol; luego el viaje a Per\u00fa, donde inaugur\u00f3 el nuevo eslab\u00f3n de la NUEVA RUTA DE LA SEDA en el Puerto [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40032","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=40032"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40032\/revisions"}],"predecessor-version":[{"id":40033,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40032\/revisions\/40033"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=40032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=40032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=40032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}