{"id":40192,"date":"2024-11-25T10:15:30","date_gmt":"2024-11-25T09:15:30","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=40192"},"modified":"2024-11-25T10:15:31","modified_gmt":"2024-11-25T09:15:31","slug":"y-vino-la-respuesta-cinco-ex-magistrados-acusan-al-emerito-de-5-delitos-de-fraude-fiscal","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/25\/y-vino-la-respuesta-cinco-ex-magistrados-acusan-al-emerito-de-5-delitos-de-fraude-fiscal\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1Y VINO LA RESPUESTA&#8230;.CINCO EX MAGISTRADOS ACUSAN AL EM\u00c9RITO DE 5 DELITOS DE FRAUDE FISCAL !!!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No era tan f\u00e1cil tratar as\u00ed al Jefe de Gobierno electo por los Ciudadanos  tras Paiporta y luego lanzarle a la cara a un corrupto,como su padre, De Aldama, no s\u00f3lo contra Sanchez sino contra el coraz\u00f3n del Partido Socialista Obrero Espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No cabr\u00e1 para Felipe VI, lo que le dijo su padre Juan Carlos I, a Adolfo Su\u00e1rez, cuando traicionado por el Em\u00e9rito, \u00bf y quien no? le reclamaba aquel domingo en la Zarzuela, el haberlo lanzado contra los caballos (los 4 generales) para dimitir, \u00bf ES QUE YO TENGO LOS VOTOS DEL PUEBLO? le dec\u00eda Adofo Suarez a lo que el Em\u00e9rito en aquel despacho en el primera piso de La Zarzuela, le solt\u00f3, \u00bf PUES YO TENGO TRES SIGLOS DE MONARCAS TRAS DE MI ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Hoy l primer d\u00eda de esta semana clave para los socialistas y para la Legislatura, y para el futuro del pueblo espa\u00f1ol salt\u00f3 la noticia en RTVE:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8221; CINCO EX MAGISTRADOS ACUSAN AL EM\u00c9RITO DE CINCO  DELITOS DE FRAUDE FISCAL &#8220;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>No era tan f\u00e1cil tratar as\u00ed al Jefe de Gobierno electo por los Ciudadanos tras Paiporta y luego lanzarle a la cara a un corrupto,como su padre, De Aldama, no s\u00f3lo contra Sanchez sino contra el coraz\u00f3n del Partido Socialista Obrero Espa\u00f1ol. No cabr\u00e1 para Felipe VI, lo que le dijo su padre Juan Carlos [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40192","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=40192"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40192\/revisions"}],"predecessor-version":[{"id":40193,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40192\/revisions\/40193"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=40192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=40192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=40192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}