{"id":40208,"date":"2024-11-26T12:27:10","date_gmt":"2024-11-26T11:27:10","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=40208"},"modified":"2024-11-26T12:27:11","modified_gmt":"2024-11-26T11:27:11","slug":"de-aldama2-el-pillo-codicioso-el-espia-condecorado-que-no-supo-entender-los-cambios-a-10000-kms","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/26\/de-aldama2-el-pillo-codicioso-el-espia-condecorado-que-no-supo-entender-los-cambios-a-10000-kms\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a1DE ALDAMA(2).- EL PILLO CODICIOSO, EL &#8220;ESP\u00cdA CONDECORADO&#8221;, QUE NO SUPO ENTENDER LOS CAMBIOS A 10,000 KMS !!!!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El se\u00f1or VICTOR DE ALDAMA, , un  inteligente pillo de medio pelo, encontr\u00f3 el camino entre la codicia, valor fundamentantal  en parte de la sociedad espa\u00f1ola, entr\u00f3 como mantequilla desde empresarios espa\u00f1oles, pol\u00edticos corruptos, lideres internacionales como Maduro, pero que, enterado del paraiso que iba a crearse para \u00e9l a 10,000 kms de distancia, no supo lo que estaba pasando all\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8221; Victor, \u00bf de donde crees que viene la fortuna del Em\u00e9rito?, \u00bf no ves la reconquista de Am\u00e9rica de Repsol, OHL, Iberdrrola, Naturgy y Endesa?, y entonces encontr\u00f3 el camino: M\u00e9xico y Venezuela. \u00bf Que iba hacer contratos en Asturias, en Murcia, en Alicante?, no eso es para &#8220;pijos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y aunque usted no se lo crea, eso ubic\u00f3 su futuro. Amigo del gobernador de Oaxaca, el hombre que pod\u00eda serle util a Maduro, se lanz\u00f3 a la aaventura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era 2018.El presidente de M\u00e9xico,planteaba el Tren Maya, ferrocarril, obra p\u00fablica, carreteras, puentes, en suma EL DORADO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello cuando el hermano Rub\u00e9n, miembro de la Guardia Civil, es asignado a ser escolta del nuevo SUPERMINISTRO,  el de Fomento, encontr\u00f3, con un poco de suertee, el camino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su hermano, le inform\u00f3 que el nuevo Superministro, ten\u00eda en Valencia, hijo de Ana, su primera de las 3 esposas, un hijo que estaba en un verdadero problema. Miembro desde hace a\u00f1os del PSOE, Victor Manuel Abalos Aguado, que manejaba la Loter\u00eda y que deb\u00eda centenares de miles que lo agobiaban, Rub\u00e9n le abri\u00f3 la  puerta en aquella comida en Madrid, con Jos\u00e9 Luis \u00c1balos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inteligente, sabedor del pa\u00f1o, le habr\u00e1 dicho, &#8221; oiga, ahora usted Superministro, necesita estar traanquilo, y me dice mi hermano que su hijo tiene un problema en Valencia&#8221;. &#8220;Puess ,si&#8221;. &#8220;No yo se lo resuelvo de inmediato&#8221;. Con dinero de un socio, le quit\u00f3 el peso de encima al hijo de Abalos y se gan\u00f3 sus confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c1balos, designa a  Koldo  Garcia, su hombre de confianza en el enlace con \u00e9l. De ah\u00ed, perdiendo la perspectiva, numero 3 de Ferraz y poderoso ministro, se enganch\u00f3 y &#8221; pa adelante&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De Aldama que ya ten\u00eda contacto con Maduro(su hombre en Espa\u00f1a, para vender petroleo, comprar  oro), de inmediato se puso en contacto con los Jefes de la Guardia Civill, sobre todo en Logro\u00f1o, con la Unidad Especial de Inteligencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo se habia hecho amigo entre copas y mariscos en Madrid con el gobernador de Oaxaca Alejandro Murat, priista, que le coment\u00f3 los grandes proyectos de L\u00f3pez Obrador: Tren Maya, Tren Trasoceanico, presass, carreteras, todo. Pero a Aldama no pod\u00eda presentarse como un empresario m\u00e1s, y entones habl\u00f3 con Koldo. &#8220;Koldo, esta semana  viajamos,como sabes, con Jos\u00e9 Luis a Oaxaca, y sabes que soy el embajador de Oaxaca en Espa\u00f1a. Pero necesitamos la FOTO.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y Koldo consigue que entre a la  Asamblea  en Madrid, mientras Koldo lo fotografiaba y m\u00e1s tarde, se acerca con Sanchez y le saca la foto, con un buen amigo.Esas son las fotos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la semana siguiente viajan los tres en diciembre del 2018 a Oaxaca. En una reuni\u00f3n de trabajo, el hijo de Pepe Murat, anterior gobernador, se reunen con el SUPERMINISTRO, De Aldama y Koldo.De Aldama  se llev\u00f3 entre sus &#8220;pendientes&#8221; el favor del due\u00f1o de Air Europa, de buscar abrir la ruta MADRID- HUATULCO, una playa bell\u00edsima en el Pac\u00edfico, que por supuesto no sali\u00f3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A principios del 2019, \u00c4balos y Koldo viajan a M\u00e9xico a abrir relaciones con Espa\u00f1a, sin saber que L\u00f3pez Obrador, ten\u00eda en la mira a las transaccionales espa\u00f1olas que hab\u00edan saqueado el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Invitan a Murat a reunirse con los tres(Aldama centro de la trama, con empresarios poderosos que aportaban la &#8220;lana&#8221;), intimo del Superministro, puertas abiertas a trav\u00e9s de Koldo, pero Murat no acepta al ver que pasaba en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el viaje anterior, Aldama &#8220;pillo pero inteligente&#8221; hab\u00eda conocido a um empresario taurino, ahora senador y le manda un mensaje: &#8220;Senador, tenemos nuestra gran oportunidad. Sabes que tengo en un pu\u00f1o al SUPERMINISTRO de Fomento. De su firma dependen los grandes negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras el jugaba su papel para la Guardia Civil, &#8220;haciendo aquello que ellos no pod\u00edan hacer como, entusiasmado el Coronel Francisco Javier Vazquez, el Jefe de la Unidad de Inteligencia UC-2, el d\u00eda que lo tuvo como invitado VIP, cinco d\u00edas, ante la molestia de sus subordinados y tiene acceso a muchas cosas&#8221; por lo que le conceden la Medalla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para un tipo como Aldama, todo lo que ten\u00eda sumaba. Su af\u00e1n el poder econ\u00f3mico, como &#8220;los grandes en Espa\u00f1a&#8221;.No logrado nada con L\u00f3pez Obrador, mientras iba mareando con peque\u00f1os lujos la debilidad ideol\u00f3gica de Abalos, el habr\u00eda el camino con Air Europa, con dificultades, y ah\u00ed empieza a embarrar a Bego\u00f1a G\u00f3mez, . <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no seria hasta aquel Halloween en 2020 donde estaba presente Adriana Lastra  la fiesta en aquel Parador Nacional, donde en un fiest\u00f3n termina con todo el bungalow destrozado, y tras la advertencia de Ivan Redondo de la vida que llevaba , \u00c1balos est\u00e1n en la mira..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descartado M\u00e9xico, le queda Venezuela, y de ah\u00ed involucra a Abalos, Koldo y De Aldama. La visita de Delcy iba a ser en Madrid, pero Marlaska acude al aeropuerto para decirle a Abalos que Delcy no pod\u00eda tocar territorio Sengen y todo se concreta en la estancia del Aeropuerto. El oro lo maneja de Aldama, hasta que en su intento de ACOSO Y DERRIBO, The Objective, con capital  del exilio venezolano. etapa la corrupci\u00f3n y le da seguimiento a trav\u00e9s de Katty, su reportera estrella a todo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y de ah\u00ed todo lo que usted sabe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Victor de Aldama, con sus contactos, el super abogadao, habla, tira de la manta contra el PSOE, con la palabra de un  acusado de un fraude con el IVA de 183 millones Y OBTIENE LA LIBERTAD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un pillo de se nivel, inteligente, pero mal informado, \u00bf Un pasaporte nuevo?, \u00bf un avi\u00f3n para irse a Brasil o Venezuela?. Aqu\u00ed entra de nuevo un juez espa\u00f1ol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El se\u00f1or VICTOR DE ALDAMA, , un inteligente pillo de medio pelo, encontr\u00f3 el camino entre la codicia, valor fundamentantal en parte de la sociedad espa\u00f1ola, entr\u00f3 como mantequilla desde empresarios espa\u00f1oles, pol\u00edticos corruptos, lideres internacionales como Maduro, pero que, enterado del paraiso que iba a crearse para \u00e9l a 10,000 kms de distancia, no [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40208","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=40208"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40208\/revisions"}],"predecessor-version":[{"id":40209,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40208\/revisions\/40209"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=40208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=40208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=40208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}