{"id":40265,"date":"2024-11-30T19:13:20","date_gmt":"2024-11-30T18:13:20","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=40265"},"modified":"2024-11-30T19:13:21","modified_gmt":"2024-11-30T18:13:21","slug":"50000-peleas-de-box-simultaneas-en-el-localizo-y-todas-las-plazas-del-pais-el-canelo-y-la-presidenta","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2024\/11\/30\/50000-peleas-de-box-simultaneas-en-el-localizo-y-todas-las-plazas-del-pais-el-canelo-y-la-presidenta\/","title":{"rendered":"\u00a1\u00a1\u00a1\u00a150,000 PELEAS DE BOX, SIMULTANEAS, EN EL LOCALIZO Y TODAS LAS PLAZAS DEL PA\u00cdS.- &#8220;EL CANELO&#8221; Y LA PRESIDENTA !!!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador lo inici\u00f3 con Julio Cesar Chavez, campe\u00f3n del mundo, donde en el Z\u00f3calo de la Capital 14,300 personas recibieron clases de box. Atraer a los j\u00f3venes a hacer ejercicio de  forma ludica era el objetivo. Separarlas de las bandas de narcotraficantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El a\u00f1o pasado fueron 30,000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer en la visita del Campe\u00f3n del Mundo, &#8220;El Canelo&#8221; Alvarez a la presidenta de la Rep\u00fab\u00f1ica, se decido romper aquel record. Ahora no va a ser s\u00f3lo en el Zocalo, sino en plazas dee todo el pa\u00eds, donde se espera que haya m\u00e1s de 50,000.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea de usar la monumental plaza, con cabida ,con las calles, que la rodean, fue de Claudia Sheinbaum cuando era gobernadora de la ciudad de M\u00e9xico. Conciertos de centenares de miles, gratis, fueron gozados por centenares de miles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OCESSA la empresa privada que cre\u00f3 el Foro Sol para atraer  a los mas grandes con capacidad para 60,000, superando al Auditorio Nacional con 10,000, ahora el gobierno utiliza LO PUBLICO para el pueblo, y as\u00ed el Zocalo ha sido el coraz\u00f3n de la naci\u00f3n, mas que nunca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">( En Iztacalco, de 1997 al 2,000, el nieto de Belarmino, al frente de esa delegaci\u00f3n de casi un mill\u00f3n de habitantes, di\u00f3 la vuelta a todo, y, por primera vez LO PUBLICO estuvo al frente. Con el mando de la policia, todos los eventos del Foro Sol, desde los Rollings, Alejandro Fern\u00e1ndez, y bailes para 30,000 parejas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo PUBLICO AL FRENTE, CERO CORRUPCIN Y AUSTERIDAD REPUBLICANA fue el exito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta la Iglesia Cat\u00f3lica fue por la organizaci\u00f3n de la visita de los 86 pasos, en la Magdalena, a estar bajo el mando de la Delegaci\u00f3n, aquella inolvidable Misa de Juan Pablo II, al que asistieron 3.500,000 de fieles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5 a\u00f1os despu\u00e9s vine a Espa\u00f1a, a los 67 a\u00f1os, a luchar contra Aznar que hab\u00eda irrumpido en M\u00e9xico contra L\u00f3pez Obrador, bajo la idea: &#8221; Para que pelearme aqu\u00ed con el empleado Calder\u00f3n; mejor me voy a Espa\u00f1a y con el PSOE, lucho contra Aznar&#8221;., y gracias aquellos mediocres de Fernandez, Trevin, Villa, que me cerraron todas las puertas: \u00a1\u00a1\u00a1VIENE A LUCRAR DEL PARTIDO!!!.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a ellos, me dedique a estudiar , aprender, escribir, lo que no hubiera podido hacer en el ACTIVISMO DE DECENA DE A\u00d1OS DE MEXICO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mis modestos trabajos all\u00ed, dee uno mas de los sin nombre, permitieron que mis hijas y mis nietas gocen del nuevo M\u00e9xico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>L\u00f3pez Obrador lo inici\u00f3 con Julio Cesar Chavez, campe\u00f3n del mundo, donde en el Z\u00f3calo de la Capital 14,300 personas recibieron clases de box. Atraer a los j\u00f3venes a hacer ejercicio de forma ludica era el objetivo. Separarlas de las bandas de narcotraficantes. El a\u00f1o pasado fueron 30,000. Ayer en la visita del Campe\u00f3n del [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40265","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=40265"}],"version-history":[{"count":1,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40265\/revisions"}],"predecessor-version":[{"id":40266,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/40265\/revisions\/40266"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=40265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=40265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=40265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}