{"id":5967,"date":"2018-11-08T08:38:35","date_gmt":"2018-11-08T07:38:35","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=5967"},"modified":"2018-11-08T08:38:35","modified_gmt":"2018-11-08T07:38:35","slug":"ofrezco-colaboracion-con-democratas-si-no-se-me-investigatrump","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2018\/11\/08\/ofrezco-colaboracion-con-democratas-si-no-se-me-investigatrump\/","title":{"rendered":"\u00a1\u00a1&#8221;OFREZCO COLABORACI\u00d3N CON DEMOCRATAS, SI NO SE ME INVESTIGA&#8221;:TRUMP!!"},"content":{"rendered":"<p><strong>Mientras expulsaba al periodista inc\u00f3modo de la CNN,Donald Trump declar\u00f3: &#8220;OFREZCO COLABORACION CON LOS DEM\u00d3CRATAS, SI NO ME INVESTIGAN.&#8221;<\/strong><\/p>\n<p><strong>La reconquista de la mayor\u00eda, casi absoluta, de la C\u00e1mara de Representantes por parte de el Partido Dem\u00f3crata, fue la peor noticia que podr\u00eda haber recibido Donald Trump.Ahora tiene un contrapeso que no tuvo en los 2 primeros a\u00f1os, se abren las posibilidades de su juicio y se debilita su posibilidad de tener un s\u00f3lo mandato.<\/strong><\/p>\n<p><strong>Ello, m\u00e1s el avance extraordinario de las mujeres,son dos signos del 6 de marzo.Su ventaja para 2020 es que parece que no tiene un o una lider dem\u00f3crata \u00a0para enfrentarlo.<\/strong><\/p>\n<p><strong>Pero, \u00bf y Michael Obama ?, todo el mundo se ha olvidado de ella, pero &#8230;&#8230;.<\/strong><\/p>\n<p><strong>No ser\u00eda la se\u00f1ora Clinton la primera mujer con posibilidades de se\u00f1or Presidente, sino Michael Obama.Es mi modesta percepci\u00f3n.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mientras expulsaba al periodista inc\u00f3modo de la CNN,Donald Trump declar\u00f3: &#8220;OFREZCO COLABORACION CON LOS DEM\u00d3CRATAS, SI NO ME INVESTIGAN.&#8221; La reconquista de la mayor\u00eda, casi absoluta, de la C\u00e1mara de Representantes por parte de el Partido Dem\u00f3crata, fue la peor noticia que podr\u00eda haber recibido Donald Trump.Ahora tiene un contrapeso que no tuvo en los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5967","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/5967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=5967"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/5967\/revisions"}],"predecessor-version":[{"id":5970,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/5967\/revisions\/5970"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=5967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=5967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=5967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}