{"id":6070,"date":"2018-11-14T20:46:53","date_gmt":"2018-11-14T19:46:53","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=6070"},"modified":"2018-11-14T20:46:53","modified_gmt":"2018-11-14T19:46:53","slug":"el-gobierno-britanico-acaba-aprobar-borrador-de-may-para-el-brexit","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2018\/11\/14\/el-gobierno-britanico-acaba-aprobar-borrador-de-may-para-el-brexit\/","title":{"rendered":"\u00a1\u00a1EL GOBIERNO BRIT\u00c1NICO ACABA APROBAR BORRADOR DE MAY PARA EL BREXIT!!"},"content":{"rendered":"<p><strong>Mucho m\u00e1s importante que la decisi\u00f3n de Italia de no dar marcha atr\u00e1s en sus presupuestos ante la Uni\u00f3n Europea; mucho m\u00e1s que los 200,000 polacos ultraderechistas que desfilaron el domingo en Varsovia o los avances de los euroescepticos en toda Europa, ha sido, la decisi\u00f3n de hace unos minutos, donde tras 5 horas de debate en el seno del gobierno, se aprob\u00f3\u00a0elproyecto que sacar\u00eda nada menos que al Reino Unido de la Uni\u00f3n Europea<\/strong><\/p>\n<p><strong>May se ha mantenido y si ma\u00f1ana logra la aprobacion delParlamento, todo estar\u00e1 listo para la salida ,por siglos, gran potencia\u00a0 europea, el Reino Unido.<\/strong><\/p>\n<p><strong>Duro golpe.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Mucho m\u00e1s importante que la decisi\u00f3n de Italia de no dar marcha atr\u00e1s en sus presupuestos ante la Uni\u00f3n Europea; mucho m\u00e1s que los 200,000 polacos ultraderechistas que desfilaron el domingo en Varsovia o los avances de los euroescepticos en toda Europa, ha sido, la decisi\u00f3n de hace unos minutos, donde tras 5 horas de [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6070","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=6070"}],"version-history":[{"count":2,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6070\/revisions"}],"predecessor-version":[{"id":6072,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6070\/revisions\/6072"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=6070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=6070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=6070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}