{"id":6073,"date":"2018-11-14T21:09:38","date_gmt":"2018-11-14T20:09:38","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=6073"},"modified":"2018-11-14T21:09:38","modified_gmt":"2018-11-14T20:09:38","slug":"interviene-pedro-sanchez-ante-alcoa-y-el-plan-de-vias","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2018\/11\/14\/interviene-pedro-sanchez-ante-alcoa-y-el-plan-de-vias\/","title":{"rendered":"\u00a1\u00a1INTERVIENE PEDRO SANCHEZ ANTE ALCOA Y EL PLAN DE VIAS !!"},"content":{"rendered":"<p><strong>Hoy en la ma\u00f1ana se di\u00f3 un alivio a los trabajadores de Alcoa, a trav\u00e9s de la Ministra correspondiente del gobierno de Pedro S\u00e1nchez.<\/strong><\/p>\n<p><strong>Plante\u00f3 que no van a\u00a0dejar s\u00f3los a los trabajadores ni que perder\u00e1 sus empleos. Dijo que hablando con la empresa, que por primera vez se sent\u00f3 con ellos, se prolongar\u00e1n los ERES en tanto ,con ayuda del Gobierno ,se encuentran nuevos inversores para la gran empresa del alumino.<\/strong><\/p>\n<p><strong>Ya est\u00e1 en Asturias Abalos, quien tras reunirse con Javier Fern\u00e1ndez y con Adri\u00e1n Barbon, ma\u00f1ana a las 11 horas tendr\u00e1 una reuni\u00f3n en el Ayuntamiento para poner las cartas sobre la mesa, en el caso del Plan de Vias, con verdad por delante, de lo que dej\u00f3 de hacer Rajoy y su flamante Ministro c\u00e1ntabro, y de lo que puede hacer y lo que no\u00a0en el Plan de V\u00edas.<\/strong><\/p>\n<p><strong>Un Ministro ,del peso del de\u00a0Fomento que maneja el 17 % de los recursos del Estado, y una Ministra, con deseos de ayudar,como es su obligaci\u00f3n, han estado hoy en Asturias y tambi\u00e9n ma\u00f1ana.<\/strong><\/p>\n<p><strong>Lo adelantamos, en el momento en que aprobado por el Comit\u00e9 Federal, el sustituto de Javier Fern\u00e1ndez, empezar\u00edan a llegar recursos de importancia para esta Asturias, que tuvo, en contra en forma despiadada a Pedro Sanchez con Javier Fern\u00e1ndez a la cabeza \u00a0y la simpat\u00eda de pocos, como Maria Luisa Garcedo,Adriana Lastra y la actual directora del ERA.<\/strong><\/p>\n<p><strong>Seremos testigos.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Hoy en la ma\u00f1ana se di\u00f3 un alivio a los trabajadores de Alcoa, a trav\u00e9s de la Ministra correspondiente del gobierno de Pedro S\u00e1nchez. Plante\u00f3 que no van a\u00a0dejar s\u00f3los a los trabajadores ni que perder\u00e1 sus empleos. Dijo que hablando con la empresa, que por primera vez se sent\u00f3 con ellos, se prolongar\u00e1n los [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6073","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=6073"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6073\/revisions"}],"predecessor-version":[{"id":6076,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6073\/revisions\/6076"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=6073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=6073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=6073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}