{"id":6149,"date":"2018-11-23T14:20:28","date_gmt":"2018-11-23T13:20:28","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=6149"},"modified":"2018-11-23T14:20:28","modified_gmt":"2018-11-23T13:20:28","slug":"cis-cataluna-independentisas-crecen-con-erc-ciudadanos-baja","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2018\/11\/23\/cis-cataluna-independentisas-crecen-con-erc-ciudadanos-baja\/","title":{"rendered":"(CIS, CATALU\u00d1A) .INDEPENDENTISAS CRECEN CON ERC, CIUDADANOS BAJA !!"},"content":{"rendered":"<p><strong>Aaba de darse a conocer la encuesta del CIS sobre Catalu\u00f1a,estimaci\u00f3n de voto si las elecciones fueran hoy.<\/strong><\/p>\n<p><strong>Los independentista suben de 46.7 a 47.2 % y los no independentistas bajan de 44.9 a\u00a0 43. 2 %.<\/strong><\/p>\n<p><strong>En relaci\u00f3n con los partidos es ERC\u00a0el \u00a0que se ubica en primer lugar aumentando 4 esca\u00f1\u00f3s hasta 36-38, desplazando a Ciudadanos que perder\u00eda 6 esca\u00f1os.Subir\u00eda tambi\u00e9n la CUP con 7 esca\u00f1os\u00a0 hasta 11,\u00a0y \u00a0los pierde PxC de Torra con 10menos m\u00e1s bajando de 34 a 24 esca\u00f1oss.<\/strong><\/p>\n<p><strong>En Comun Podem sube 8 hasta 17 y finalmente quedando, sin cambio, el PSC seguir\u00eda con 18.<\/strong><\/p>\n<p><strong>Al final quedar\u00eda el PP que bajar\u00eda de los 4 a los 2 esca\u00f1os.<\/strong><\/p>\n<p><strong>Un primer an\u00e1lisis, nos lleva a observar que han sido mas eficientes los independeentistas que los llamados Constitucionalistas y se quedan a 2.3 puntos de tener la mayor\u00eda social.<\/strong><\/p>\n<p><strong>Que entre los independentistas Oriol Junqueras que lleva un programa de un proceso paulatino, con dialogo, es el principal ganador igual que la CUP quit\u00e1ndoles 10 esca\u00f1os a Puigdemont y a Torra, que han fracasado en su pol\u00edtica del todo o nada.<\/strong><\/p>\n<p><strong>Podemos incrementa 10 esca\u00f1os, el PSC queda estancado y el gran derrotado, es el PP, que hab\u00eda perdido los 5 que permiten formar grupo, y est\u00e1n a punto de desaparecer, con 2<\/strong><\/p>\n<p><strong>Ante las elecciones andaluces, donde se presentaban como la opci\u00f3n contra la izquierda, caen dolorosamente\u00a0de aquel primer lugar que Ines Arrimadas tanto flore\u00f3 y que Rivera pensaba que era la t\u00f3nica general en el pa\u00eds.<\/strong><\/p>\n<p><strong>Es solo una encuesta. Es s\u00f3lo una fotografia, pero nos permite ver como obseerva al puebelo catal\u00e1n los \u00faltimos acontecimientos.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aaba de darse a conocer la encuesta del CIS sobre Catalu\u00f1a,estimaci\u00f3n de voto si las elecciones fueran hoy. Los independentista suben de 46.7 a 47.2 % y los no independentistas bajan de 44.9 a\u00a0 43. 2 %. En relaci\u00f3n con los partidos es ERC\u00a0el \u00a0que se ubica en primer lugar aumentando 4 esca\u00f1\u00f3s hasta 36-38, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6149","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=6149"}],"version-history":[{"count":4,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6149\/revisions"}],"predecessor-version":[{"id":6153,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6149\/revisions\/6153"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=6149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=6149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=6149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}