{"id":6570,"date":"2018-12-29T20:00:59","date_gmt":"2018-12-29T19:00:59","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=6570"},"modified":"2018-12-29T20:00:59","modified_gmt":"2018-12-29T19:00:59","slug":"en-2010-villa-sabia-que-el-1-enero-2019-estaban-cerradas-todas-las-minas","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2018\/12\/29\/en-2010-villa-sabia-que-el-1-enero-2019-estaban-cerradas-todas-las-minas\/","title":{"rendered":"\u00a1\u00a1EN 2010, VILLA SABIA QUE EL 1 ENERO 2019 ESTABAN CERRADAS TODAS LAS MINAS !!"},"content":{"rendered":"<p><strong>De 52,000 mineros activos en Espa\u00f1a en 1985, hoy quedaban 2,046.Del carb\u00f3n que se utiliza en Espa\u00f1a para crear energ\u00eda el\u00e9ctrica\u00a0en Asturias, Castilla y Le\u00f3n y Arag\u00f3n se produce el 14 %, mientras que importamos de Rusia y Colombia el 86 %.<\/strong><\/p>\n<p><strong>En 2010, Espa\u00f1a, Alemania y Ruman\u00eda solicitaron una prorroga a la Uni\u00f3n Europea para que se permitiese la estracci\u00f3n del carb\u00f3n hasta el 31 diciembre del 2018, so pena de no cumplir y pagar 500 millones de euros.<\/strong><\/p>\n<p><strong>El desplome de las cuencas y la corrupci\u00f3n en el SOMA, fue un proceso, sabido, y aprovechado por algunos cuantos .<\/strong><\/p>\n<p><strong>En espera de que podamos analizar mejor este tema,\u00a0 la Amnist\u00eda Fiscal para que los espa\u00f1oles sacaron al extranjero para resguardarlos,no pagar impuestos\u00a0de Rajoy, fue aprovechado por Villa, quien, aldeano, si no aprovechaba la ocasi\u00f3n el dinero que estaba en el extranjero, el lavado de dinero, le hubiera costado trabajo maniobrarlo y recuperarlo.<\/strong><\/p>\n<p><strong>De 54,000 mineros en 1985, a los 2,046 que terminaron ayer viernes, hubo mucho m\u00e1s que el cambio de una energ\u00eda a otra.<\/strong><\/p>\n<p><strong>\u00bf Que pas\u00f3 en Asturias ?, \u00bf Que paso en el heroico SINDICATO de OBREROS MINEROS DE ASTURIAS,(SOMA,) creado por Manuel Llaneza y otros mineros en\u00a0 1910 en los Altos de San Emiliano\u00a0,entre Langreo y Mieres<\/strong><\/p>\n<p><strong>\u00bf Que fuerza sindical y pol\u00edtica asturiana va a enfrentar el desaf\u00edo del Three Party en las muncipales , autonomicas de mayo pr\u00f3ximo?.<\/strong><\/p>\n<p><strong>De ese PSOE ya empezaron a subirse al\u00a0 nuevo caballo, como\u00a0\u00a0cuando en su momento\u00a0 Vicente Alvarez Areces, Riopedre y otros en Perlora olvidaron su pasado comunista y se subieron al caballo del Socialismo,\u00a0si ya es miembro de la directiva de Vox, hasta &#8220;personajes de los gobiernos\u00a0 asturianos&#8221;como\u00a0aquel Director General de Comercio y Turismo\u00a0del Gobierno de Areces\u00a0,Javier de la Ballina?.<\/strong><\/p>\n<p><strong>Nunca terminar\u00e1 de arrepentirse Pedro de Silva, cuando hace tres o cuatro dijo: &#8221; EL HOMBRE CLAVE EN LA TRANSICION EN ASTURIAS\u00a0HA SIDO JOSE ANGEL FERNANDEZ VILLA &#8220;<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mucha tristeza.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>De 52,000 mineros activos en Espa\u00f1a en 1985, hoy quedaban 2,046.Del carb\u00f3n que se utiliza en Espa\u00f1a para crear energ\u00eda el\u00e9ctrica\u00a0en Asturias, Castilla y Le\u00f3n y Arag\u00f3n se produce el 14 %, mientras que importamos de Rusia y Colombia el 86 %. En 2010, Espa\u00f1a, Alemania y Ruman\u00eda solicitaron una prorroga a la Uni\u00f3n Europea [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6570","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=6570"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6570\/revisions"}],"predecessor-version":[{"id":6573,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/6570\/revisions\/6573"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=6570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=6570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=6570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}