{"id":7325,"date":"2019-04-12T17:44:52","date_gmt":"2019-04-12T15:44:52","guid":{"rendered":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/?p=7325"},"modified":"2019-04-12T17:44:52","modified_gmt":"2019-04-12T15:44:52","slug":"suave-una-campana-electoral-un-debate-para-lograr-100-escanos-250-estan-localizados","status":"publish","type":"post","link":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/2019\/04\/12\/suave-una-campana-electoral-un-debate-para-lograr-100-escanos-250-estan-localizados\/","title":{"rendered":"\u00a1\u00a1SUAVE&#8230;..UNA CAMPA\u00d1A ELECTORAL, UN DEBATE, PARA LOGRAR 100 ESCA\u00d1OS.- 250 ESTAN LOCALIZADOS !!"},"content":{"rendered":"<p><strong>Creemos que hay que ir con calma para entender esta campa\u00f1a electoral oficial.<\/strong><\/p>\n<p><strong>Todas las encuestas, salvo la del CIS, reunidas por Llaneras, daban como ubicadas ya en su casillero 250 esca\u00f1os y que faltan por definirse 100.La macroencuesta del CIS y la entrevista en la SER, al d\u00eca siguiente de Tezanos, era tan poderosa, que hubo que matizarlo para que nadie las diese como definitivas. Y en la SER, adem\u00e0s de recalcar que el 46 % est\u00e0n indecisos, habl\u00f2 de que el PP no estaba tan abajo y que hab\u00eca un voto oculto de Vox.<\/strong><\/p>\n<p><strong>Hoy en las tertulias, y con cualquiera que hablemos, nadie garantiza nada.Todo puede pasar.Eso es sano.Llegar al 70 % de participaci\u00f2n, ser\u00eca una buena noticia para la estabilidad que requieree nuestro pa\u00ecs.<\/strong><\/p>\n<p><strong>Veamos.En nuestra opini\u00f2n, con el buen manejo de la campa\u00f1a la mancuerna Sanchez-Redondo, parece confirmar que Pedro S\u00e0nchez va a ser el proximo Presidente del Gobierno,con Unidas-Podemos y PNV, o en \u00f9ltima instancia con ERC.<\/strong><\/p>\n<p><strong>Aunque haya voto oculto del Vox,detr\u00e0s del cual est\u00e0 Bannon y es su estilo, Casado, Rivera y Abascal no llegar\u00e0n a los 176, creo que no pasar\u00e0n de los 163, por lo tanto, por el momento la &#8220;derechona&#8221; involucionista \u00a0no llegar\u00e0 al gobierno.<\/strong><\/p>\n<p><strong>Nosotros pensamos\u00a0 en algo de sentido com\u00f9n. Los partidos que pueden subir en estos 14 d\u00ecas, ser\u00e0n, sin duda, Unidas- Podemos y el PP,y quien ir\u00e0 en picada ser\u00e0 Albert Rivera, de donde saldr\u00e0 la subida del PP.El PSOE mantendr\u00e0 la tendencia de serenidad, no agresi\u00f2n y calma.<\/strong><\/p>\n<p><strong>La deseperaci\u00f2n del PP se observa en el video de Nuevas Generaciones, en el ataque a Pedro S\u00e0nchez\u00a0 utilizando las imagenes de las hijas.<\/strong><\/p>\n<p><strong>Tendremos 14 d\u00ecas y un debate.<\/strong><\/p>\n<p><strong>De este resultado depender\u00e0n las Auton\u00f2micas y las Municipales.<\/strong><\/p>\n<p><strong>Las europeas ser\u00e1n otro asunto&#8230;..Ya hablaremos.<\/strong><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Creemos que hay que ir con calma para entender esta campa\u00f1a electoral oficial. Todas las encuestas, salvo la del CIS, reunidas por Llaneras, daban como ubicadas ya en su casillero 250 esca\u00f1os y que faltan por definirse 100.La macroencuesta del CIS y la entrevista en la SER, al d\u00eca siguiente de Tezanos, era tan poderosa, [&hellip;]<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7325"}],"collection":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/comments?post=7325"}],"version-history":[{"count":3,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7325\/revisions"}],"predecessor-version":[{"id":7328,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/posts\/7325\/revisions\/7328"}],"wp:attachment":[{"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/media?parent=7325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/categories?post=7325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.elcomercio.es\/reflexiones-de-belarmino\/wp-json\/wp\/v2\/tags?post=7325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}